{"id":67727,"date":"2017-07-29T08:16:57","date_gmt":"2017-07-29T12:16:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=67727"},"modified":"2017-07-29T08:18:06","modified_gmt":"2017-07-29T12:18:06","slug":"un-club-venerado-y-muy-exclusivo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-club-venerado-y-muy-exclusivo\/","title":{"rendered":"Un club venerado y muy exclusivo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-67728 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/07\/un-club-venerado-y-muy-exclusivo.jpeg\" alt=\"\" width=\"294\" height=\"237\" \/>Eddie Murray alcanz\u00f3 su hit tres mil en la misma fecha en que su madre, Carrie celebraba su cumplea\u00f1os. Stan Musial se inscribi\u00f3 en la historia como el \u00fanico miembro en lograrlo en rol de bateador emergente. Derek Jeter y Craig Biggio son los \u00fanicos en coleccionar cinco imparables el d\u00eda memorable en que registraron la haza\u00f1a.<!--more--><\/p>\n<p>Varias decenas de historias y an\u00e9cdotas involucran a los 30 peloteros, quienes mostraron gran talento, consistencia y longevidad en el transcurrir de sus carreras, que al momento de decir adi\u00f3s le permitieron pertenecer a este exclusivo c\u00edrculo.<\/p>\n<p>Un grupo tan resumido que leyendas del b\u00e9isbol como Joe Dimaggio, Ted Williams, Babe Ruth, Lou Gehrig, Mickey Mantle, Barry Bonds, Jimmie Foxx, Al Simmons, Rogers Hornsby, Frank Robinson, Willie Keeler\u00a0 y muchos otros no pertenecen a este club que poco a poco le abre sus puertas a un nuevo integrante: Adrian Beltr\u00e9.<\/p>\n<p>El dominicano, quien el pasado mi\u00e9rcoles agreg\u00f3 tres imparables m\u00e1s a su registro ahora se coloca a cuatro para pertenecer a esta lista tan distinguida, cuya presencia en un par de d\u00edas se elevar\u00e1 a 31 miembros.<\/p>\n<p>Cuando lo alcance habr\u00e1 sellado su ingreso a Cooperstown por las puertas m\u00e1s anchas, pues la mayor\u00eda ha ingresado con superbos porcentajes y en el primer momento en que figuraron en las boletas, con las excepciones de Craig Biggio (3,060), quien tuvo que esperar un par de a\u00f1os, as\u00ed como Pete Rose y Rafael Palmeiro por razones ya conocidas.<\/p>\n<p>Miembros del club como George Brett (98.7 %); Cal Ripken (98.5); Ty Cobbs (98.2 %); Hank Aaron (97.8); Tony Gwynn (97-6); (Honus Wagner (95.1); Rickie Henderson (94.8); Willie Mays (94.6); Carl Yastrezemski (94.6); Musial (93.2); Roberto Clemente (92.6); Wade Boggs (91.8); Rod Carew (90.5), se encuentran en la lista de los inmortales de mayor votaci\u00f3n para Cooperstown, exaltaci\u00f3n que inici\u00f3 en 1936.<\/p>\n<p>Incluso, el gran templo posee decenas de souvenires de todos los integrantes de este club, cuyos millares de visitantes se deleitan con bates, pelotas, guantes, camisetas, gorras u otros utensilios de estos peloteros tan distinguidos.<\/p>\n<div id=\"FIOnDemandWrapper_fiInstance_101888_6_7384983\" class=\"FIOnDemandWrapper\"><\/div>\n<p>Beltr\u00e9, un consistente bateador que ha promediado 170 imparables en las \u00faltimas siete campa\u00f1as, a cuya haza\u00f1a agrega 454 jonrones, 604 dobletes, ambos a\u00fan contando, as\u00ed como una envidiable defensa que le ha permitido conquistar cinco guantes dorados, ser\u00e1 pronto uno de ellos.<\/p>\n<p>Esto a pesar, de no poseer los ocho lideratos de bateo de Gwynn, las 10 campa\u00f1as sobre 200 hits de Rose o de Ichiro Suzuki, ni mucho menos el promedio de .366 de por vida que exhibe Cobbs, el quisqueyano, estar\u00e1 frente al talento m\u00e1s resaltante que ha podido conocer el b\u00e9isbol.<\/p>\n<p><strong>ALGUNOS REGISTROS DE MIEMBROS DE 3000 HITS<\/strong><br \/>\nCuando el dominicano alcance la apetecida marca la unir\u00e1 a sus 454 vuelacercas y ser\u00e1 uno de 10 peloteros en el club de 400 vuelacercas y 3,000 imparables, al que pertenecen Aaron (3,771 y 755); Mays (3,283 y 660) Alex ( 3,115 y 696 ); Musial (3,630 y 475); Palmeiro (3,020 y 569 ); Murray ( 3,255 y 504 ); Winfield (3,110 y 465); Yastrzemski (3,419 y 452); Ripken (3,184 y 431) Mientras Cobbs lidera con su docena de coronas de bateo a por los menos ocho integrantes que en su paso por la gran carpa alcanzaron al menos cuatro, Beltr\u00e9 se unir\u00e1 a un grupo que incluye a Palmeiro, Lou Brock, Rickie Henderson, Biggio, Winfield, Robin Yount, Cal Ripken, Murray, Jeter, Eddie Collins, Paul Molitor, quienes nunca se apoderaron del cetro de bateo.<\/p>\n<p>El antesalista quisqueyano encabez\u00f3 el circuito en imparables en el 2013 con 199, empero otros como Brock, Henderson, Biggio, Winfield, Murray, Collins nunca lideraron el circuito en imparables en alg\u00fan momento de sus carreras.<\/p>\n<p>Cuando Beltr\u00e9 alcance la proeza ser\u00e1 el tercer a\u00f1o seguido en que al menos un jugador llega a la misma y se unir\u00e1 a Alex (2015) e Ichiro el a\u00f1o pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eddie Murray alcanz\u00f3 su hit tres mil en la misma fecha en que su madre, Carrie celebraba su cumplea\u00f1os. Stan Musial se inscribi\u00f3 en la historia como el \u00fanico miembro en lograrlo en rol de bateador emergente. Derek Jeter y Craig Biggio son los \u00fanicos en coleccionar cinco imparables el d\u00eda memorable en que registraron la haza\u00f1a.<\/p>\n","protected":false},"author":9,"featured_media":67728,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-67727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=67727"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67727\/revisions"}],"predecessor-version":[{"id":67730,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67727\/revisions\/67730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/67728"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=67727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=67727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=67727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}