{"id":68550,"date":"2017-08-09T10:06:33","date_gmt":"2017-08-09T14:06:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=68550"},"modified":"2017-08-09T10:06:33","modified_gmt":"2017-08-09T14:06:33","slug":"cientificos-crean-un-helado-que-no-se-derrite","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cientificos-crean-un-helado-que-no-se-derrite\/","title":{"rendered":"Cient\u00edficos crean un helado que no se derrite"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-68551 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/helado-no-derrite_0.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/helado-no-derrite_0.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/helado-no-derrite_0-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\u00bfUn helado\u00a0que no se derrite? Un equipo de cient\u00edficos <span lang=\"es-ES\">del Centro de Investigaci\u00f3n de Desarrollo Bioterap\u00e9utico de Jap\u00f3n en Kanazawa ha utilizado<\/span><span lang=\"es-ES\"><strong>un extracto de los polifenoles de la fresa\u00a0para desarrollar helados que no se derriten.<\/strong><\/span><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"es-ES\"><strong>Aprovechando el descubrimiento hecho accidentalmente por un chef,<\/strong><\/span><span lang=\"es-ES\">un equipo de cient\u00edficos japoneses ha desarrollado la manera de hacer -y vender- un tipo de helado que no se derrite, algo que tiene visos de revolucionar el mercado de los helados, puesto que la mayor\u00eda de los helados cremosos, comienza a derretirse momentos despu\u00e9s de sacarlos del congelador y puestos sobre un cucurucho o un bol\/plato. Es precisamente uno de los motivos por los que solemos comernos el helado tan r\u00e1pido como nos sea posible, para que no se nos derrita y acabe manch\u00e1ndonos las manos o la ropa que llevemos puesta.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"es-ES\">Sin embargo, esta acci\u00f3n de comer el helado a toda velocidad podr\u00eda dar un giro de 180 grados gracias a <\/span><span lang=\"es-ES\"><strong>esta t\u00e9cnica que mantiene la forma del helado, sin importar el tiempo que quieras tardar en com\u00e9rtelo.<\/strong><\/span><\/p>\n<div id=\"paragraph_2\">\n<p><span lang=\"es-ES\">odo comenz\u00f3 con un extracto completamente natural de las fresas. Este extracto hace que sea mucho m\u00e1s dif\u00edcil separar el agua y el aceite, que es lo que ocurre con los helados tradicional. Al intentar mezclar el extracto de fresas con el helado, descubrieron que <\/span><span lang=\"es-ES\"><strong>evitar\u00eda que este se derritiera.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"es-ES\"><strong>Teniendo en cuenta que es un extracto natural, no requiere pruebas de inspecci\u00f3n de salud,<\/strong><\/span><span lang=\"es-ES\"> por lo que ha sido puesto a disposici\u00f3n de los propietarios de helader\u00edas locales, que con mucho gusto han comenzado a vender el helado en forma de polo con los m\u00e1s variopintos dise\u00f1os.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"es-ES\">Seg\u00fan los testimonios de los que han probado dicho experimento,<\/span><span lang=\"es-ES\"><strong> el helado sabe bien y puede hacer frente a las temperaturas c\u00e1lidas sin derretirse.<\/strong><\/span><span lang=\"es-ES\"> Algunos clientes expusieron su helado directamente a la luz del sol y otros decidieron hacer alguna prueba m\u00e1s extrema, poniendo el helado durante muchos minutos delante de un secador de pelo emanandocalor.\u00a0En cualquiera de los casos, los helados no se derritieron y mantuvieron la forma intacta durante varias horas, conservando el frescor a la hora de comerlo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id=\"paragraph_3\">\n<div class=\"related_content gallery hidden-print pull-left col-xs-12 col-lg-6\">\n<div class=\"title col-xs-12\">SEGURO QUE TE INTERESA&#8230;<\/div>\n<div class=\"image col-xs-4 no_padding\">\n<figure><img decoding=\"async\" class=\"\" src=\"https:\/\/estaticos.muyinteresante.es\/media\/cache\/320x240_thumb\/uploads\/images\/gallery\/58cfe5465bafe8b8ca01519f\/fresas.jpg\" alt=\"Beneficios de las fresas\" \/><\/figure>\n<\/div>\n<div class=\"content col-xs-8\">Beneficios de las fresas<\/p>\n<div class=\"hidden-print social_items_list\"><\/div>\n<\/div>\n<\/div>\n<p><span lang=\"es-ES\">Este intrigante producto es fabricado por<\/span><span lang=\"es-ES\"><em>Biotherapy Development Research Center Co<\/em><\/span><span lang=\"es-ES\">. en Kanazawa (Jap\u00f3n), y la compa\u00f1\u00eda comenz\u00f3 a comercializar los helados en el mes de abril, a\u00f1adiendo puntos de venta en Osaka y en Tokio.<\/p>\n<p>Takeshi Toyoda, presidente de la compa\u00f1\u00eda, afirma que \u00ablos polos siguen siendo casi iguales incluso si est\u00e1n expuestos al aire caliente de un secador\u00bb.<\/p>\n<p><\/span><span lang=\"es-ES\"><strong>\u00abEl l\u00edquido de polifenol tiene propiedades que hacen que sea dif\u00edcil separar el agua y el aceite para que un helado que lo contenga pueda conservar la forma original de lacrema\u00a0durante m\u00e1s tiempo de lo habitual y sea dif\u00edcil de derretir\u00bb<\/strong><\/span><span lang=\"es-ES\">, explic\u00f3 Tomihisa Ota, profesor de la Universidad de Kanazawa y l\u00edder del proyecto de los helados resistentes al calor.<\/p>\n<p>Antes de llegar a la versi\u00f3n actual, los expertos probaron muchas variaciones, utilizando una variedad de leches y cremas frescas de diferentes productores, as\u00ed como cambiando la combinaci\u00f3n, la cantidad de polifenol y otras caracter\u00edsticas hasta llegar a la versi\u00f3n actual del helado.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span lang=\"es-ES\">\u00bfDeseando probarlo? Actualmente, el helado que no se derrite solo est\u00e1 disponible para la venta en Jap\u00f3n.<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfUn helado\u00a0que no se derrite? Un equipo de cient\u00edficos del Centro de Investigaci\u00f3n de Desarrollo Bioterap\u00e9utico de Jap\u00f3n en Kanazawa ha utilizadoun extracto de los polifenoles de la fresa\u00a0para desarrollar helados que no se derriten.<\/p>\n","protected":false},"author":9,"featured_media":68551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-68550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=68550"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68550\/revisions"}],"predecessor-version":[{"id":68552,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68550\/revisions\/68552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/68551"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=68550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=68550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=68550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}