{"id":68574,"date":"2017-08-09T18:22:25","date_gmt":"2017-08-09T22:22:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=68574"},"modified":"2017-08-09T18:22:25","modified_gmt":"2017-08-09T22:22:25","slug":"eeuu-sanciona-hermano-de-chavez-y-a-otros-siete-funcionarios-de-venezuela","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/eeuu-sanciona-hermano-de-chavez-y-a-otros-siete-funcionarios-de-venezuela\/","title":{"rendered":"EEUU sanciona hermano de Ch\u00e1vez y a otros siete funcionarios de Venezuela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-68575 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/adan.jpg\" alt=\"\" width=\"392\" height=\"221\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/adan.jpg 1023w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/adan-300x169.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/08\/adan-768x432.jpg 768w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/>WASHINGTON.- El gobierno de Estados Unidos sancion\u00f3 a ocho funcionarios venezolanos vinculados con el establecimiento y organizaci\u00f3n de la Asamblea Constituyente, la cual considera \u201cantidemocr\u00e1tica\u201d e \u201cileg\u00edtima\u201d.<!--more--><\/p>\n<p>En esta nueva ronda de sanciones aparece el nombre de Ad\u00e1n Ch\u00e1vez, hermano del fallecido presidente Hugo Ch\u00e1vez, por su papel en la constituci\u00f3n de la Asamblea Nacional Constituyente (ANC).<\/p>\n<p>En el comunicado de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s) del departamento del Tesoro de Estados Unidos divulgado el mi\u00e9rcoles, se explican las razones por las cuales EE.UU. considera que la Asamblea Constituyente fue elegida bajo un proceso antidemocr\u00e1tico \u201cinstigado por el gobierno del presidente venezolano Nicol\u00e1s Maduro para socavar la voluntad del pueblo venezolano\u201d.<\/p>\n<div><\/div>\n<p>\u201cEl presidente Maduro tom\u00f3 juramento a esta Asamblea Constituyente ileg\u00edtima para afianzar a\u00fan m\u00e1s su dictadura y contin\u00faa estrechando su control sobre el pa\u00eds\u201d, dijo el secretario del Tesoro, Steven T. Mnuchin.<\/p>\n<p>Mnuchin insisti\u00f3 en que no se puede aceptar \u201cel desprecio de este r\u00e9gimen por la voluntad del pueblo\u201d y ofreci\u00f3 el respaldo del gobierno estadounidense para luchar contra la \u201ctiran\u00eda\u201d hasta lograr que se restaure en Venezuela una \u201cdemocracia pac\u00edfica y pr\u00f3spera\u201d.<\/p>\n<p>El departamento del Tesoro se\u00f1al\u00f3 que las designaciones de hoy incluyen a siete funcionarios actuales y antiguos del gobierno venezolano y un individuo que ha participado en acciones o pol\u00edticas que socavan procesos democr\u00e1ticos o instituciones en Venezuela.<\/p>\n<p>\u201cComo resultado de las acciones de hoy, todos los activos de estas personas sujetas a la jurisdicci\u00f3n de Estados Unidos est\u00e1n congelados, y se proh\u00edbe a los estadounidenses tratar con ellos\u201d, se lee en el comunicado.<\/p>\n<p>El anuncio de los nuevos sancionados se produce una semana despu\u00e9s de que Washington incluyera al presidente Nicol\u00e1s Maduro en su \u201clista negra\u201d internacional.<\/p>\n<p>La OFAC design\u00f3 a seis individuos que han desempe\u00f1ado un papel importante en la organizaci\u00f3n o creaci\u00f3n de la Asamblea Constituyente a trav\u00e9s de su participaci\u00f3n en dos \u00f3rganos, la Comisi\u00f3n Presidencial para la ANC y el Comando Constituyente Zamora 200.<\/p>\n<p>Maduro cre\u00f3 la Comisi\u00f3n Presidencial para la formaci\u00f3n y operaci\u00f3n del proceso de la Constituyente. El presidente venezolano tambi\u00e9n cre\u00f3 el Comando Constituyente Zamora 200 para llevar a cabo una campa\u00f1a para las elecciones de la ANC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.- El gobierno de Estados Unidos sancion\u00f3 a ocho funcionarios venezolanos vinculados con el establecimiento y organizaci\u00f3n de la Asamblea Constituyente, la cual considera \u201cantidemocr\u00e1tica\u201d e \u201cileg\u00edtima\u201d.<\/p>\n","protected":false},"author":9,"featured_media":68575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-68574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=68574"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68574\/revisions"}],"predecessor-version":[{"id":68576,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/68574\/revisions\/68576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/68575"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=68574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=68574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=68574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}