{"id":69116,"date":"2017-09-18T11:05:36","date_gmt":"2017-09-18T15:05:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69116"},"modified":"2017-09-18T11:05:36","modified_gmt":"2017-09-18T15:05:36","slug":"maria-alcanza-categoria-2-y-su-fuerza-se-intensificara-en-proximas-horas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/maria-alcanza-categoria-2-y-su-fuerza-se-intensificara-en-proximas-horas\/","title":{"rendered":"Mar\u00eda alcanza categor\u00eda 2 y su fuerza se intensificar\u00e1 en pr\u00f3ximas horas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-69117 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/201709180906171.png\" alt=\"\" width=\"294\" height=\"209\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/201709180906171.png 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/201709180906171-75x52.png 75w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>El hurac\u00e1n Mar\u00eda alcanza ya la categor\u00eda 2 sobre 5 en las escala Saffir-Simpson y su fuerza se intensificar\u00e1 en las pr\u00f3ximas horas en su recorrido a trav\u00e9s del Caribe hasta convertirse en un fen\u00f3meno peligroso, seg\u00fan el \u00faltimo parte del Centro Nacional de Huracanes de Estados Unidos (CNH).<!--more--><\/p>\n<div id=\"FIOnDemandWrapper_fiInstance_101888_0_2723195\" class=\"FIOnDemandWrapper\">\u00a0<span style=\"line-height: inherit\">A las 12.00 GMT de hoy el centro del hurac\u00e1n estaba localizado cerca de la latitud 14.6 norte, longitud 59.7 oeste, en el mar Caribe.<\/span>Mar\u00eda se mueve hacia el oeste-noroeste a cerca de 12 millas por hora (19 km\/h) y se espera que este movimiento contin\u00fae con una disminuci\u00f3n en la velocidad de traslaci\u00f3n hasta la noche del martes.<\/p>\n<p>El centro de Mar\u00eda se mover\u00e1 a trav\u00e9s de las Islas de Sotavento esta misma noche y luego sobre el extremo noreste del mar Caribe.<\/p>\n<p>El hurac\u00e1n se mantiene a unas 85 millas (135 kil\u00f3metros) de Martinica y cerca de unas 120 millas, unos 195 kil\u00f3metros, al este de la isla de Dominica.<\/p>\n<p>Sus vientos sostenidos ya alcanzan una velocidad de 110 millas a la hora, unos 175 kil\u00f3metros por hora, seg\u00fan la fuente.<\/p>\n<p>En este contexto, el Gobierno de Santa Luc\u00eda ha emitido un aviso de hurac\u00e1n para la isla, mientras el servicio meteorol\u00f3gico de St. Maarten mantiene un aviso de tormenta tropical.<\/p>\n<p>Se ha decretado avisos por la llegada del hurac\u00e1n tambi\u00e9n en las islas de Guadalupe, St. Kitss y Nevis, Montserrat, Martinica y Santa Luc\u00eda.<\/p>\n<p>Adem\u00e1s existe una aviso de tormenta tropical para Antigua y Barbuda y las islas de Saba y Saint Eustatius.<\/p>\n<p>El aviso de hurac\u00e1n permanece asimismo en vigor para Puerto Rico, Vieques y Culebra, adem\u00e1s de las Islas V\u00edrgenes estadounidenses y brit\u00e1nicas, as\u00ed como Anguila.<\/p>\n<p>Por el momento, Mar\u00eda se comportar\u00e1 como tormenta tropical en Barbados y Las Granadinas, adem\u00e1s de San Vicente, seg\u00fan el mismo parte.<\/p>\n<p>Las marejadas generadas por Mar\u00eda est\u00e1n afectando a todas las Antillas Menores. Es probable que estas marejadas causen condiciones de resacas y corrientes marinas peligrosas que pueden poner en peligro la vida de los habitantes de la zona.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El hurac\u00e1n Mar\u00eda alcanza ya la categor\u00eda 2 sobre 5 en las escala Saffir-Simpson y su fuerza se intensificar\u00e1 en las pr\u00f3ximas horas en su recorrido a trav\u00e9s del Caribe hasta convertirse en un fen\u00f3meno peligroso, seg\u00fan el \u00faltimo parte del Centro Nacional de Huracanes de Estados Unidos (CNH).<\/p>\n","protected":false},"author":9,"featured_media":69117,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-69116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69116"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69116\/revisions"}],"predecessor-version":[{"id":69118,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69116\/revisions\/69118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69117"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}