{"id":69153,"date":"2017-09-19T09:15:48","date_gmt":"2017-09-19T13:15:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69153"},"modified":"2017-09-19T09:15:48","modified_gmt":"2017-09-19T13:15:48","slug":"cuanto-oxigeno-genera-central-park","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuanto-oxigeno-genera-central-park\/","title":{"rendered":"\u00bfCu\u00e1nto ox\u00edgeno genera Central Park?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-69154 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/central-park_0.jpg\" alt=\"\" width=\"339\" height=\"254\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/central-park_0.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/central-park_0-300x225.jpg 300w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/>Central Park, tal vez el parqueurbano m\u00e1s conocido de todo el mundo \u2013no en vano ha sido escenario de numerosas pel\u00edculas, como las m\u00edticas<em>Desayuno con diamantes<\/em> (1961),<em>Love Story<\/em> (1970) o <em>Cuando Harry encontr\u00f3 a Sally<\/em> (1989)\u2013,<!--more--> cuenta con unas dimensiones aproximadas de 4.000 x 800 metros. Para que te hagas una idea, piensa que, con sus 341 hect\u00e1reas de superficie total, <strong>es m\u00e1s grande que dos de las naciones m\u00e1s peque\u00f1as del mundo:<\/strong> casi multiplica por dos el territorio de M\u00f3naco y por ocho el de la Ciudad del Vaticano.<\/p>\n<p>Todo el parque, incluidos sus lagos y monta\u00f1as, son lo que son por obra del hombre. Los planos de esta aut\u00e9ntica reserva natural fueron dise\u00f1ados por el arquitecto paisajista, periodista y bot\u00e1nico estadounidense Frederick Law Olmsted y por Calvert Vaux, tambi\u00e9n arquitecto paisajista, pero este de nacionalidad brit\u00e1nica. Se concluy\u00f3 en el a\u00f1o 1873 y<strong> alberga unos 250.000 \u00e1rboles en numerosos valles, entre ellos una de las \u00faltimas arboledas de olmos americanos del nordeste de Estados Unidos<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Este gran parque urbano proporciona diversos beneficios a los habitantes de la Gran Manzana y, en concreto, al distrito metropolitano de Manhattan, donde se encuentra ubicado. Adem\u00e1s de ser una gran \u00e1rea l\u00fadica y de esparcimiento, est\u00e1 demostrado que <strong>un espacio verde revaloriza los inmuebles de sus alrededores, y contribuye a purificar el aire y generar un medio ambiente m\u00e1s limpio<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Pero regresemos en este punto a la pregunta formulada al principio. Para darle respuesta, debemos tener en cuenta que <strong>la cantidad de ox\u00edgeno que puede producir un \u00e1rbol es algo muy variable<\/strong>, ya que depende de factores muy diferentes como su especie, su edad o su estado de salud.<\/p>\n<p>&nbsp;<\/p>\n<p>No obstante, s\u00ed podemos ofrecer una estimaci\u00f3n aproximada. Seg\u00fan c\u00e1lculos realizados por Reforesta (asociaci\u00f3n sin \u00e1nimo de lucro fundada en 1991 y declarada de Utilidad P\u00fablica) basados en datos proporcionados en las jornadas <em>Bosques y Cambio Clim\u00e1tico<\/em>, un \u00e1rbol de un encinar espa\u00f1ol libera 42 kilos de ox\u00edgeno al a\u00f1o de promedio. Si llevamos a cabo la extrapolaci\u00f3n de estas cifras, los 250.000 \u00e1rboles que hay en Central Park <strong>generar\u00edan en total unos 10,5 millones de kilos de ox\u00edgeno durante esos doce meses<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Central Park, tal vez el parqueurbano m\u00e1s conocido de todo el mundo \u2013no en vano ha sido escenario de numerosas pel\u00edculas, como las m\u00edticasDesayuno con diamantes (1961),Love Story (1970) o Cuando Harry encontr\u00f3 a Sally (1989)\u2013,<\/p>\n","protected":false},"author":9,"featured_media":69154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-69153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69153"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69153\/revisions"}],"predecessor-version":[{"id":69155,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69153\/revisions\/69155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69154"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}