{"id":69205,"date":"2017-09-20T08:52:03","date_gmt":"2017-09-20T12:52:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69205"},"modified":"2017-09-20T08:52:03","modified_gmt":"2017-09-20T12:52:03","slug":"puerto-rico-pierde-uno-de-sus-radares-por-la-entrada-de-maria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/puerto-rico-pierde-uno-de-sus-radares-por-la-entrada-de-maria\/","title":{"rendered":"Puerto Rico pierde uno de sus radares por la entrada de Mar\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-69206 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/puerto-rico-pierde-uno-de-sus-radares-por-la-entrada-de-maria.jpeg\" alt=\"\" width=\"294\" height=\"195\" \/>El Servicio Meteorolog\u00eda (SNM) en San Juan, Puerto Rico, perdi\u00f3 comunicaci\u00f3n con uno de sus radares, seg\u00fan confirmaron autoridades oficiales a medios de comunicaci\u00f3n de la vecina isla.<!--more--><\/p>\n<p>Roberto Garc\u00eda, director de Meteorolog\u00eda de Puerto Rico, inform\u00f3 que el radar ubicado en la Sierra de Cayey sali\u00f3 de funciones, seg\u00fan informa el peri\u00f3dico El Nuevo D\u00eda.<\/p>\n<p>El funcionario dijo que no era normal que el radar saliera de funcionamiento. \u201cNo es normal. Lo que pasa es que esto no es cualquier hurac\u00e1n. En Georges, el radar estuvo funcionando en todo momento. Pero, Georges fue menos intenso que esto\u201d, cita el peri\u00f3dico El Nuveo D\u00eda en su portal de internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio Meteorolog\u00eda (SNM) en San Juan, Puerto Rico, perdi\u00f3 comunicaci\u00f3n con uno de sus radares, seg\u00fan confirmaron autoridades oficiales a medios de comunicaci\u00f3n de la vecina isla.<\/p>\n","protected":false},"author":9,"featured_media":69206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-69205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69205"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69205\/revisions"}],"predecessor-version":[{"id":69207,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69205\/revisions\/69207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69206"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}