{"id":69211,"date":"2017-09-20T12:25:54","date_gmt":"2017-09-20T16:25:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69211"},"modified":"2017-09-20T12:51:36","modified_gmt":"2017-09-20T16:51:36","slug":"aerodom-aumentan-a-49-los-vuelos-cancelados-desde-rd-por-huracan-maria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aerodom-aumentan-a-49-los-vuelos-cancelados-desde-rd-por-huracan-maria\/","title":{"rendered":"Aerodom: aumentan a 49 los vuelos cancelados desde RD por hurac\u00e1n Mar\u00eda"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-69212 size-medium alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/780edcbcc18f1cea7ae5c0f8af3b9221_XL-300x195.jpg\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/780edcbcc18f1cea7ae5c0f8af3b9221_XL-300x195.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/780edcbcc18f1cea7ae5c0f8af3b9221_XL-768x500.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/09\/780edcbcc18f1cea7ae5c0f8af3b9221_XL.jpg 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Aeropuertos Dominicanos Siglo XXI (Aerodom) informa que debido al trayecto que sigue actualmente el hurac\u00e1n Mar\u00eda hay 49 vuelos cancelados entre hoy y ma\u00f1ana a distintas ciudades.<!--more--><br \/>\nLos vuelos afectados para hoy mi\u00e9rcoles, a trav\u00e9s del Aeropuerto Internacional de Las Am\u00e9ricas, Jos\u00e9 Francisco Pe\u00f1a G\u00f3mez (AILA-JFPG) son, hasta el momento, el 2037, 1437, 1637, 2138, 1938 y 2038 de JetBlue Airways desde y hacia San Juan, Puerto Rico; las operaciones de Pawa Dominicana 750 y 755 tambi\u00e9n desde y hacia San Juan, Puerto Rico; los vuelos 410 y 411 de InterCaribbean Airways que cubren la ruta Providenciales.<\/div>\n<div>Tambi\u00e9n el vuelo 108 de Copa Airlines procedente de Panam\u00e1; as\u00ed como las operaciones de carga de CaribEx 1911 y 1912 con origen y destino a Aguadilla, Puerto Rico; 8108 y 7108 de Federal Express tambi\u00e9n con la ruta Aguadilla, Puerto Rico; adem\u00e1s de los vuelos de MYN Aviation 405 y 406 desde Santiago de los Caballeros con destino San Juan, Puerto Rico.<\/div>\n<div>En el Aeropuerto Internacional Presidente Dr. Joaqu\u00edn Balaguer (AILI) fue cancelada la operaci\u00f3n 2216 y 2217 de Sunrise Airways con procedencia y destino a Puerto Pr\u00edncipe, Hait\u00ed.<\/div>\n<div>En tanto que, para el jueves 21 de septiembre ya han sido notificadas las cancelaciones en Las Am\u00e9ricas de los vuelos 2037, 1437, 1337, 1938 y 2938 de JetBlue Airways desde y hacia San Juan, Puerto Rico; 250 y 251 de Avianca con origen y destino a Bogot\u00e1, Colombia; los vuelos de Pawa Dominicana 750 y 755 desde y hacia San Juan, Puerto Rico y los vuelos 764 y 763 con procedencia y destino a Miami; el 1470 y 1473 de United Airlines con origen y destino a Newark, New Jersey; as\u00ed como los 556, 308, 128, 557, 129, 307 y 107 de Copa Airlines desde y hacia Panam\u00e1.<\/div>\n<div>De igual modo, en el Presidente Dr. Joaqu\u00edn Balaguer fueron afectados los vuelos 144 y 143 de Air Century desde y hacia San Juan, Puerto Rico, adem\u00e1s de los vuelos 132, 134, 131 y 133 desde y hacia Puerto Pr\u00edncipe, Hait\u00ed, operados por dicha aerol\u00ednea; asimismo, el 216, 2216, 217 y 2217 de Sunrise Airways que cubren la ruta de Puerto Pr\u00edncipe, Hait\u00ed.<\/div>\n<div>Las operaciones en los dem\u00e1s aeropuertos operados por Aerodom se desarrollan seg\u00fan su programaci\u00f3n regular.<\/div>\n<div>Aerodom recuerda a los pasajeros que es muy importante verificar con las aerol\u00edneas el estatus de sus vuelos previo a salir hacia el aeropuerto y que ofrece informaci\u00f3n actualizada a trav\u00e9s de su p\u00e1gina web www.aerodom.com, en su fan page en Facebook: Aerodom RD y su cuenta en Twitter: @AerodomRD<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aeropuertos Dominicanos Siglo XXI (Aerodom) informa que debido al trayecto que sigue actualmente el hurac\u00e1n Mar\u00eda hay 49 vuelos cancelados entre hoy y ma\u00f1ana a distintas ciudades.<\/p>\n","protected":false},"author":9,"featured_media":69212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-69211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69211"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69211\/revisions"}],"predecessor-version":[{"id":69214,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69211\/revisions\/69214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69212"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}