{"id":6947,"date":"2014-08-08T18:30:03","date_gmt":"2014-08-08T22:30:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6947"},"modified":"2014-08-08T13:47:05","modified_gmt":"2014-08-08T17:47:05","slug":"cuidado-estos-10-alimentos-te-ponen-de-mal-humor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuidado-estos-10-alimentos-te-ponen-de-mal-humor\/","title":{"rendered":"\u00a1Cuidado! Estos 10 alimentos te ponen de mal humor"},"content":{"rendered":"<p><label style=\"color: #0000ff;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/taza-cafe-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6948 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/taza-cafe-644x362-300x200.jpg\" alt=\"taza-cafe--644x362\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/taza-cafe-644x362-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/taza-cafe-644x362.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dietas<\/label>\u00a0ricas en grasas y cafe\u00edna pueden agriar tu car\u00e1cter. As\u00ed que es mejor que cuides o regules lo que comes.<!--more--><\/p>\n<p><strong>Cafe\u00edna<\/strong><\/p>\n<p>Una peque\u00f1a dosis puede ser el empuj\u00f3n que necesitamos para continuar el\u00a0<label style=\"color: #0000ff;\">d\u00eda<\/label>, pero el exceso de este componente altera nuestro estado, llegando a provocar ansiedad, nerviosismo y\u00a0<label style=\"color: #0000ff;\">cambios<\/label>\u00a0de\u00a0<label style=\"color: #0000ff;\">humor<\/label>.<\/p>\n<p><strong>\u2018Chips\u2019<\/strong><\/p>\n<p><label style=\"color: #0000ff;\">Uno<\/label>\u00a0de los peores alimentos que podemos a\u00f1adir a nuestra dieta, no solo por los cambios de humor. La mayor\u00eda de los aceites usados en su proceso, disminuye la actividad cerebral, generando estados negativos de \u00e1nimo.<\/p>\n<p><strong>Embutidos<\/strong><\/p>\n<p>Las carnes procesadas como los embutidos o las salchichas, contienen altos niveles de conservantes y otros productos que nos pueden provocar dolores de cabeza, mal humor y retenci\u00f3n de l\u00edquidos.<\/p>\n<p><strong>Margarina<\/strong><\/p>\n<p>A pesar de tener menos contenido en grasa animal, contiene grasa procesada que es causante entre otros muchos problemas, de los cambios de humor.<\/p>\n<p><strong>Patatas fritas<\/strong><\/p>\n<p>Suelen gustar a casi todo el mundo, pero es un alimento altamente nocivo para la salud. Al ser alimentos procesados y fritos, su digesti\u00f3n se hace m\u00e1s pesada, causando malestar.<\/p>\n<p><strong>Refrescos<\/strong><\/p>\n<p>Bebida eliminada por la mayor\u00eda de dietistas y m\u00e9dicos del mundo, debido a su alto contenido en az\u00facares refinados y gas. Suele provocar alteraci\u00f3n del estado de \u00e1nimo que comienza con un falso sentido de animaci\u00f3n.<\/p>\n<p><strong>Cacahuetes salados<\/strong><\/p>\n<p>A pesar de su alto contenido de prote\u00ednas, los cacahuetes que nos ponen en los bares suele producir migra\u00f1as y mal humor por el contenido de sal y aditivos.<\/p>\n<p><strong>Beagels<\/strong><\/p>\n<p>Este alimento procesado no es nada saludables por sus carbohidratos, causando un r\u00e1pido aumento de az\u00facar en la sangre.<\/p>\n<p><strong>Pasteler\u00eda<\/strong><\/p>\n<p>Alimentos saturados de mantequilla, aceites y az\u00facares refinados, que dan un placer moment\u00e1neo en el paladar pero su composici\u00f3n acaba por afectar al estado de \u00e1nimo. Aconsejan que si se tiene necesidad de az\u00facar lo mejor es tomar fruta.<\/p>\n<p><strong>Bebidas sin az\u00facar<\/strong><\/p>\n<p>A pesar de no tener az\u00facar, este tipo de bebidas contiene aspartamo, un aditivo cancer\u00edgeno y nocivo para la salud. Tambi\u00e9n afectan mucho al estado de \u00e1nimo, creando una monta\u00f1a rusa de emociones.<\/p>\n<p>Fuente:\u00a0<a style=\"color: #006e94;\" href=\"http:\/\/www.abc.es\/sociedad\/20140808\/abci-alimentos-ponen-humor-201408072115_1.html\" target=\"_blank\">ABC<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dietas\u00a0ricas en grasas y cafe\u00edna pueden agriar tu car\u00e1cter. As\u00ed que es mejor que cuides o regules lo que comes.<\/p>\n","protected":false},"author":3,"featured_media":6948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6947"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6947\/revisions"}],"predecessor-version":[{"id":6949,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6947\/revisions\/6949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6948"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}