{"id":69500,"date":"2017-10-02T07:32:55","date_gmt":"2017-10-02T11:32:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69500"},"modified":"2017-10-02T07:32:55","modified_gmt":"2017-10-02T11:32:55","slug":"este-hombre-se-desperto-al-oir-un-ruido-extrano-y-se-encontro-esto-en-su-porche-16-imagenes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/este-hombre-se-desperto-al-oir-un-ruido-extrano-y-se-encontro-esto-en-su-porche-16-imagenes\/","title":{"rendered":"Este hombre se despert\u00f3 al o\u00edr un ruido extra\u00f1o y se encontr\u00f3 esto en su porche (16 im\u00e1genes)"},"content":{"rendered":"<p>Hace poco compartirmos los momentos m\u00e1s divertidos \u201c<a href=\"http:\/\/www.boredpanda.es\/10-de-los-momentos-me-desperte-asi-mas-divertidos-que-han-sucedido-nunca\/\">Me despert\u00e9 as\u00ed<\/a>\u201c, y esta historia que le ha ocurrido a Tim Newton de Alaska pertenece definitivamente a esa categor\u00eda.<!--more--><\/p>\n<div class=\"hidden-mobile-paragraphs\">\n<p>\u201cTim se despert\u00f3 la semana pasada oyendo ruidos en el suelo, y mir\u00f3 hacia afuera. Sorprendido, agarr\u00f3 su c\u00e1mara y\u2026 \u00bfos lo pod\u00e9is creer? \u00a1All\u00ed estaba una mam\u00e1 lince con 7 peque\u00f1os!\u201d, pon\u00eda en su p\u00e1gina sobre fotograf\u00eda en Facebook.<\/p>\n<p>\u201cElla los llam\u00f3 y se pusieron justo delante de donde \u00e9l estaba (\u00a1al otro lado de la puerta con rejas!). \u00a1La fauna salvaje de Alaska es incre\u00edble! Siguieron jugando y corriendo por el porche y luego por el patio.\u201d<\/p>\n<p>\u201cHe sacado la conclusi\u00f3n de que los linces pasan un 1% de su vida persiguiendo conejos y un 99% persiguiendo a sus cr\u00edas. No paraban de jugar y armar trifulca.\u201d<\/p>\n<p class=\"post-content-source\">M\u00e1s informaci\u00f3n en:\u00a0<a href=\"https:\/\/www.facebook.com\/pg\/timnewtonphotography\/\" target=\"_blank\" rel=\"nofollow noopener\">Facebook<\/a>\u00a0|\u00a0<a href=\"https:\/\/fineartamerica.com\/profiles\/tim-newton.html\" target=\"_blank\" rel=\"nofollow noopener\">fineartamerica.com<\/a><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22154215_175666019665367_3755948942974761858_n-59cf5c7c3812f__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22154215_175666019665367_3755948942974761858_n-59cf5c7c3812f__880.jpg\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-69511\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area.jpg\" alt=\"\" width=\"857\" height=\"857\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area.jpg 880w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-768x768.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-500x500.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-400x400.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/felinos-en-el-area-120x120.jpg 120w\" sizes=\"auto, (max-width: 857px) 100vw, 857px\" \/><\/a><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22008479_175070429724926_2058312356996045682_n-59cf5c6d6a66a__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22008479_175070429724926_2058312356996045682_n-59cf5c6d6a66a__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22008479_175070429724926_2058312356996045682_n-59cf5c6d6a66a__880.jpg\" width=\"880\" height=\"704\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22046134_174828416415794_1459898045393331449_n-59cf5c6f66810__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22046134_174828416415794_1459898045393331449_n-59cf5c6f66810__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22046134_174828416415794_1459898045393331449_n-59cf5c6f66810__880.jpg\" width=\"880\" height=\"880\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22049946_175069786391657_1697120214737338485_n-59cf5c764d7d5__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22049946_175069786391657_1697120214737338485_n-59cf5c764d7d5__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22049946_175069786391657_1697120214737338485_n-59cf5c764d7d5__880.jpg\" width=\"880\" height=\"880\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22007830_174828343082468_2583598576507846295_n-59cf5c611abbd__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22007830_174828343082468_2583598576507846295_n-59cf5c611abbd__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22007830_174828343082468_2583598576507846295_n-59cf5c611abbd__880.jpg\" width=\"880\" height=\"587\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22050047_174828199749149_1562979235772166674_n-59cf5c77d0334__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22050047_174828199749149_1562979235772166674_n-59cf5c77d0334__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22050047_174828199749149_1562979235772166674_n-59cf5c77d0334__880.jpg\" width=\"880\" height=\"585\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22008383_175070433058259_9074310936018327177_n-59cf5c6beba54__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22008383_175070433058259_9074310936018327177_n-59cf5c6beba54__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22008383_175070433058259_9074310936018327177_n-59cf5c6beba54__880.jpg\" width=\"880\" height=\"587\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22007600_175069809724988_7480355674185582685_n-59cf5c5e296df__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22007600_175069809724988_7480355674185582685_n-59cf5c5e296df__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22007600_175069809724988_7480355674185582685_n-59cf5c5e296df__880.jpg\" width=\"880\" height=\"1320\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"21768100_174828223082480_1358723601856755304_n-59cf5c576b3e5__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=21768100_174828223082480_1358723601856755304_n-59cf5c576b3e5__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/21768100_174828223082480_1358723601856755304_n-59cf5c576b3e5__880.jpg\" width=\"880\" height=\"880\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22008183_174828086415827_2269595996106451614_n-59cf5c673564a__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22008183_174828086415827_2269595996106451614_n-59cf5c673564a__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22008183_174828086415827_2269595996106451614_n-59cf5c673564a__880.jpg\" width=\"880\" height=\"1320\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22007518_174828293082473_7080932165005497623_n-59cf5c5b298c4__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22007518_174828293082473_7080932165005497623_n-59cf5c5b298c4__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22007518_174828293082473_7080932165005497623_n-59cf5c5b298c4__880.jpg\" width=\"880\" height=\"587\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22008140_175069776391658_7937767810784750760_n-59cf5c65af3a1__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22008140_175069776391658_7937767810784750760_n-59cf5c65af3a1__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22008140_175069776391658_7937767810784750760_n-59cf5c65af3a1__880.jpg\" width=\"880\" height=\"704\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22008319_174828266415809_3177875385025128982_n-59cf5c68a3235__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22008319_174828266415809_3177875385025128982_n-59cf5c68a3235__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22008319_174828266415809_3177875385025128982_n-59cf5c68a3235__880.jpg\" width=\"880\" height=\"587\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22089418_174828333082469_1798039609637499939_n-59cf5c7ab37ab__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22089418_174828333082469_1798039609637499939_n-59cf5c7ab37ab__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22089418_174828333082469_1798039609637499939_n-59cf5c7ab37ab__880.jpg\" width=\"880\" height=\"587\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22007805_174828743082428_8622724861007746444_n-59cf5c5fab6b9__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22007805_174828743082428_8622724861007746444_n-59cf5c5fab6b9__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22007805_174828743082428_8622724861007746444_n-59cf5c5fab6b9__880.jpg\" width=\"880\" height=\"880\" \/><\/p>\n<\/div>\n<div class=\"shareable-post-image\">\n<p id=\"22046686_175663809665588_5950716886077605380_n-59cf5c7140777__880\" class=\"attachment-link-container shareable-image-block\" data-href=\"http:\/\/www.boredpanda.es\/familia-linces-porche-tin-newton-alaska\/?image_id=22046686_175663809665588_5950716886077605380_n-59cf5c7140777__880.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.boredpanda.com\/blog\/wp-content\/uploads\/2017\/09\/22046686_175663809665588_5950716886077605380_n-59cf5c7140777__880.jpg\" width=\"880\" height=\"880\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hace poco compartirmos los momentos m\u00e1s divertidos \u201cMe despert\u00e9 as\u00ed\u201c, y esta historia que le ha ocurrido a Tim Newton de Alaska pertenece definitivamente a esa categor\u00eda.<\/p>\n","protected":false},"author":12,"featured_media":69511,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-69500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69500"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69500\/revisions"}],"predecessor-version":[{"id":69512,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69500\/revisions\/69512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69511"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}