{"id":69532,"date":"2017-10-03T13:48:33","date_gmt":"2017-10-03T17:48:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69532"},"modified":"2017-10-03T13:48:33","modified_gmt":"2017-10-03T17:48:33","slug":"jumbo-impulsa-dinamismo-comercial-en-puerto-plata-con-la-apertura-de-su-duodecima-sucursal","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/jumbo-impulsa-dinamismo-comercial-en-puerto-plata-con-la-apertura-de-su-duodecima-sucursal\/","title":{"rendered":"Jumbo impulsa dinamismo comercial en Puerto Plata con la apertura de su duod\u00e9cima sucursal"},"content":{"rendered":"<div id=\"p_p_id_contentviewerportlet_WAR_newsportlet_INSTANCE_441acb4f259f4fb8a0286c078d11be00_\" class=\"portlet-boundary portlet-boundary_contentviewerportlet_WAR_newsportlet_  portlet-static portlet-static-end content-viewer-portlet \">\n<div class=\"td-portlet\">\n<section id=\"portlet_contentviewerportlet_WAR_newsportlet_INSTANCE_441acb4f259f4fb8a0286c078d11be00\" class=\"portlet\">\n<div class=\"portlet-content\">\n<div class=\" portlet-content-container\">\n<div class=\"portlet-body\">\n<div class=\"last td-viewer full-access\">\n<div class=\"detalle-texto\">\n<div class=\"text\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-69533 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/image_content_8899914_20171002135304.jpg\" alt=\"\" width=\"614\" height=\"328\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/image_content_8899914_20171002135304.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/image_content_8899914_20171002135304-300x160.jpg 300w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/>San Felipe de Puerto Plata, RD.- Con la bendici\u00f3n de monse\u00f1or Julio C\u00e9sar Corniel Amaro, Centro Cuesta Nacional (CCN) abri\u00f3 hoy en esta ciudad la duod\u00e9cima sucursal de hipermercados Jumbo, que se espera impactar\u00e1 positivamente en la econom\u00eda y el dinamismo comercial local, creando m\u00e1s de 300 empleos directores e indirectos.<\/p>\n<div class=\"text\"><!--more--><\/div>\n<p>&nbsp;<\/p>\n<p>Con m\u00e1s de 4,000 metros cuadrados, la nueva sucursal de Jumbo est\u00e1 ubicada en la avenida Manolo Tavares Justo esquina avenida Luis Ginebra, en la urbanizaci\u00f3n Buenaventura de esta costera ciudad del Norte del pa\u00eds.<\/p>\n<p>Desde su apertura este jueves, cientos de clientes y consumidores visitaron la nueva tienda, la m\u00e1s grande de esta provincia, que despliega una agresiva oferta de m\u00e1s 65 mil art\u00edculos y estar\u00e1 apoyando a los productores agr\u00edcolas de la zona, con la compra directa de los rubros agr\u00edcolas que se cultivan en sus \u00e1reas rurales.<\/p>\n<p><i>\u201cDesde Centro Cuesta Nacional (CCN) y Jumbo estamos convencidos de que nuestra llegada a las diferentes provincias del pa\u00eds deben responder a un modelo de negocio inclusivo, donde la comunidad forme parte activa y protag\u00f3nica del engranaje econ\u00f3mico que se desarrolla alrededor de nuestras tiendas\u201d<\/i>, manifest\u00f3 Madelyn Mart\u00ednez, directora de mercadeo corporativo de CCN.<\/p>\n<p>Coherente con su propuesta de innovaci\u00f3n y diferenciaci\u00f3n, Jumbo llega a Puerto Plata con precios bajos y competitivos poniendo al alcance de toda la provincia productos de calidad mundial, as\u00ed como importantes marcas en las categor\u00edas de supermercado, electrodom\u00e9sticos, hogar, deportes, juguetes, escolares, ropa, calzados, ferreter\u00eda, jardiner\u00eda, librer\u00eda, entre otros.<\/p>\n<p>Como es propio de la marca, esta apertura viene acompa\u00f1ada de una agresiva din\u00e1mica de ofertas y opciones de servicios, los cuales llegar\u00e1n a los clientes por diferentes medios: prensa, redes sociales, p\u00e1gina Web (www.jumbo.com.do), encartes, radio y televisi\u00f3n local. De igual forma, la tienda ofrecer\u00e1 un calendario de actividades y promociones exclusivas de la sucursal.<\/p>\n<p>Entre sus fortalezas principales, Jumbo cuenta con Agro CCN, la primera planta dominicana de procesamiento de carnes de res y cerdo certificada bajo la norma internacional ISO 9001:2008, ofreciendo a los clientes productos de la mejor calidad.<\/p>\n<p>Asimismo, ofrecer\u00e1 panes y productos de reposter\u00eda reci\u00e9n horneados bajo su marca La Panera. Tendr\u00e1 disponible el Certified Angus Beef, una carne Angus de la mejor calidad, la cual es importada, fresca y nunca congelada. Y su \u00e1rea de frutas y vegetales asegura productos con la mayor frescura para el consumidor.<\/p>\n<p>Est\u00e1n sus marcas propias, tanto en el \u00e1rea de alimentos como de no alimentos. Cuenta con un amplio portafolio de marcas exclusivas, como la marca local L\u00edder y otras de importaci\u00f3n como Food Club, Simply Done, Valu Time, Tippy Toes y Paws. Las ventajas de estas llamadas marcas blancas lo constituye la relaci\u00f3n calidad-precio que les caracteriza.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>El \u00e1rea textil es tambi\u00e9n uno de los grandes pilares de Jumbo y se ha caracterizado por ser pioneros en creaciones de colecciones de moda de grandes dise\u00f1adores dominicanos a precios asequibles. Del mismo modo, cuenta con sus marcas propias Mondino y Creatif, as\u00ed como la marca exclusiva Hering y Hering Kids, que ofrecen en cada temporada piezas a la moda y de calidad.<\/p>\n<p>El proyecto de Centro Cuesta Nacional para enaltecer los valores dominicanos, Orgullo de mi Tierra, hace casi 4 a\u00f1os que presento Descubre Puerto Plata, para revalorizar a la Novia del Atl\u00e1ntico como el punto tur\u00edstico m\u00e1s completo del Caribe. Como parte de este proyecto, la iniciativa Coraz\u00f3n Dominicano, apoya a los microempresarios ofreci\u00e9ndoles acompa\u00f1amiento en sus procesos de mejoras continuas y de disponer la plataforma de CCN para la distribuci\u00f3n de sus productos.<\/p>\n<p>Jumbo Puerto Plata reforzar\u00e1 su posicionamiento como la principal tienda por departamentos del pa\u00eds, brind\u00e1ndole al visitante la posibilidad de comprar todo lo que necesita en un solo lugar. Los clientes tendr\u00e1n a su alcance una amplia gama de servicios y productos financieros que servir\u00e1n como formas de pago, tales como La Tarjeta Suma CCN con el Banco del Progreso, Tarjeta Plus CCN Mastercard con el Banco Popular, Bonos CCN y facilidades de Financiamientos para comprar art\u00edculos en tienda, recargas de m\u00f3viles en las cajas registradoras y venta de boletas para conciertos.<\/p>\n<p>Tambi\u00e9n contar\u00e1 con balanzas de pesaje en las cajas, verificadores de precios, amplia \u00e1rea de parqueos de autos y motores, acceso con la mejor ubicaci\u00f3n, entre otras comodidades.<\/p>\n<p>De igual forma, estar\u00e1n presentes instituciones aliadas que consolidan a\u00fan m\u00e1s el concepto de todo en un solo lugar. Dentro de los negocios aliados est\u00e1n Orange, VITASALUD, Equivalenza, Kopcalecas, Helados Bon, Caribe Express, entre otros.<\/p>\n<p><i>\u201cNuestra llegada a Puerto Plata tiene el prop\u00f3sito de convertirse en un motor que complemente el desarrollo tur\u00edstico de la zona, as\u00ed como otros sectores productivos que desde ya son nuestros suplidores. De esta manera nos convertiremos en sus aliados comerciales para la compra de sus productos\u201d<\/i>, enfatiz\u00f3 Mart\u00ednez.<\/p>\n<p>Como de costumbre en Centro Cuesta Nacional, no se realiz\u00f3 un gran acto de apertura,<\/p>\n<p>para as\u00ed destinar esos recursos a las siguientes instituciones ben\u00e9ficas: Casa de Albergue de Martina, con 60 a\u00f1os de servicio, que acoge a 22 ni\u00f1as entre los 5 y 18 a\u00f1os de edad, ofreciendo alojamiento, educaci\u00f3n y alimentaci\u00f3n; El Hogar de Ancianos Hijas de la Caridad, con 44 a\u00f1os de servicio, donde brinda un servicio integral a los 48 ancianos que actualmente residen en el hogar, y Si Se Puede, un proyecto cautivador que trabaja con ni\u00f1os de escasos recursos, educ\u00e1ndolos en el \u00e1mbito musical y despertando su inter\u00e9s por una nueva pasi\u00f3n.<\/p>\n<p><i>\u201cEn Jumbo estamos convencidos de que las mejores causas son aquellas que son capaces de unirnos entorno a la solidaridad y el apoyo de aquellos que lo necesitan\u201d,<\/i>\u00a0expuso la Sra. Mart\u00ednez.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div id=\"p_p_id_articletopicsportlet_WAR_newsportlet_INSTANCE_e37a799f88fe445eb99fbd1b24e5dc82_\" class=\"portlet-boundary portlet-boundary_articletopicsportlet_WAR_newsportlet_  portlet-static portlet-static-end article-topics-portlet detalle-metadatos\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>San Felipe de Puerto Plata, RD.- Con la bendici\u00f3n de monse\u00f1or Julio C\u00e9sar Corniel Amaro, Centro Cuesta Nacional (CCN) abri\u00f3 hoy en esta ciudad la duod\u00e9cima sucursal de hipermercados Jumbo, que se espera impactar\u00e1 positivamente en la econom\u00eda y el dinamismo comercial local, creando m\u00e1s de 300 empleos directores e indirectos.<\/p>\n","protected":false},"author":9,"featured_media":69533,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-69532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69532"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69532\/revisions"}],"predecessor-version":[{"id":69534,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69532\/revisions\/69534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69533"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}