{"id":69566,"date":"2017-10-07T08:31:56","date_gmt":"2017-10-07T12:31:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69566"},"modified":"2017-10-07T08:31:56","modified_gmt":"2017-10-07T12:31:56","slug":"como-saber-si-lo-bloquearon-en-whatsapp-o-facebook","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-saber-si-lo-bloquearon-en-whatsapp-o-facebook\/","title":{"rendered":"C\u00f3mo saber si lo bloquearon en WhatsApp o Facebook"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/bloquo-redes.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69570\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/bloquo-redes.png\" alt=\"\" width=\"640\" height=\"338\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/bloquo-redes.png 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/bloquo-redes-300x158.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>La\u00a0<strong>seguridad\u00a0<\/strong>y la\u00a0<strong>privacidad\u00a0<\/strong>se encuentran entre las principales demandas de los usuarios, y por ende, los bloqueos de contactos.<!--more--><\/p>\n<p>M\u00e1s all\u00e1 de conocer c\u00f3mo bloquear a una persona en aplicaciones como\u00a0<strong>Facebook\u00a0<\/strong>o\u00a0<strong>WhatsApp<\/strong>, uno de los aspectos m\u00e1s importantes para los usuarios es saber si fueron bloqueados por alguno de sus contactos.<\/p>\n<p>En WhatsApp existen\u00a0<strong>configuraciones de privacidad\u00a0<\/strong>con las que se podr\u00e1 enga\u00f1ar a los contactos y hacerles creer que se los bloqueo. Por ejemplo, si antes se ve\u00eda la\u00a0<strong>imagen de perfil de un contacto\u00a0<\/strong>y ya no la ve, lo m\u00e1s seguro es que lo haya bloqueado.<\/p>\n<p>Lo mismo ocurre cuando\u00a0<strong>deja de ver su estado<\/strong>, su \u00faltima conexi\u00f3n, cuando est\u00e1 en l\u00ednea, cuando no puede invitarlo a grupos o llamarlo, cuando le env\u00eda mensajes y solo aparece un \u201ccheck\u201d en vez de dos. Si todas estas se\u00f1ales aparecen juntas para un mismo contacto, esa persona decidi\u00f3 bloquearle de sus contactos.<\/p>\n<p>En Facebook es m\u00e1s sencillo saber si fui bloqueado. Algunos de los\u00a0<strong>indicios m\u00e1s importantes\u00a0<\/strong>empiezan por el hecho de que no pueda encontrar a la persona en cuesti\u00f3n al colocar su nombre en el buscador de la red social, no pueda ver sus comentarios en perfiles de amigos en com\u00fan o incluso en grupos, y no pueda ver sus publicaciones en los grupos que tienen en com\u00fan.<\/p>\n<p>Adem\u00e1s, si alguna vez tuvo una conversaci\u00f3n con esa persona a trav\u00e9s de\u00a0<strong>Facebook Messenger<\/strong>, ya no ver\u00e1 su foto, apareciendo solamente como \u201cUsuario de Facebook\u201d en la bandeja de entrada.<\/p>\n<p>Incluso si tiene el enlace directo al perfil de esa persona, si al colocarlo en la barra de direcciones genera el mensaje \u201c<strong>No se encontr\u00f3 o no est\u00e1 disponible el perfil<\/strong>\u201d, quiere decir que est\u00e1 bloqueado. Adem\u00e1s, las interacciones, incluyendo las fotograf\u00edas, ser\u00e1n borradas.<\/p>\n<p><a href=\"http:\/\/www.iprofesional.com\/notas\/256839-redes-sociales-software-tecnologia-ciberseguridad-Como-saber-si-lo-bloquearon-en-WhatsApp-o-Facebook\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0seguridad\u00a0y la\u00a0privacidad\u00a0se encuentran entre las principales demandas de los usuarios, y por ende, los bloqueos de contactos.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-69566","post","type-post","status-publish","format-standard","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69566"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69566\/revisions"}],"predecessor-version":[{"id":69572,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69566\/revisions\/69572"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}