{"id":69625,"date":"2017-10-09T11:44:54","date_gmt":"2017-10-09T15:44:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69625"},"modified":"2017-10-09T11:44:54","modified_gmt":"2017-10-09T15:44:54","slug":"canciones-para-siempre-lleva-a-puerto-plata-el-lado-mas-romantico-de-milanes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/canciones-para-siempre-lleva-a-puerto-plata-el-lado-mas-romantico-de-milanes\/","title":{"rendered":"\u00abCanciones para siempre\u00bb lleva a Puerto Plata el lado m\u00e1s rom\u00e1ntico de Milan\u00e9s"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-69626 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/canciones-para-siempre-lleva-a-puerto-plata-el-lado-mas-romantico-de-milanes.jpeg\" alt=\"\" width=\"367\" height=\"262\" \/>El cantautor cubano Pablo Milan\u00e9s llev\u00f3 al Anfiteatro de Puerto Plata una selecci\u00f3n de su extenso repertorio en un show que dio preferencia a los temas de amor. \u201cVengan a m\u00ed jard\u00edn, y juntos hagamos un solo canto a la felicidad que nos espera\u201d, dijo desde el escenario el artista, invitando con las letras de la canci\u00f3n \u201cMarginal\u201d, a disfrutar de \u201cCanciones para siempre\u201d.<!--more--><\/p>\n<p>As\u00ed recib\u00eda este escenario de la costa norte la noche del pasado s\u00e1bado al cantante nacido en Bayamo, Cuba, hace 74 a\u00f1os. \u201cDe todos los rincones del mundo que visito, donde tengo m\u00e1s amigos es en Rep\u00fablica Dominicana, m\u00e1s que amigos, hermanos\u201d, expres\u00f3 la primera vez que habl\u00f3 con el p\u00fablico, al que prometi\u00f3 ofrecer algunas canciones de sus 54 discos, que cree que aqu\u00ed no conoc\u00edan.<\/p>\n<p>Acompa\u00f1ado de una banda de tres m\u00fasicos (teclados, bajo y bater\u00eda), capaces de hacer los temas de Milan\u00e9s con aires de balada pop (\u201cSi ella me faltara alguna vez\u201d) o los que conten\u00edan elementos del son montuno (\u201cEn saco roto\u201d), que mostraron esa experiencia distinta de escuchar en vivo y bien interpretada una canci\u00f3n que el p\u00fablico ha escuchado bastante en grabaciones.<\/p>\n<div id=\"FIOnDemandWrapper_fiInstance_101888_2_6033853\" class=\"FIOnDemandWrapper\"><\/div>\n<p>La clave se dejaba escuchar por el percusionista, quien daba el color caribe\u00f1o cuando era necesario, por ejemplo en \u201cDe que callada manera\u201d, en la que hicieron una mezcla especial entre el son y el rock, que termin\u00f3 con una descarga de bater\u00eda.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/63.134.216.63:8025\/res\/content\/486\/485671\/p\/\/201710082347112.jpg?=1507506226352\" alt=\"\" \/><\/p>\n<p>Sentado como siempre, con su atril en frente, el cantante present\u00f3 \u201cCual si fuera morir\u201d, tambi\u00e9n de \u201cRenacimiento\u201d, diciendo que fue primero un poema al que luego puso m\u00fasica. De este disco tambi\u00e9n hizo un tema musicalmente interesante, ya que es dedicado a un ritmo de Cuba, que seg\u00fan expres\u00f3 es poco conocido hasta en su mismo pa\u00eds. As\u00ed sus m\u00fasicos entonaron los acordes de \u201cHomenaje al changui\u201d.<\/p>\n<p>A \u00abComienzo y final de una verde ma\u00f1ana\u00bb, sigui\u00f3 \u00abLos d\u00edas de gloria\u00bb, una canci\u00f3n oto\u00f1al que reflexiona sobre la edad y la experiencia de los a\u00f1os vividos. Con \u00ab\u00c1mame como soy\u00bb inici\u00f3 la segunda parte del show, en la que Milan\u00e9s dio protagonismo a temas m\u00e1s conocidos. De esta manera lleg\u00f3 el turno de \u00abPara vivir\u00bb, que provoc\u00f3 que los presentes tomaran sus celulares y grabaran el momento en que hac\u00eda esta, considerada por algunos su canci\u00f3n m\u00e1s importante.<\/p>\n<p>\u00abYolanda\u00bb, \u00abEl breve espacio\u00bb (en la que fue ayudado a cantar por la audiencia que se puso de pies); \u00abAmo esta isla\u00bb, fue tocada por sus m\u00fasicos con elementos propios del latin jazz, fue la pen\u00faltima canci\u00f3n que interprtet\u00f3. Al final, un solo de bajo dio entrada a \u00abYo no te pido\u00bb, tema con el que finalmente se despidi\u00f3 de \u00abLa Novia del Atl\u00e1ntico\u00bb.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/63.134.216.63:8025\/res\/content\/486\/485671\/p\/\/201710082347111.jpg?=1507506247761\" alt=\"\" \/><br \/>\n<strong><em>Pavel Nu\u00f1ez<\/em><\/strong><\/p>\n<p><strong>El anfitri\u00f3n\u00a0<\/strong><br \/>\nEl concierto, que\u00a0cont\u00f3 con la producci\u00f3n local de Gialp Production, que preside el empresario puertoplateno Elvis Peralta,\u00a0tuvo como telonero a Pavel N\u00fa\u00f1ez, quien cargado de sus conocidas canciones puso el p\u00fablico a tono para recibir a Pablo Milan\u00e9s. En varias ocasiones el cantautor dominicano expres\u00f3 lo honrado que estaba de abrir el concierto del veterano cantante cubano. Aproximadamente media hora estuvo el autor de \u00abTe d\u00ed\u00bb, \u00abBethania\u00bb y \u00abViene gente\u00bb en el escenario del anfiteatro de Puerto Plata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantautor cubano Pablo Milan\u00e9s llev\u00f3 al Anfiteatro de Puerto Plata una selecci\u00f3n de su extenso repertorio en un show que dio preferencia a los temas de amor. \u201cVengan a m\u00ed jard\u00edn, y juntos hagamos un solo canto a la felicidad que nos espera\u201d, dijo desde el escenario el artista, invitando con las letras de la canci\u00f3n \u201cMarginal\u201d, a disfrutar de \u201cCanciones para siempre\u201d.<\/p>\n","protected":false},"author":9,"featured_media":69626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-69625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69625"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69625\/revisions"}],"predecessor-version":[{"id":69627,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69625\/revisions\/69627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69626"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}