{"id":69678,"date":"2017-10-11T21:40:18","date_gmt":"2017-10-12T01:40:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69678"},"modified":"2017-10-11T21:40:18","modified_gmt":"2017-10-12T01:40:18","slug":"terry-crews-confiesa-tambien-haber-sido-acosado-sexualmente-por-productor-de-hollywood","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/terry-crews-confiesa-tambien-haber-sido-acosado-sexualmente-por-productor-de-hollywood\/","title":{"rendered":"Terry Crews confiesa tambi\u00e9n haber sido acosado sexualmente por productor de Hollywood"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-feature-0215.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-69679\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-feature-0215.jpg\" alt=\"\" width=\"640\" height=\"361\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-feature-0215.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-feature-0215-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>Contin\u00faa el esc\u00e1ndalo por las acusaciones contra\u00a0Harvey Weinstein, conocido productor de Hollywood que\u00a0abus\u00f3 sexualmente de varios rostros del entretenimiento por casi tres d\u00e9cadas.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div>A prop\u00f3sito de las recientes denuncias por parte de celebridades como\u00a0Angelina Jolie y Gwyneth Paltrow,\u00a0entre otras figuras, el actor\u00a0Terry Crews\u00a0(49) opt\u00f3 por revelar su\u00a0experiencia de abuso sexual\u00a0a trav\u00e9s de su cuenta oficial en Twitter este martes.<\/p>\n<\/div>\n<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-y-esposa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-69680 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-y-esposa.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-y-esposa.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/terry-crews-y-esposa-300x225.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>Mediante las redes sociales, el actor expres\u00f3 su incomodidad afirmando que \u00abesto de Harvey Weinstein me est\u00e1 dando\u00a0estr\u00e9s postraum\u00e1tico.\u00a0Porque\u00a0esto tambi\u00e9n me ocurri\u00f3 a m\u00ed\u00bb.<\/p>\n<\/div>\n<div>\u00abMi esposa y yo est\u00e1bamos en un evento de Hollywood el a\u00f1o pasado y un ejecutivo de alto nivel de Hollywood\u00a0se acerc\u00f3 a mi y tante\u00f3 mis partes privadas. Reaccionando, le dije\u00a0&#8216;\u00bfQu\u00e9 est\u00e1s haciendo?&#8217;\u00a0Mi esposa vio todo, ambos lo miramos como a un loco. \u00c9l\u00a0solo sonri\u00f3 como un imb\u00e9cil\u00bb, confes\u00f3 Crews.<\/p>\n<\/div>\n<div>Asimismo, la estrella aclar\u00f3 que \u00abno pate\u00f3 su trasero\u00bb porque pens\u00f3 en el impacto negativo que tendr\u00eda en los medios. \u00abUn hombre negro de 108 kilos golpea a un poderoso de Hollywood\u00bb, habr\u00eda sido el titular de los medios seg\u00fan Crews, el cual tambi\u00e9n agrega que\u00a0\u00abhabr\u00eda terminado en la c\u00e1rcel\u00bb.<\/p>\n<\/div>\n<div>Adem\u00e1s, el actor detr\u00e1s de \u00ab\u00bfD\u00f3nde est\u00e1n las rubias?\u00bb agreg\u00f3 que no quiso denunciar los hechos en su debido momento, ya que nadie creer\u00eda en su palabra.<\/p>\n<\/div>\n<div>Terry Crews ha sido uno de los \u00faltimos en revelar ser\u00a0v\u00edctima de acoso por parte del alto ejecutivo, sentenciando que Weinstein \u00abno es el \u00fanico depredador de la industria\u00bb.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contin\u00faa el esc\u00e1ndalo por las acusaciones contra\u00a0Harvey Weinstein, conocido productor de Hollywood que\u00a0abus\u00f3 sexualmente de varios rostros del entretenimiento por casi tres d\u00e9cadas.<\/p>\n","protected":false},"author":12,"featured_media":69679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-69678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69678"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69678\/revisions"}],"predecessor-version":[{"id":69681,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69678\/revisions\/69681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69679"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}