{"id":69696,"date":"2017-10-12T08:57:34","date_gmt":"2017-10-12T12:57:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=69696"},"modified":"2017-10-12T08:57:34","modified_gmt":"2017-10-12T12:57:34","slug":"medias-rojas-de-boston-cancelan-a-su-dirigente-john-farrell","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/medias-rojas-de-boston-cancelan-a-su-dirigente-john-farrell\/","title":{"rendered":"Medias Rojas de Boston cancelan a su dirigente John Farrell"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/ex-manager-de-boston.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-69697  alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/ex-manager-de-boston.jpg\" alt=\"\" width=\"329\" height=\"220\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/ex-manager-de-boston.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/10\/ex-manager-de-boston-300x200.jpg 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/><\/a><\/p>\n<p class=\"DETALLE_N_titulo \">Boston (EE.UU.), (EFE).- La salida \u201canunciada\u201d de John Farrell como piloto de los Medias Rojas de Boston se confirm\u00f3 cuando el equipo anunci\u00f3 este mi\u00e9rcoles de manera oficial que no seguir\u00e1 en el cargo la pr\u00f3xima temporada, a pesar que le quedaba uno m\u00e1s de contrato.<!--more--><\/p>\n<div id=\"texto\" class=\"texto_txt\">\n<div class=\"DETALLE_N_texto \">\n<p><span id=\"ctl14_lblMostra\">Farrell, que dirigi\u00f3 al equipo a los primeros t\u00edtulos de divisi\u00f3n consecutivos, pero luego cay\u00f3 eliminado en la primera ronda de los playoffs, al final le cost\u00f3 el puesto.<\/span><\/p>\n<p>El veterano manejador fue dejado en libertad por el equipo, de acuerdo a lo expresado por el presidente de operaciones de\u00a0<span class=\"classCadenaBusqueda\">b\u00e9isbol<\/span>\u00a0de los Medias Rojas, Dave Dombrowski, que no dio detalles sobre las razones que le llevaron a despedir a Farrell.<\/p>\n<p>La marca de Farrell al frente de los Medias Rojas fue de 432-378 en un periodo de cinco a\u00f1os de monta\u00f1a rusa que incluy\u00f3 un campeonato de la Serie Mundial en 2013 y dos \u00faltimos lugares.<\/p>\n<p>Se convirti\u00f3 el \u00fanico piloto de los Medias Rojas que gana tres coronas del Este de la Liga Americana y ocupa el sexto lugar en la lista de victorias hist\u00f3rica del equipo.<\/p>\n<p>Pero Farrell tambi\u00e9n se convirti\u00f3 en un saco de boxeo para los frustrados fan\u00e1ticos y comentaristas radiales.<\/p>\n<p>Mientras todos los pilotos est\u00e1n bajo fuego por los movimientos dentro de juego que no funcionan, Farrell fue objeto de un mayor escrutinio que muchos.<\/p>\n<p>Los te\u00f3ricos de la conspiraci\u00f3n sostienen que habr\u00eda sido despedido en 2015 si no hubiera perdido las \u00faltimas seis semanas de la temporada para someterse a un tratamiento contra el c\u00e1ncer.<\/p>\n<p>Dombrowski no quiso decir si Farrell se habr\u00eda mantenido al frente del equipo si los Medias Rojas hubiesen eliminado en la Serie Divisional a los Astros de Houston, que fueron los ganadores 3-1 al mejor de cinco partidos.<\/p>\n<p>Lo \u00fanico que confirm\u00f3 Dombrowski fue que no hab\u00eda sido una decisi\u00f3n tomada a la ligera sino todo lo contrario, que se hab\u00eda llegado a la conclusi\u00f3n que el equipo necesitaba una nueva voz dentro del vestuario y una nueva imagen ante el p\u00fablico.<\/p>\n<p>A pesar de otro final en primer lugar en la Divisi\u00f3n Este de la Liga Americana, la impopularidad de los Medias Rojas creci\u00f3 bastante esta temporada.<\/p>\n<p>Las audiencias de televisi\u00f3n en las horas punta en la cadena de los Medias Rojas New England Sports Network (NESN) bajaron un 15 por ciento este a\u00f1o respecto al pasado, que fue la temporada final del toletero dominicano David Ortiz.<\/p>\n<p>Dombrowski se reuni\u00f3 con su personal de operaciones deportivas luego de la derrota del lunes y tom\u00f3 la decisi\u00f3n de cortar sus lazos con Farrell.<\/p>\n<p>El martes, present\u00f3 su decisi\u00f3n en una reuni\u00f3n cara a cara con el due\u00f1o del equipo, John Henry, el presidente CEO, Sam Kennedy, mientras que el presidente, Tom Werner, escuch\u00f3 toda la conversaci\u00f3n en teleconferencia.<\/p>\n<p>El mi\u00e9rcoles en la ma\u00f1ana, Dombrowski cit\u00f3 a Farrell para que acudiese a las oficinas del Fenway Park, donde le comunic\u00f3 la noticia de su despido, y de acuerdo al gerente general de los Medias Rojas s\u00f3lo recibi\u00f3 una pregunta por parte del ya exmanejador del que dijo que lo vio \u201cdecepcionado\u201d por la decisi\u00f3n que hab\u00edan tomado de que no siguiese con el equipo.<\/p>\n<p>Dombrowski ahora podr\u00e1 seleccionar al piloto por s\u00ed mismo. Al tomar las riendas de la organizaci\u00f3n a finales de la temporada 2015, Dombrowski hered\u00f3 a un Farrell en el puesto que ya sufr\u00eda de c\u00e1ncer.<\/p>\n<p>Y aunque Dombrowski nunca dej\u00f3 entrever su incomodidad, llegando incluso a felicitar a Farrell la semana pasada cuando los Medias Rojas aseguraron el bander\u00edn del Este LA, tampoco fue demasiado efusivo en su alabanza.<\/p>\n<p>Dombrowski solo ha contratado dos pilotos en las pasadas 12 temporadas como fueron Jim Leyland, con quien trabaj\u00f3 tanto con los Marlins de Florida como con los Tigres de Detroit, pero que est\u00e1 retirado, y Brad Ausmus, un potencial candidato a reemplazar a Farrell.<\/p>\n<p>Ausmus fue recientemente despedido por los Tigres tras una temporada en la que terminaron en el s\u00f3tano con 98 derrotas.<\/p>\n<p>Los Medias Rojas podr\u00edan mirar dentro de la organizaci\u00f3n a su exreceptor y capit\u00e1n del equipo Jason Varitek, que tiene una gran aceptaci\u00f3n entre los fan\u00e1ticos.<\/p>\n<p>Otras posibilidades podr\u00edan incluir a Gary DiSarcina, que fue el entrenador de la banca con Farrell, y al boricua Alex Cora, que tambi\u00e9n ocupa el mismo puesto con los Astros de Houston.<\/p>\n<p>Cora, que ha sido entrevistado por varias organizaciones en las pasadas temporadas y quien fue jugador de los Medias Rojas de 2005 al 2008.<\/p>\n<p>Dombrowski tambi\u00e9n tiene una gran relaci\u00f3n con el piloto y miembro del Sal\u00f3n de la Fama Tony La Russa, quien recientemente cumpli\u00f3 73 a\u00f1os y no ha dirigido desde 2001 cuando estaba con los Cardenales de San Luis, pero ha sido el responsable de la reconstrucci\u00f3n de los Diamondbacks de Arizona.EFE<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Boston (EE.UU.), (EFE).- La salida \u201canunciada\u201d de John Farrell como piloto de los Medias Rojas de Boston se confirm\u00f3 cuando el equipo anunci\u00f3 este mi\u00e9rcoles de manera oficial que no seguir\u00e1 en el cargo la pr\u00f3xima temporada, a pesar que le quedaba uno m\u00e1s de contrato.<\/p>\n","protected":false},"author":12,"featured_media":69697,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-69696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=69696"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69696\/revisions"}],"predecessor-version":[{"id":69698,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/69696\/revisions\/69698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/69697"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=69696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=69696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=69696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}