{"id":70136,"date":"2017-11-06T10:29:39","date_gmt":"2017-11-06T14:29:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=70136"},"modified":"2017-11-06T10:29:39","modified_gmt":"2017-11-06T14:29:39","slug":"republica-dominicana-conmemora-hoy-el-173-aniversario-de-su-constitucion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/republica-dominicana-conmemora-hoy-el-173-aniversario-de-su-constitucion\/","title":{"rendered":"Rep\u00fablica Dominicana conmemora hoy el 173 aniversario de su Constituci\u00f3n"},"content":{"rendered":"<div class=\"text\"><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/nueva constitucion republica dominicana noticias sc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21000 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/nueva constitucion republica dominicana noticias sc.jpg\" alt=\"\" width=\"310\" height=\"479\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/nueva%20constitucion%20republica%20dominicana%20noticias%20sc.jpg 310w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/11\/nueva%20constitucion%20republica%20dominicana%20noticias%20sc-194x300.jpg 194w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" \/><\/a>SANTO<\/b>\u00a0<b>DOMINGO<\/b>.<span class=\"Apple-converted-space\">\u00a0<\/span>Hoy se conmemora un nuevo aniversario de la creaci\u00f3n del conjunto de reglas fundamentales que rigen la organizaci\u00f3n y funcionamiento del Estado Dominicano y sus instituciones. En San Crist\u00f3bal, as\u00ed como en todo el pa\u00eds, se celebrar\u00e1 el 173 aniversario de la Constituci\u00f3n.<!--more-->A lo largo de este per\u00edodo, la Carta Magna ha sido reformada 39 veces, a pesar de que al realizar la gran reforma constitucional del 2010 (la n\u00famero 38) que crea el estado democr\u00e1tico y de derecho e incorpora una suma importante de nuevos derechos fundamentales, as\u00ed como las garant\u00edas para que se puedan respetar y hacer valer, se entend\u00eda que pasar\u00edan muchos a\u00f1os antes de una nueva.<\/p>\n<p>Para muchos juristas, las modificaciones, cuestionadas algunas en su momento, han sido necesarias para activar una cultura constitucional inexistente o dormida, y que propicie la consolidaci\u00f3n de un verdadero Estado Social y Democr\u00e1tico de Derecho.<\/p>\n<p>El presidente del Tribunal Constitucional, Milton Ray Guevara, entidad creada con la Constituci\u00f3n del 2010, una de las m\u00e1s avanzadas de Iberoam\u00e9rica, al igual que la Defensora del Pueblo, Zoila Mart\u00ednez, hacen un llamado a todos los ciudadanos y a la administraci\u00f3n del Estado a respetar la Carta Magna, para as\u00ed escalar a nuevos estadios de progreso, democracia y libertad en el pa\u00eds.<\/p>\n<p>Guevara considera que las cuatro constituciones m\u00e1s importantes que ha tenido la Rep\u00fablica Dominicana son las del 6 de noviembre de 1844, la primera; en segundo lugar la del 19 de febrero de 1858, conocida como la de Moca; le sigue la del 29 de abril de 1963, la Constituci\u00f3n de Juan Bosch, y la del 26 de enero del 2010.<\/p>\n<p>El presidente del Constitucional se\u00f1ala que \u201csalvo el fat\u00eddico art\u00edculo 210, que fue incorporado por Pedro Santana a los constituyentes de San Crist\u00f3bal\u201d en el 1844, esa es la Constituci\u00f3n que organiz\u00f3 el Estado dominicano con las estructuras esenciales de un r\u00e9gimen presidencial, con un Congreso Nacional conformado en dos c\u00e1maras, la incorporaci\u00f3n de derechos fundamentales y la separaci\u00f3n de los poderes del Estado, que es un mecanismo de limitaci\u00f3n de los poderes de los gobernantes.<\/p>\n<p>\u201cLa de Moca, esa es una Constituci\u00f3n liberal, empapada o impregnada del pensamiento liberal de sectores intelectuales importantes de Santiago de los Caballeros\u201d, dijo.<\/p>\n<p>En tanto que la del profesor Bosch, en la cual se establece que la naci\u00f3n dominicana descansaba esencialmente en el trabajo de su gente, agrupa una serie de conquistas sociales y de principios rectores que le dieron la caracter\u00edstica de ser la primera Constituci\u00f3n social, describi\u00f3 Ray Guevara.<\/p>\n<p>\u201cAhora, la mejor Constituci\u00f3n que nosotros hemos tenido en la Rep\u00fablica Dominicana es la del 26 de enero del 2010 que ha sido considerada como la m\u00e1s avanzada de Iberoam\u00e9rica y esa Constituci\u00f3n crea entre nosotros el Estado Democr\u00e1tico y de Derecho, incorpora una suma importante de nuevos derechos fundamentales, pero adem\u00e1s, establece las garant\u00edas para que se puedan respetar y hacer valer ese derecho\u201d, puntualiz\u00f3.<\/p>\n<p>Ese criterio de Guevara es compartido por el procurador general de la Rep\u00fablica, Jean Alain Rodr\u00edguez, y el jurista Luis Miguel Pereyra, quien a\u00f1ade que \u201cpor primera vez tenemos una Constituci\u00f3n que pretende hacer la letra y esp\u00edritu de la Constituci\u00f3n, no mera filosof\u00eda sino derecho vivo, de aplicaci\u00f3n inmediata a los poderes p\u00fablicos y a los ciudadanos\u201d.<\/p>\n<p>Describi\u00f3 adem\u00e1s, que la principal importancia de esa Carta Magna radica en la creaci\u00f3n del Tribunal Constitucional, cuyas decisiones son vinculantes para todos los derechos p\u00fablicos.<\/p>\n<\/div>\n<div class=\"entretitulo\">\u00bfOtra modificaci\u00f3n?<\/div>\n<div class=\"text\">Apenas dos a\u00f1os despu\u00e9s de haberse reformado la Constituci\u00f3n para permitir la reelecci\u00f3n consecutiva del Presidente de la Rep\u00fablica, ya hay sectores que hablan de hacer otra.Al responder respecto a si se deber\u00eda estar modificando constantemente la Carta Magna, el presidente del TC dijo que no se puede mantener una poblaci\u00f3n atada a normas como si \u00e9stas no evolucionan con relaci\u00f3n a las nuevas realidades de la vida econ\u00f3mica y social pero que \u201ctampoco es deseable que la Constituci\u00f3n sea constantemente reformada. Estim\u00f3 que esto \u00faltimo depende de determinados factores hist\u00f3ricos del r\u00e9gimen pol\u00edtico, de la voluntad de los poderes p\u00fablicos y los ciudadanos.<\/p>\n<p>\u201cYo dir\u00eda que la Constituci\u00f3n no es inmutable, que la Constituci\u00f3n no se puede quedar sin reformar, pero tampoco es deseable que en cada suspiro que se d\u00e9, se modifique la Constituci\u00f3n\u201d, resalt\u00f3.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO\u00a0DOMINGO.\u00a0Hoy se conmemora un nuevo aniversario de la creaci\u00f3n del conjunto de reglas fundamentales que rigen la organizaci\u00f3n y funcionamiento del Estado Dominicano y sus instituciones. En San Crist\u00f3bal, as\u00ed como en todo el pa\u00eds, se celebrar\u00e1 el 173 aniversario de la Constituci\u00f3n.<\/p>\n","protected":false},"author":12,"featured_media":50683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83,88],"tags":[],"class_list":["post-70136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=70136"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70136\/revisions"}],"predecessor-version":[{"id":70137,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70136\/revisions\/70137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/50683"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=70136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=70136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=70136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}