{"id":70191,"date":"2017-11-13T12:41:54","date_gmt":"2017-11-13T16:41:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=70191"},"modified":"2017-11-13T12:41:54","modified_gmt":"2017-11-13T16:41:54","slug":"brayelin-jineiry-y-gaila-comandan-la-ofensiva-de-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/brayelin-jineiry-y-gaila-comandan-la-ofensiva-de-rd\/","title":{"rendered":"Br\u00e1yelin, Jineiry y Gaila comandan la ofensiva de RD"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/reinas-del-caribe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-70193 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/reinas-del-caribe.jpg\" alt=\"\" width=\"308\" height=\"340\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/reinas-del-caribe.jpg 308w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/reinas-del-caribe-272x300.jpg 272w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/a>SANTA MARTA, COLOMBIA. La Selecci\u00f3n de Voleibol Femenino, categor\u00eda Sub-23, de la Rep\u00fablica Dominicana consigui\u00f3 anoche su primera victoria al vencer en forma f\u00e1cil tres sets por cero (25-15, 25-21,y 25-17) a Venezuela, en el choque de apertura del Torneo de Voleibol de los Juegos Boliviarianos que se celebran aqu\u00ed.<!--more--><\/p>\n<p>El ataque ofensivo fue guiado por Br\u00e1yelin Mart\u00ednez, quien logr\u00f3 anotar 16 tantos gracias a potentes remates que cayeron en terreno venezolano.<\/p>\n<p>Otras que aportaron fueron Jineiry Mart\u00ednez se fue con 12 tantos, Gaila Gonz\u00e1lez marc\u00f3 nueve, mientras que Natalia Mart\u00ednez y Ang\u00e9lica Hinojosa concluyeron con cinco tantos.<\/p>\n<p>En el deporte ofensivo, Dominicana super\u00f3 a sus rivales en ataque con 36 positivos, mientras que Venezuela hizo 24 ataques.<\/p>\n<p>En la defensa, las dominicanas realizaron 11 bloqueos, y Venezuela apenas siete.<\/p>\n<p><strong>Tiro con arco<\/strong><\/p>\n<p>El seleccionado de tiro con arco tuvo una destacada jornada en el segundo d\u00eda de competencias eliminatorias. Carlina Guzm\u00e1n quebr\u00f3 dos marcas nacionales en la distancia de los 50 metros.<\/p>\n<p>Guzm\u00e1n tuvo 342 puntos y dej\u00f3 atr\u00e1s la marca de 338 hecha por Julissa Espinal, y que en la prueba 2 por 50 metros logr\u00f3 un puntaje de 678. Este lunes arrancan las eliminaciones directas individuales, donde estar\u00e1n compitiendo los seleccionados nacionales de arquer\u00eda.<\/p>\n<p><strong>Boxeo<\/strong><\/p>\n<p>Rohan Polanco Emiliano se coloc\u00f3 en la segunda ronda del peso welter (69 kilos) al vencer sin contratiempos por 5-0 a Bryan Alejandro Angulo George, de Venezuela en el torneo de boxeo de los Juegos Bolivarianos que se celebra en el Coliseo de Gaira, Ring de Boxeo.<\/p>\n<p>En otro combate, en la divisi\u00f3n mosca (52 kilos) el dominicano Rodrigo Marte de la Roa qued\u00f3 eliminado al perder 0-5 ante Ceiber David \u00c1vila Segura.<\/p>\n<p><strong>EL DATO<\/strong><\/p>\n<p><strong>En la primera<\/strong><\/p>\n<p>Jornada de remo la Rep\u00fablica Dominicana ocupa la primera posici\u00f3n en la modalidad dos pares de remos cortos masculino con tiempo de 3:24:614<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTA MARTA, COLOMBIA. La Selecci\u00f3n de Voleibol Femenino, categor\u00eda Sub-23, de la Rep\u00fablica Dominicana consigui\u00f3 anoche su primera victoria al vencer en forma f\u00e1cil tres sets por cero (25-15, 25-21,y 25-17) a Venezuela, en el choque de apertura del Torneo de Voleibol de los Juegos Boliviarianos que se celebran aqu\u00ed.<\/p>\n","protected":false},"author":12,"featured_media":70193,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-70191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=70191"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70191\/revisions"}],"predecessor-version":[{"id":70194,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70191\/revisions\/70194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/70193"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=70191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=70191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=70191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}