{"id":70286,"date":"2017-11-22T02:23:03","date_gmt":"2017-11-22T06:23:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=70286"},"modified":"2017-11-22T02:23:03","modified_gmt":"2017-11-22T06:23:03","slug":"murio-el-actor-y-musico-david-cassidy-de-la-serie-the-partridge-family","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/murio-el-actor-y-musico-david-cassidy-de-la-serie-the-partridge-family\/","title":{"rendered":"Muri\u00f3 el actor y m\u00fasico David Cassidy, de la serie \u00abThe Partridge Family\u00bb"},"content":{"rendered":"<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/david-cassidy-getty.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-70287\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/11\/david-cassidy-getty.jpg\" alt=\"\" width=\"509\" height=\"383\" \/><\/a>El actor y m\u00fasico estadounidense<strong>\u00a0David Cassidy,<\/strong>\u00a0quien protagoniz\u00f3 en la d\u00e9cada de 1970 la serie de televisi\u00f3n \u00ab<strong>The Partridge Family<\/strong>\u00ab, muri\u00f3 este martes a los 67 a\u00f1os, inform\u00f3 la familia.<\/p>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">\u00ab<strong>David muri\u00f3 rodeado por los que am\u00f3, con regocijo en su coraz\u00f3n y libre del dolor que lo afect\u00f3 durante tanto tiempo\u00bb<\/strong>, dijo la familia en un comunicado.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">El m\u00fasico hab\u00eda sido\u00a0hospitalizado el pasado mi\u00e9rcoles y\u00a0<strong>se encontraba en \u00abestado cr\u00edtico\u00bb despu\u00e9s de unos meses en los que su salud se ha ido deteriorando.<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<figure class=\"element element-image col-xs-12\">\n<div class=\"single-image\">\n<div class=\"shares\"><\/div>\n<p><img decoding=\"async\" id=\"5IQ4E3CQBFH4PO27BOKZLSINKM\" class=\"image-lazy\" src=\"https:\/\/www.infobae.com\/new-resizer\/LO_m8926WR66jg7AoG9GHfWyXNQ=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/11\/21232930\/david-cassidy1.jpg\" alt=\"David Cassidy en una foto de 1995 (Reuters)\" width=\"750\" height=\"421.875\" data-url=\"http:\/\/www.infobae.com\/america\/entretenimiento\/2017\/11\/21\/murio-el-musico-david-cassidy-de-la-serie-the-partridge-family\/%235IQ4E3CQBFH4PO27BOKZLSINKM\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/LO_m8926WR66jg7AoG9GHfWyXNQ=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/11\/21232930\/david-cassidy1.jpg\" \/><\/div><figcaption class=\"\"><span class=\"credit\">David Cassidy en una foto de 1995 (Reuters)<\/span><\/figcaption><\/figure>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">El cantante, quien a comienzos de este a\u00f1o confes\u00f3 que\u00a0<strong>batallaba contra la p\u00e9rdida de memoria y la demencia<\/strong>, hab\u00eda tenido recientemente\u00a0<strong>problemas con su ri\u00f1\u00f3n e h\u00edgado y requer\u00eda un trasplante.<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">A inicios de este a\u00f1o,<strong>\u00a0Cassidy anunci\u00f3 que se ve\u00eda obligado a concluir una carrera musical de 50 a\u00f1os a causa de la artritis que sufr\u00eda<\/strong>, pues, seg\u00fan dijo a la revista\u00a0<em>People<\/em>, convert\u00eda en un martirio tocar la guitarra, as\u00ed como por los constantes viajes que obligaban sus giras.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"element element-rawhtml col-xs-12\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wJYSu2OVCGM?feature=oembed\" width=\"840\" height=\"630\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\"><em>\u00abThe Partridge Family\u00bb era una original mezcla de musical y sit-com sobre la vida de una familia estadounidense\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"element element-rawhtml col-xs-12\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/S3fPtMuBtMs?feature=oembed\" width=\"840\" height=\"630\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\"><strong>Tras el \u00e9xito que sabore\u00f3 en la d\u00e9cada de 1970, tras varios exitosos \u00e1lbumes y apariciones televisivas<\/strong>, Cassidy lidi\u00f3 en a\u00f1os posteriores con\u00a0<strong>problemas de alcohol que propiciaron su arresto en varias ocasiones por conducir con niveles por encima de lo permitido<\/strong>\u00a0y luego a un proceso de rehabilitaci\u00f3n en 2014.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<figure class=\"element element-image col-xs-12\">\n<div class=\"single-image\">\n<div class=\"shares\"><\/div>\n<p><img decoding=\"async\" id=\"3VFDY5W5QFH6BCPPHBWNYM5KT4\" class=\"image-lazy\" src=\"https:\/\/www.infobae.com\/new-resizer\/lFwGGJf2zSbJkf0VNR4yWmJSDhE=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/11\/21232824\/2017-11-22T022236Z_104104277_RC16BC6F92F0_RTRMADP_3_PEOPLE-DAVIDCASSIDY.jpg\" alt=\"David Cassidy tras ser detenido en 2013 por conducir ebrio (REUTERS)\" width=\"750\" height=\"941.2435824301198\" data-url=\"http:\/\/www.infobae.com\/america\/entretenimiento\/2017\/11\/21\/murio-el-musico-david-cassidy-de-la-serie-the-partridge-family\/%233VFDY5W5QFH6BCPPHBWNYM5KT4\" data-original=\"https:\/\/www.infobae.com\/new-resizer\/lFwGGJf2zSbJkf0VNR4yWmJSDhE=\/600x0\/filters:quality(100)\/s3.amazonaws.com\/arc-wordpress-client-uploads\/infobae-wp\/wp-content\/uploads\/2017\/11\/21232824\/2017-11-22T022236Z_104104277_RC16BC6F92F0_RTRMADP_3_PEOPLE-DAVIDCASSIDY.jpg\" \/><\/div><figcaption class=\"\"><span class=\"credit\">David Cassidy tras ser detenido en 2013 por conducir ebrio (REUTERS)<\/span><\/figcaption><\/figure>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">Al a\u00f1o siguiente,<strong>\u00a0el cantante se declar\u00f3 en bancarrota.<\/strong><\/p>\n<\/div>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-print-12\">\n<p class=\"element element-paragraph\">El int\u00e9rprete es hijo de<strong>\u00a0Tony Cassidy<\/strong>, actor y ganador de un Premio Tony, e hijastro de Shirley Jones, protagonista de \u00abThe Partridge Family\u00bb.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El actor y m\u00fasico estadounidense\u00a0David Cassidy,\u00a0quien protagoniz\u00f3 en la d\u00e9cada de 1970 la serie de televisi\u00f3n \u00abThe Partridge Family\u00ab, muri\u00f3 este martes a los 67 a\u00f1os, inform\u00f3 la familia.<\/p>\n","protected":false},"author":12,"featured_media":70287,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-70286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=70286"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70286\/revisions"}],"predecessor-version":[{"id":70288,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70286\/revisions\/70288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/70287"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=70286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=70286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=70286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}