{"id":70499,"date":"2017-12-06T14:00:43","date_gmt":"2017-12-06T18:00:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=70499"},"modified":"2017-12-06T14:00:43","modified_gmt":"2017-12-06T18:00:43","slug":"disney-esta-listo-para-comprar-fox-por-una-millonada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/disney-esta-listo-para-comprar-fox-por-una-millonada\/","title":{"rendered":"Disney est\u00e1 listo para comprar Fox por una millonada"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/fox-marvel-disney-simpsons-700x394.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-70500\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/fox-marvel-disney-simpsons-700x394.jpg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/fox-marvel-disney-simpsons-700x394.jpg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/fox-marvel-disney-simpsons-700x394-300x169.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>Durante algunas semanas hab\u00eda corrido\u00a0el rumor casi fantasioso\u00a0de que Disney podr\u00eda comprar a la\u00a0<strong>21th Century Fox<\/strong>, abriendo con ello la posibilidad de que los h\u00e9roes de Marvel que a\u00fan son propiedad de ese estudio se integren a las cintas del MCU. Todo sonaba como un disparate, pero al parecer es verdad.<!--more--><\/p>\n<p>De acuerdo con\u00a0un reporte de CNBC, ambas compa\u00f1\u00edas se encuentran cerca de cerrar un trato multimillonario, donde Disney pondr\u00eda sobre mesa cerca de\u00a0<strong>USD $60 mil millones<\/strong>\u00a0para adquirir la divisi\u00f3n de cine de la Fox junto con otras \u00e1reas tremendamente populares:<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-785982\" src=\"https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men.jpg\" sizes=\"(max-width: 1190px) 100vw, 1190px\" srcset=\"https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men.jpg 1190w, https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men-250x141.jpg 250w, https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men-768x432.jpg 768w, https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men-700x394.jpg 700w, https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men-120x68.jpg 120w, https:\/\/media.betazeta.com\/fayerwayer\/2017\/12\/06111416\/fox-marvel-x-men-160x90.jpg 160w\" alt=\"\" \/><\/p>\n<blockquote><p>El acuerdo contempla la venta de Nat Geo, Star, Fox, redes deportivas regionales, estudios de cine y participaciones en Sky y Hulu, entre otras propiedades. Lo que quedar\u00eda en Fox incluye sus divisiones de noticias y noticias de negocios, red de transmisi\u00f3n y Fox Sports.<\/p><\/blockquote>\n<p>Se afirma que\u00a0<strong>el trato podr\u00eda cerrarse tan pronto como la siguiente semana<\/strong>, y de lograrse esto, representar\u00eda la pieza final en la plataforma de Disney, antes de llevar sus producciones al siguiente nivel, incluyendo el Universo Cinematogr\u00e1fico de Marvel, y\u00a0su nuevo servicio de streaming que competir\u00e1 contra Netflix.<\/p>\n<p>De lograrse este acuerdo no s\u00f3lo\u00a0<strong>X-Men<\/strong>\u00a0se integrar\u00eda a la galer\u00eda de h\u00e9roes de Marvel, sino tambi\u00e9n\u00a0<strong>Deadpool, los New Mutants y hasta Fantastic Four.<\/strong>Candidatos ideales para las futuras fases de este universo.<\/p>\n<p>Encima de ello\u00a0entrar\u00edan nuevas propiedades intelectuales a las arcas de Disney, como\u00a0<strong>Avatar, Planet of the Apes, Alien, Predator, The Simpsons, Family Guy y hasta Die Hard.<\/strong><\/p>\n<p>Netflix est\u00e1 en serios problemas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante algunas semanas hab\u00eda corrido\u00a0el rumor casi fantasioso\u00a0de que Disney podr\u00eda comprar a la\u00a021th Century Fox, abriendo con ello la posibilidad de que los h\u00e9roes de Marvel que a\u00fan son propiedad de ese estudio se integren a las cintas del MCU. Todo sonaba como un disparate, pero al parecer es verdad.<\/p>\n","protected":false},"author":12,"featured_media":70500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387,4],"tags":[],"class_list":["post-70499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=70499"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70499\/revisions"}],"predecessor-version":[{"id":70501,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70499\/revisions\/70501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/70500"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=70499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=70499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=70499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}