{"id":70540,"date":"2017-12-09T17:31:36","date_gmt":"2017-12-09T21:31:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=70540"},"modified":"2017-12-09T17:31:36","modified_gmt":"2017-12-09T21:31:36","slug":"ocupan-125-sacos-de-ajo-en-interior-de-jeepeta-en-dajabon","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ocupan-125-sacos-de-ajo-en-interior-de-jeepeta-en-dajabon\/","title":{"rendered":"Ocupan 125 sacos de ajo en interior de jeepeta en Dajab\u00f3n"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-70542\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1.jpeg\" alt=\"\" width=\"858\" height=\"483\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1.jpeg 1280w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1-300x169.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1-768x432.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/12\/WhatsApp-Image-2017-12-09-at-4.01.57-PM-1-1024x576.jpeg 1024w\" sizes=\"auto, (max-width: 858px) 100vw, 858px\" \/><\/a>DAJAB\u00d3N, Rep\u00fablica Dominicana.-<\/strong>\u00a0Militares del Ej\u00e9rcito de la Rep\u00fablica Dominicana (ERD) y miembros de la Direcci\u00f3n General de Capacitaci\u00f3n y Entrenamiento Militar ocuparon un veh\u00edculo cargado con 125 sacos de ajo, introducidos\u00a0clandestinamente al territorio dominicano.<!--more--><\/p>\n<p>Los militares destacados para servicio en la zona de Carbonera, detuvieron la Jeepeta de color negro placa G 491910, cuyo conductor al notar la presencia de los efectivos militares emprendi\u00f3 la huida dejando abandonado el veh\u00edculo.<\/p>\n<p>Luego de ser revisada la jeepeta, los agentes encontraron los sacos con ajo que habr\u00edan sido introducidos al territorio nacional a trav\u00e9s de la frontera Dominico-Haitiana.<\/p>\n<p>El veh\u00edculo conjuntamente con la mercanc\u00eda fue trasladado a la Fortaleza Beller en esta provincia sede del 10mo. Batall\u00f3n, para los fines correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DAJAB\u00d3N, Rep\u00fablica Dominicana.-\u00a0Militares del Ej\u00e9rcito de la Rep\u00fablica Dominicana (ERD) y miembros de la Direcci\u00f3n General de Capacitaci\u00f3n y Entrenamiento Militar ocuparon un veh\u00edculo cargado con 125 sacos de ajo, introducidos\u00a0clandestinamente al territorio dominicano.<\/p>\n","protected":false},"author":12,"featured_media":70542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-70540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=70540"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70540\/revisions"}],"predecessor-version":[{"id":70543,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/70540\/revisions\/70543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/70542"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=70540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=70540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=70540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}