{"id":7067,"date":"2014-08-13T13:09:21","date_gmt":"2014-08-13T17:09:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=7067"},"modified":"2015-09-20T18:17:54","modified_gmt":"2015-09-20T22:17:54","slug":"realizan-vigilia-frente-a-oficinas-administrativas-de-corapplata-en-protesta-por-privatizacion-cobranza-del-agua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/realizan-vigilia-frente-a-oficinas-administrativas-de-corapplata-en-protesta-por-privatizacion-cobranza-del-agua\/","title":{"rendered":"Realizan vigilia frente a oficinas administrativas de CORAPPLATA en protesta por privatizaci\u00f3n cobranza del agua"},"content":{"rendered":"<p><span style=\"color: #000000;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/VIGILIA_EN_CONTRA_DE_LA_CORAAPPLATA_II.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7068\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/VIGILIA_EN_CONTRA_DE_LA_CORAAPPLATA_II-300x162.jpg\" alt=\"VIGILIA_EN_CONTRA_DE_LA_CORAAPPLATA_II\" width=\"448\" height=\"242\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/VIGILIA_EN_CONTRA_DE_LA_CORAAPPLATA_II-300x162.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/VIGILIA_EN_CONTRA_DE_LA_CORAAPPLATA_II.jpg 719w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/a>PUERTO PLATA.- Desde tempranas horas de la ma\u00f1ana de este martes, decenas de ciudadanos, dirigentes pol\u00edticos y los miembros de las diferentes organizaciones que integran el Comit\u00e9 Pro Puerto, participaron en la vigilia realizada en la calle Villanueva casi al frente a las oficinas administrativas de la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPLATA) como postura de protesta en contra de la reciente privatizaci\u00f3n al servicio de agua potable\u201d.<\/span><\/p>\n<p><!--more--><\/p>\n<p style=\"color: #000000;\">En la cercan\u00edas a la referida vigilia fue apostado un contingente formado por casi una docena de agentes de la Polic\u00eda Nacional quienes supuestamente fueron enviados all\u00ed atendiendo una solicitud de las autoridades del Gobierno para prevenir la ocurrencia de des\u00f3rdenes y acciones que alborotaran el orden p\u00fablico.<\/p>\n<p>Dicha acci\u00f3n de protesta fue apoyada por varios dirigentes pol\u00edticos tal es el caso del Partido Alianza Pa\u00eds que lidera el doctor Guillermo Moreno, organizaci\u00f3n cuyo comit\u00e9 de Puerto Plata mediante un comunicado afirmaba que \u201cla rebeli\u00f3n ciudadana est\u00e1 justificada en contra los funcionarios y pol\u00edticos corruptos, que mantienen secuestrada la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPPLATA) para sus fines particulares y de grupo\u201d.<\/p>\n<p>Asimismo, todo el staff del programa radial matutino \u201cLa Ma\u00f1ana Caliente\u201d que se difunde diariamente por la emisora 97.3 FM (La Voz del Atl\u00e1ntico), transmiti\u00f3 en vivo todas las incidencias de esta vigilia donde los integrantes del Comit\u00e9 Pro Puerto de Puerto Plata reiteraron que \u201clos moradores de esta provincia est\u00e1n manifestando su ira ciudadana, exigiendo la despolitizaci\u00f3n de la CORAAPPLATA que una empresa gubernamental, sanear la n\u00f3mina de empleados, hacer un uso transparente de los recursos econ\u00f3micos, nombrar un nuevo Consejo Directivo.<\/p>\n<p>Los manifestantes tambi\u00e9n exigieron que la CORAAPPLATA debe ser dirigida por miembros pulcros y honestos, adem\u00e1s de eliminar todas las botellas nombradas por el senador Francis Vargas, el director de CORAAPLATA y algunos miembros del Consejo Directivo que mantienen sumida en la inoperancia a esta entidad rectora de los servicios de agua potable y el sistema de alcantarillados en toda la provincia de Puerto Plata.<\/p>\n<p>En dicha vigilia fue observado el actual diputado y aspirante a senador por el oficialista Partido de la Liberaci\u00f3n Dominicana (PLD); licenciado Javier Clark, quien llam\u00f3 a todos los Puertoplate\u00f1os a rechazar el contrato de privatizaci\u00f3n del \u00e1rea comercial de la CORAAPLATA ya que seg\u00fan dijo el mismo perjudicar\u00e1 a las clases m\u00e1s necesitada de toda la provincia.<\/p>\n<p>Mientras que dirigentes pol\u00edticos del Partido Revolucionario Dominicano (PRD) como es el caso del ex diputado Carlos Mart\u00ednez Arango (Papito) y la regidora Rosa D\u00fancan (Rochy) estuvieron respaldando esta protesta pac\u00edfica que concluy\u00f3 sin mayores contratiempos.<\/p>\n<p>[<a href=\"http:\/\/costanortetv3.tv\/index.php\/k2-component\/regionales\/4975-realizan-vigilia-frente-a-oficinas-administrativas-de-corapplata-en-protesta-por-privatizacion-cobranza-del-agua\">FUENTE<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- Desde tempranas horas de la ma\u00f1ana de este martes, decenas de ciudadanos, dirigentes pol\u00edticos y los miembros de las diferentes organizaciones que integran el Comit\u00e9 Pro Puerto, participaron en la vigilia realizada en la calle Villanueva casi al frente a las oficinas administrativas de la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPLATA) como postura de protesta en contra de la reciente privatizaci\u00f3n al servicio de agua potable\u201d.<\/p>\n","protected":false},"author":12,"featured_media":7068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-7067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=7067"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7067\/revisions"}],"predecessor-version":[{"id":7070,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7067\/revisions\/7070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/7068"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=7067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=7067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=7067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}