{"id":71292,"date":"2018-01-04T18:19:12","date_gmt":"2018-01-04T22:19:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71292"},"modified":"2018-01-04T18:19:12","modified_gmt":"2018-01-04T22:19:12","slug":"los-ocho-cambios-que-trae-whatsapp-para-este-ano-2018","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-ocho-cambios-que-trae-whatsapp-para-este-ano-2018\/","title":{"rendered":"Los Ocho Cambios Que Trae WhatsApp Para Este A\u00f1o 2018"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/whatsapp.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-71297 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/whatsapp.png\" alt=\"\" width=\"443\" height=\"254\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/whatsapp.png 443w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/whatsapp-300x172.png 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/whatsapp-595x340.png 595w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/a>Hasta hoy, las videollamadas solo pueden realizarse entre dos personas. Pero ahora podr\u00e1n hacerse de manera grupal entre varios contactos y ver a todos los integrantes al mismo tiempo. La pantalla se dividir\u00e1 seg\u00fan las personas que formen parte de la videollamada.<!--more--><\/p>\n<p><strong><br \/>\nPersonalizaci\u00f3n<br \/>\n<\/strong>En las redes sociales, no solo el contenido es importante, tambi\u00e9n la apariencia. Es por esto que una de las nuevas funciones que podr\u00edan debutar este a\u00f1o ser\u00eda la de cambiar la apariencia de los diferentes chats, modificando el cl\u00e1sico color verde por el que cada usuario desee.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mejores fotos<br \/>\n<\/strong>Otra novedad de la aplicaci\u00f3n estar\u00e1 enfocada en el ahorro de memoria o espacio en el equipo. Esto ser\u00e1 posible gracias a la optimizaci\u00f3n inteligente de las im\u00e1genes. Permitir\u00e1 detectar de qu\u00e9 tipo de imagen se trata y la comprimir\u00e1 en funci\u00f3n de la calidad que esta necesite.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"outstream_article\" data-id=\"80\" data-m=\"{&quot;i&quot;:80,&quot;p&quot;:75,&quot;n&quot;:&quot;article-inlineOutstreamAd&quot;,&quot;t&quot;:&quot;inlineOutstreamAd&quot;,&quot;o&quot;:5}\">\n<div id=\"inlineoutstreamcontainer\" class=\"inlineOutstreamContainer\">\n<div id=\"apn_display_container_xniis6j5vrp\" class=\"\"><strong>Manejar grupo<br \/>\n<\/strong>Los administradores en grupos de WhatsApp tendr\u00e1n mayor control sobre qui\u00e9n habla y qui\u00e9n no. Podr\u00e1n silenciar a una persona en espec\u00edfico por una cantidad de tiempo determinada. Hoy, los administradores solo pod\u00edan agregar o eliminar gente, cambiar el nombre o la imagen del grupo.<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Para negocios<br \/>\n<\/strong>WhatsApp Business es una versi\u00f3n creada de manera exclusiva para negocios. Ser\u00e1 independiente y dirigida a peque\u00f1os y medianos negocios y empresarios, como tambi\u00e9n a grandes corporaciones.<\/p>\n<p>Ya ha sido experimentada por algunos usuarios.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Reportar falla<br \/>\n<\/strong>Frente a un error en la aplicaci\u00f3n, los usuarios pueden reportarlo en el men\u00fa de ajustes. Pero ahora ser\u00e1 m\u00e1s f\u00e1cil, ya que cuando el usuario reconozca un error o comportamiento extra\u00f1o en la app, podr\u00e1 agitar el tel\u00e9fono con la aplicaci\u00f3n abierta lo que se entender\u00e1 como un reporte.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cambiar n\u00famero<br \/>\n<\/strong>La app ahora tendr\u00e1 un asistente que se encargar\u00e1 de enviar un mensaje a todos los contactos de la agenda en caso de que un usuario haya cambiado de n\u00famero. El objetivo es que todos queden notificados y actualicen el contacto con el nuevo n\u00famero.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Videos youtube<br \/>\n<\/strong>Buscando hacer m\u00e1s sencillo el uso de YouTube en la aplicaci\u00f3n, ahora cuando alguien env\u00ede un enlace o link de un video, este se podr\u00e1 reproducir sin necesidad de salir de la aplicaci\u00f3n. De hecho, ni siquiera ser\u00e1 necesario abandonar la conversaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta hoy, las videollamadas solo pueden realizarse entre dos personas. Pero ahora podr\u00e1n hacerse de manera grupal entre varios contactos y ver a todos los integrantes al mismo tiempo. La pantalla se dividir\u00e1 seg\u00fan las personas que formen parte de la videollamada.<\/p>\n","protected":false},"author":12,"featured_media":71297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-71292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71292"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71292\/revisions"}],"predecessor-version":[{"id":71298,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71292\/revisions\/71298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71297"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}