{"id":71402,"date":"2018-01-13T11:11:54","date_gmt":"2018-01-13T15:11:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71402"},"modified":"2018-01-13T11:11:54","modified_gmt":"2018-01-13T15:11:54","slug":"meteorologia-pronostica-ocurrencia-de-aguaceros-durante-el-fin-de-semana-mantienen-alertas-por-inundaciones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/meteorologia-pronostica-ocurrencia-de-aguaceros-durante-el-fin-de-semana-mantienen-alertas-por-inundaciones\/","title":{"rendered":"METEOROLOG\u00cdA PRONOSTICA OCURRENCIA DE AGUACEROS DURANTE EL FIN DE SEMANA; MANTIENEN ALERTAS POR INUNDACIONES"},"content":{"rendered":"<p style=\"font-weight: 400;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-43468\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4-100x75.jpg 100w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>Las lluvias continuar\u00e1 durante el fin de semana en la Capital, El Gran Santo Domingo y otras provincias, pronostica la Oficina Nacional de Meteorolog\u00eda (Onamet) que mantiene alerta por inundaciones repentinas y posibles deslizamientos de tierra.<!--more--><\/p>\n<p style=\"font-weight: 400;\"><em>Durante las horas matutinas predominar\u00e1 un ambiente meteorol\u00f3gico relativamente estable, \u00a0con ausencia de precipitaciones sobre las regiones noroeste, \u00a0noreste y este, sin embargo, en el suroeste predominaran los nublados, debido a la incidencia que mantiene una vaguada en la troposfera alta al este de Jamaica y su incidencia se manifiesta al sur del pa\u00eds en agua del mar Caribe. En horas de la tarde se esperan algunos episodios lluviosos sobre la porci\u00f3n oriental del Valle del Cibao y la zona norte, debido al arrastre de humedad que mantiene el viento del este\/noreste. Esta actividad lluviosa disminuir\u00e1 despu\u00e9s de entrada la noche.<\/em><\/p>\n<p style=\"font-weight: 400;\">Para este domingo, seguir\u00e1n reduci\u00e9ndose las lluvias, debido a la incidencia que mantendr\u00e1n sobre la\u00a0atm\u00f3sfera\u00a0media y alta un flujo anticicl\u00f3nico, el mismo traer\u00e1 estabilidad al Caribe Central y por otro lado, un viento con menor contenido de humedad seguir\u00e1 llegando hasta nuestro territorio, de manera que estas condiciones reducir\u00e1n considerable las precipitaciones y aquellas que se presenten estar\u00e1n m\u00e1s concentradas hacia el suroeste, cordillera central y centro del pa\u00eds.<\/p>\n<p style=\"font-weight: 400;\"><em>Este lunes habr\u00e1 una reducci\u00f3n de las lluvias a nivel nacional, predominar\u00e1 el ant-icicl\u00f3n y la humedad no ser\u00e1 suficiente para que se generen precipitaciones significativas. Algunos nublados hacia el centro de pa\u00eds y sectores del litoral costero del Caribe.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em>La\u00a0<b>ONAMET<\/b>,\u00a0<b>DESCONTINUA<\/b>\u00a0el\u00a0<b>ALERTA<\/b>\u00a0por inundaciones repentinas, as\u00ed como deslizamientos de tierra, desbordamientos de r\u00edos, arroyos y ca\u00f1adas para las provincias de Mar\u00eda Trinidad S\u00e1nchez, S\u00e1nchez Ram\u00edrez, Monte Plata, Hato Mayor, Peravia, San Crist\u00f3bal, La Altagracia y El Gran Santo Domingo por inundaciones urbanas.<\/em><em>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/em><\/p>\n<p style=\"font-weight: 400;\"><em><b>Distrito Nacional:<\/b><\/em><em>\u00a0Medio nublado a nublado con chubascos dispersos.<\/em><em><b>Santo Domingo Este<\/b><\/em><em>:\u00a0\u00a0 \u00a0\u00a0Ligeros incrementos nubosos con aguaceros dispersos y aisladas tronadas.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em><b>Santo Domingo Norte<\/b><\/em><em>:Medio nublado a nublado con aguaceros dispersos posibles tronadas.<\/em><em><b>Santo domingo Oeste:<\/b><\/em><em>\u00a0Medio nublado en ocasiones con chubascos dispersos.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em><b>El gran Santo Domingo<\/b><\/em><em>. Temperatura m\u00e1xima entre 28\u00baC y 30\u00baC y m\u00ednima entre\u00a0 20\u00baC y 22\u00baC.<\/em><\/p>\n<p style=\"font-weight: 400;\"><em><b>Resumen: Se Descontin\u00faan las alertas meteorol\u00f3gico. Lluvias se reducen en el fin de semana. Temperaturas agradables en la madrugada<\/b><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las lluvias continuar\u00e1 durante el fin de semana en la Capital, El Gran Santo Domingo y otras provincias, pronostica la Oficina Nacional de Meteorolog\u00eda (Onamet) que mantiene alerta por inundaciones repentinas y posibles deslizamientos de tierra.<\/p>\n","protected":false},"author":12,"featured_media":43468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-71402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71402"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71402\/revisions"}],"predecessor-version":[{"id":71403,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71402\/revisions\/71403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43468"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}