{"id":71414,"date":"2018-01-13T17:36:09","date_gmt":"2018-01-13T21:36:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71414"},"modified":"2018-01-13T11:57:20","modified_gmt":"2018-01-13T15:57:20","slug":"he-man-masters-of-the-universe-comenzara-a-rodarse-pronto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/he-man-masters-of-the-universe-comenzara-a-rodarse-pronto\/","title":{"rendered":"\u2018He-man\u2019 (Masters of The Universe) comenzar\u00e1 a rodarse pronto"},"content":{"rendered":"<p><strong>\u00abHe-man\u00bb<\/strong>\u00a0pertenece a las figuras de acci\u00f3n de los\u00a0<strong>Masters of The Universe<\/strong>\u00a0de Mattel. Tambi\u00e9n hay varias series de animaci\u00f3n, c\u00f3mics y una pel\u00edcula que se estreno en\u00a0<strong>1987<\/strong>. Ahora quieren devolver los personajes a la gran pantalla.<!--more--><\/p>\n<div class=\"code-block code-block-2\"><ins class=\"adsbygoogle adslot_S1\" data-ad-client=\"ca-pub-5512390705137507\" data-ad-slot=\"2593624863\/1349165183\" data-adsbygoogle-status=\"done\"><\/ins><ins id=\"aswift_1_expand\"><\/ins><ins id=\"aswift_1_anchor\"><\/ins> <a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/he-man.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-71417\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/he-man.jpg\" alt=\"\" width=\"570\" height=\"297\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/he-man.jpg 570w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/he-man-300x156.jpg 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/a><\/div>\n<div class=\"seedtag-gohan seedtag-adunit\"><\/div>\n<p>Ya que piensan que tiene mucho tir\u00f3n. Como ya ha pasado con\u00a0<strong>Transformers o G.I. Joe.<\/strong><\/p>\n<p><strong>David S. Goyer<\/strong>\u00a0(\u2018Blade: Trinity\u2019, \u2018La semilla del mal\u2019) ha sido contratado para co-escribir y dirigir la pel\u00edcula. De acuerdo con\u00a0Omega Underground,\u00a0<strong>empezar\u00e1 a rodar en abril.<\/strong>\u00a0Quiz\u00e1s como director no levante pasiones, pero ha escrito guiones como los de\u00a0<strong>\u2018la Trilog\u00eda del Caballero Oscuro\u2019<\/strong>,\u00a0\u2018El hombre de Acero\u2019\u00a0o la serie\u00a0<strong>\u2018Da Vinci\u2019s Demons\u2019<\/strong>. Adem\u00e1s el gui\u00f3n tambi\u00e9n lo firma\u00a0<strong>Lindsey Beer<\/strong>. Esta joven no tiene ninguna pel\u00edcula estrenada en su filmografia, pero se encargar\u00e1 de las historias de\u00a0<strong>\u2018Godzilla vs. Kong\u2019<\/strong>\u00a0(2020) y\u00a0<strong>\u2018Dungeons &amp; Dragons\u2019<\/strong>\u00a0(2021).\u00a0Adem\u00e1s hace poco fue noticia por que dijo que hacia falta un Darth Vader femenino en Star Wars.<\/p>\n<h3>La pel\u00edcula anterior de He-Man era de serie B.<\/h3>\n<p>Quiz\u00e1s a muchos ni le suene, pero en los 80 estrenaron<strong>\u00a0\u2018Masters del universo\u2019<\/strong>, un film con\u00a0Dolph Lundgren\u00a0(Rocky IV). Como curiosidad pod\u00edamos ver tambi\u00e9n a una jovenc\u00edsima\u00a0<strong>Courteney Cox<\/strong>\u00a0que a\u00f1os despu\u00e9s conseguir\u00eda el papel de M\u00f3nica en la m\u00edtica\u00a0<strong>\u2018Friends\u2019<\/strong>. La pel\u00edcula solo obtuvo 17 millones de recaudaci\u00f3n. Aunque seguramente gan\u00f3 m\u00e1s gracias a su versi\u00f3n de alquiler.<\/p>\n<p>En la historia eran los protagonistas quienes viajaban a la Tierra, all\u00ed deb\u00edan frenar al malvado Skeletor (Frank Langella).<\/p>\n<p>Ahora todo apunta a que en vez de llegar a nuestro planeta, la acci\u00f3n se desarrollar\u00e1 en\u00a0<strong>Eternia<\/strong>. Donde una vez m\u00e1s las fuerzas del bien y del mal chocar\u00e1n en una \u00e9pica batalla para definir el futuro del Universo.<\/p>\n<p><strong>La imagen que les dejamos a continuaci\u00f3n se filtr\u00f3 en 2015:<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_32910 aligncenter wp-image-50300 size-full\" title=\"Battle Cat Masters of the Universe - He-Man\" src=\"https:\/\/www.cinemascomics.com\/wp-content\/uploads\/2015\/03\/Battle-Cat-1.jpg\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" srcset=\"https:\/\/www.cinemascomics.com\/wp-content\/uploads\/2015\/03\/Battle-Cat-1.jpg 503w, https:\/\/www.cinemascomics.com\/wp-content\/uploads\/2015\/03\/Battle-Cat-1-150x150.jpg 150w, https:\/\/www.cinemascomics.com\/wp-content\/uploads\/2015\/03\/Battle-Cat-1-80x80.jpg 80w\" alt=\"Battle Cat Masters of the Universe - He-Man\" width=\"503\" height=\"503\" \/><\/p>\n<div class=\"seedtag-gohan seedtag-adunit\"><\/div>\n<p><strong>La pel\u00edcula de He-Man se estrenar\u00e1 en navidades de 2019.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abHe-man\u00bb\u00a0pertenece a las figuras de acci\u00f3n de los\u00a0Masters of The Universe\u00a0de Mattel. Tambi\u00e9n hay varias series de animaci\u00f3n, c\u00f3mics y una pel\u00edcula que se estreno en\u00a01987. Ahora quieren devolver los personajes a la gran pantalla.<\/p>\n","protected":false},"author":12,"featured_media":71417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387],"tags":[],"class_list":["post-71414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71414"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71414\/revisions"}],"predecessor-version":[{"id":71420,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71414\/revisions\/71420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71417"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}