{"id":71535,"date":"2018-01-22T12:00:09","date_gmt":"2018-01-22T16:00:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71535"},"modified":"2018-01-22T09:57:11","modified_gmt":"2018-01-22T13:57:11","slug":"samsung-niega-las-sospechas-sobre-la-obsolescencia-programada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/samsung-niega-las-sospechas-sobre-la-obsolescencia-programada\/","title":{"rendered":"Samsung niega las sospechas sobre la obsolescencia programada"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-71536\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9.jpg\" alt=\"\" width=\"681\" height=\"392\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9.jpg 1400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9-300x173.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9-768x442.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/01\/dims-9-1024x590.jpg 1024w\" sizes=\"auto, (max-width: 681px) 100vw, 681px\" \/><\/a>Despu\u00e9s del episodio de la bater\u00eda del\u00a0iPhone, es normal que los consumidores tengan ciertas sospechas con su tel\u00e9fono. \u00bfHacen otras marcas lo mismo? \u00bfHay alg\u00fan tipo de obsolescencia programada que afecta al consumidor? En Italia\u00a0ya han avisado\u00a0que piensan comenzar una investigaci\u00f3n para ver si\u00a0Apple\u00a0Y\u00a0Samsung\u00a0hacen uso de este tipo de pr\u00e1cticas, pero los coreanos no est\u00e1n dispuestos a que se les ponga en duda en absoluto.<!--more--><\/p>\n<p>Con el\u00a0Galaxy S9\u00a0a la vuelta de la esquina, el fabricante surcoreano no quiere que su pr\u00f3ximo lanzamiento quede manchado por falsas pol\u00e9micas o investigaciones que no llegan a nada, as\u00ed que ha salido al paso comunicando inmediatamente que niegan cualquier tipo de pr\u00e1ctica relacionada con la obsolescencia programada. En palabras de la compa\u00f1\u00eda, \u00abSamsung no proporciona actualizaciones de software para reducir el rendimiento del producto durante el ciclo de vida del dispositivo. Cooperaremos plenamente con la Autoridad Italiana de Investigaci\u00f3n de Mercado y Competencia en Italia para aclarar los hechos\u00bb.<\/p>\n<p>El mensaje est\u00e1 ah\u00ed, pero no podemos descartar un posible giro de los acontecimientos. Y es que todo depender\u00e1 del enfoque que se le d\u00e9 a la situaci\u00f3n, ya que, en el caso de Apple, las intenciones de los de Cupertino eran las de cuidar y proteger la vida de la bater\u00eda, aunque ello conllevara la reducci\u00f3n del rendimiento del terminal. \u00bfHab\u00eda buena fe en la acci\u00f3n? Seg\u00fan como se mire.<\/p>\n<p>Est\u00e1 claro que el caso de Apple marcar\u00e1 las directrices en las futuras acusaciones y sentencias, as\u00ed que tendremos que seguir muy atentos a c\u00f3mo evoluciona el caso en Italia para saber c\u00f3mo actuar\u00e1n con el resto de marcas. En Samsung lo tienen claro, ellos no ralentizan con actualizaciones de software.<\/p>\n<p><a href=\"http:\/\/es.engadget.com\/2018\/01\/22\/samsung-niega-sospechas-obsolescencia-programada\/?utm_source=bloglovin.com&amp;utm_medium=feed&amp;utm_campaign=Feed%3A+EngadgetSpanish+%28Engadget+Spanish%29\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s del episodio de la bater\u00eda del\u00a0iPhone, es normal que los consumidores tengan ciertas sospechas con su tel\u00e9fono. \u00bfHacen otras marcas lo mismo? \u00bfHay alg\u00fan tipo de obsolescencia programada que afecta al consumidor? En Italia\u00a0ya han avisado\u00a0que piensan comenzar una investigaci\u00f3n para ver si\u00a0Apple\u00a0Y\u00a0Samsung\u00a0hacen uso de este tipo de pr\u00e1cticas, pero los coreanos no est\u00e1n dispuestos a que se les ponga en duda en absoluto.<\/p>\n","protected":false},"author":12,"featured_media":71536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-71535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71535"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71535\/revisions"}],"predecessor-version":[{"id":71537,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71535\/revisions\/71537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71536"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}