{"id":71684,"date":"2018-02-07T10:07:38","date_gmt":"2018-02-07T14:07:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71684"},"modified":"2018-02-07T10:07:38","modified_gmt":"2018-02-07T14:07:38","slug":"semifinales-hoy-en-serie-del-caribe","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/semifinales-hoy-en-serie-del-caribe\/","title":{"rendered":"Semifinales hoy en Serie del Caribe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-71685 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/semifinales-hoy-en-serie-del-caribe.jpeg\" alt=\"\" width=\"251\" height=\"167\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/semifinales-hoy-en-serie-del-caribe.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/semifinales-hoy-en-serie-del-caribe-300x200.jpeg 300w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/>Con los anfitriones Tomateros de Culiac\u00e1n fuera, los equipos \u00c1guilas Cibae\u00f1as, Alazanes de Granma, Caribes de Anzo\u00e1tegui y Criollos de Caguas intentar\u00e1n hoy sobrevivir a la serie semifinal para tener ma\u00f1ana en la noche la oportunidad de levantar el trofeo de campe\u00f3n de la Serie del Caribe 2018 en el moderno parque Charros de Jalisco.<!--more--><\/p>\n<p>Hasta anoche, al cierre de Listin, los enfrentamientos de la semifinal \u201cA\u201d y \u201cB\u201d depend\u00edan\u00a0 del resultado del encuentro de esta madrugada entre los representativos de Rep\u00fablica Dominicana y M\u00e9xico.<\/p>\n<p>Una victoria del equipo que dirige Lino Rivera ante M\u00e9xico enviar\u00eda a las \u00c1guilas al primer lugar, pero si son\u00a0 los aztecas\u00a0 que ganan mandar\u00eda a Cuba hasta la cima de la clasificaci\u00f3n<\/p>\n<p>Yunesky Maya uno de los tres cubanos que conforman la rotaci\u00f3n de cinco del equipo aguilucho,\u00a0\u00a0 tiene esta noche la misi\u00f3n de\u00a0 ayudar al colectivo quisqueyano a empu\u00f1ar el boleto que conduce a la final.<\/p>\n<p>Al igual que el pasado a\u00f1o en Culiac\u00e1n, los Alazanes clasificaron con registro de 3-1 y pretenden sumar otro trofeo de campe\u00f3n al conquistado por Pinar del R\u00edo en el 2015, un a\u00f1o despu\u00e9s de haber regresado a la denominada \u201cPeque\u00f1a Serie del Caribe\u201d. Los Criollos, contra viento y marea, resultaron campeones de la recortada Liga Roberto Clemente y concluyeron aqu\u00ed con marca de 2-2, primer paso para en la defensa del t\u00edtulo que conquistaron en el 2017 en Culiac\u00e1n, su primero desde el a\u00f1o 2000.<\/p>\n<p>Los Caribes, tambi\u00e9n con foja de 2-2, tienen el objetivo de llevar a Venezuela el t\u00edtulo de una serie que debi\u00f3 celebrarse este a\u00f1o en Barquisimeto, pero que lo dejaron para el 2019, cuando se conf\u00eda que la crisis pol\u00edtica que le afecta permita celebrar la misma.<\/p>\n<p>En el 2016, el experimento fue fallido, pero un a\u00f1o despu\u00e9s Edwin Espinal no quiso perder la segunda oportunidad, elev\u00f3 su cuota de trabajo y los resultados fueron m\u00e1s que satisfactorios.<\/p>\n<p>\u201cPienso que llegu\u00e9 al lugar donde quer\u00eda estar, en base al trabajo fuerte lo logr\u00e9\u201d, expres\u00f3 el fornido inicialista, cuyo desempe\u00f1o de este a\u00f1o le hizo ganar esa posici\u00f3n con las \u00c1guilas.<\/p>\n<p>Hace un a\u00f1o y por recomendaci\u00f3n de un instructor de Detroit, las \u00c1guilas lo colocaron en la inicial, pero un pobre promedio de .154 (39-6) le hicieron al club buscar otras alternativas, Jos\u00e9 Julio Ruiz y Kennys Vargas terminaron adue\u00f1\u00e1ndose del puesto.<\/p>\n<p>Empero, un segundo chance fue suficiente para que Espinal mejorara notablemente y colocara las estad\u00edsticas que el conjunto requer\u00eda de \u00e9l para otorgarle la posici\u00f3n al mastodonte de 6\u00a52 y 250 libras.<\/p>\n<p>En la concluida campa\u00f1a los n\u00fameros de Espinal fueron muy diferentes, un robusto .287 (143-41) con dos jonrones y 24 remolcadas fueron m\u00e1s que suficientes para quedarse con la posici\u00f3n, la cual espera sea definitiva.\u00a0 \u201cRealiz\u00f3 un buen trabajo, el que nosotros esper\u00e1bamos y pienso que hemos conseguido ya nuestro inicialista\u201d, se\u00f1al\u00f3 Manny Acta, gerente general de las \u00c1guilas.<\/p>\n<p>Espinal, un nativo de Mao y quien creci\u00f3 idolatrando a las \u00c1guilas entiende que\u00a0 con su brillante desempe\u00f1o ya le lleg\u00f3 la oportunidad que siempre anhelaba. Y en su caso, lo m\u00e1s importante en su primera campa\u00f1a completa ayud\u00f3 al conjunto a conseguir la corona.<\/p>\n<p>\u201cTambi\u00e9n estoy orgulloso y este es un gran premio para m\u00ed el poder ser parte de esta gran historia con las \u00c1guilas\u201d, manifest\u00f3 el jugador, quien pr\u00f3ximamente partir\u00e1 a los entrenamientos con los Tigres de Detroit.<\/p>\n<p>\u201cEstoy preparado para ser el inicialista de las \u00c1guilas por un largo tiempo\u201d, se\u00f1ala el inicialista que se hizo como jugador actuando en la Academia de Luis Polonia.<\/p>\n<p>\u201cEs un gran orgullo poder brindarle esa corona a esa gran fanaticada de las \u00c1guilas y batallaremos en grande en busca de conseguir el cetro en la Serie del Caribe y as\u00ed tener una doble celebraci\u00f3n\u201d, puntualiz\u00f3.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con los anfitriones Tomateros de Culiac\u00e1n fuera, los equipos \u00c1guilas Cibae\u00f1as, Alazanes de Granma, Caribes de Anzo\u00e1tegui y Criollos de Caguas intentar\u00e1n hoy sobrevivir a la serie semifinal para tener ma\u00f1ana en la noche la oportunidad de levantar el trofeo de campe\u00f3n de la Serie del Caribe 2018 en el moderno parque Charros de Jalisco.<\/p>\n","protected":false},"author":9,"featured_media":71685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-71684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71684"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71684\/revisions"}],"predecessor-version":[{"id":71686,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71684\/revisions\/71686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71685"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}