{"id":71714,"date":"2018-02-09T15:00:06","date_gmt":"2018-02-09T19:00:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71714"},"modified":"2018-02-09T15:00:06","modified_gmt":"2018-02-09T19:00:06","slug":"haitianos-roban-fusil-m-16-a-un-sargento-en-pedernales-esto-provoca-baja-asistencia-en-el-mercado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/haitianos-roban-fusil-m-16-a-un-sargento-en-pedernales-esto-provoca-baja-asistencia-en-el-mercado\/","title":{"rendered":"Haitianos roban fusil M-16 a un sargento en Pedernales; esto provoca baja asistencia en el mercado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-71715 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/haitianos-roban-fusil-m-16-a-un-sargento-en-pedernales-esto-provoca-baja-asistencia-en-el-mercado.jpeg\" alt=\"\" width=\"335\" height=\"251\" \/>Dos haitianos golpearon a palos y despojaron de un fusil M-16 a un sargento mayor del Ej\u00e9rcito de Rep\u00fablica Dominicana, en cuartel de chequeo Pasoceno, en este municipio fronterizo.<!--more--><\/p>\n<p>El sargento quien fue arrestado esta ma\u00f1ana \u00a0es Francisco Arturo P\u00e9rez Jos\u00e9, adscrito a la compa\u00f1\u00eda del Ej\u00e9rcito de Pedernales, su uniforme militar estaba ensangrentado y seg\u00fan dijo fue de los golpes que recibi\u00f3.<\/p>\n<p>Los superiores iniciaron las investigaciones del despojo del fusil. Esta es la segunda vez que oficiales son despojados de fusiles en este puesto de chequeo, ya que hace m\u00e1s de dos a\u00f1os fueron sustra\u00eddas dos armas de alto calibre.<\/p>\n<p><strong>Mercado binacional<\/strong><\/p>\n<p>Esta ma\u00f1ana productoo del despojo del fusil, en el mercado fronterizo disminuy\u00f3 la presencia de comerciantes haitianos, por temor a las requisas que se producen cuando ocurren estos hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos haitianos golpearon a palos y despojaron de un fusil M-16 a un sargento mayor del Ej\u00e9rcito de Rep\u00fablica Dominicana, en cuartel de chequeo Pasoceno, en este municipio fronterizo.<\/p>\n","protected":false},"author":9,"featured_media":71715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-71714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71714"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71714\/revisions"}],"predecessor-version":[{"id":71716,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71714\/revisions\/71716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71715"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}