{"id":71797,"date":"2018-02-16T11:56:10","date_gmt":"2018-02-16T15:56:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71797"},"modified":"2018-02-16T11:56:10","modified_gmt":"2018-02-16T15:56:10","slug":"escogido-anuncia-luis-rojas-se-mantiene-como-su-dirigente","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/escogido-anuncia-luis-rojas-se-mantiene-como-su-dirigente\/","title":{"rendered":"Escogido anuncia Luis Rojas se mantiene como su dirigente"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-71798 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/VIC9895.jpg\" alt=\"\" width=\"288\" height=\"192\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/VIC9895.jpg 2250w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/VIC9895-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/VIC9895-768x513.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/VIC9895-1024x684.jpg 1024w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/>SANTO DOMINGO.-<\/strong>\u00a0La Directiva del Escogido Baseball Club present\u00f3 oficialmente a Jos\u00e9 G\u00f3mez Fr\u00edas como Gerente General, y de inmediato, el nuevo ejecutivo realiz\u00f3 su primer anuncio importante: \u201cLuis Rojas se mantiene como dirigente\u201d.<!--more--><\/p>\n<p>G\u00f3mez Fr\u00edas anunci\u00f3 la continuidad de Rojas durante un encuentro con la prensa celebrado en el camerino de los Leones del Escogido, en el Estadio Quisqueya Juan Marichal. Estuvo acompa\u00f1ado de Jos\u00e9 Miguel Bonetti, Vicepresidente Ejecutivo, Eduardo Najri, Tesorero y Luis Manuel Bonetti, ex presidente y miembro de la Directiva.<\/p>\n<p>Pero Rojas no es el \u00fanico miembro del cuerpo t\u00e9cnico que se mantendr\u00e1 en la cueva roja para el torneo oto\u00f1o-invernal 2018-19, ya que el asistente de banca Jos\u00e9 Leger tambi\u00e9n fue confirmado.<\/p>\n<p>\u201cLa decisi\u00f3n de retener a Rojas nos permite darle continuidad al proyecto que se ha venido llevando bajo su direcci\u00f3n. Tanto \u00e9l como Leger son dos activos de esta organizaci\u00f3n que cuentan con el respeto de los jugadores, la voluntad de trabajo y apertura de nuevas ideas que este equipo representa\u201d, indic\u00f3 G\u00f3mez Fr\u00edas.<\/p>\n<p>\u201cConjuntamente con toda la directiva del club, siento que son las personas correctas para acompa\u00f1arme en el reto de continuar el legado de disciplina y respeto al juego que Mois\u00e9s Alou dej\u00f3 como ejemplo a esta nueva gesti\u00f3n\u201d, sigui\u00f3 diciendo.<\/p>\n<p>Desde Port Saint Lucie, Florida, hogar de entrenamiento primaveral de los Mets de Nueva York, Rojas agradeci\u00f3 la oportunidad de continuar al frente de los melenudos, a quienes condujo a la corona nacional en el campeonato 2015-16.<\/p>\n<p>\u201cAgradecido con la directiva y con G\u00f3mez por recibir una nueva oportunidad. Tenemos como meta seguir mejorando el conjunto y s\u00e9 que podemos hacerlo, no solo para superar la primera etapa, sino tambi\u00e9n para levantar nuestra corona n\u00famero 17 en la temporada 2018-19\u201d, indic\u00f3 Rojas a trav\u00e9s de un video que fue presentado en la actividad.<\/p>\n<p><strong>Palabras de Jos\u00e9 Miguel Bonetti<\/strong><\/p>\n<p>\u201cDesde que lo conoc\u00ed, vi en \u00e9l su potencial y cualidades que lo distinguen de los dem\u00e1s. Para m\u00ed, esas cualidades son: dinamismo, curiosidad y trabajador incansable, pero lo m\u00e1s importante y que le har\u00e1 un excelente gerente es que tiene sus propias ideas\u201d, dijo el vicepresidente ejecutivo al introducir oficialmente a G\u00f3mez Fr\u00edas como gerente.<\/p>\n<p><strong>Departamento de Operaciones<\/strong><\/p>\n<p>G\u00f3mez Fr\u00edas aprovech\u00f3 la ocasi\u00f3n para anunciar la reestructuraci\u00f3n del Departamento de Operaciones de B\u00e9isbol del Escogido.<\/p>\n<p>Jaylon Pimentel, adem\u00e1s de ser asistente del Gerente General, fue promovido al puesto de Director de Operaciones, quedando a su cargo la parte del d\u00eda a d\u00eda del equipo. Estar\u00e1 acompa\u00f1ado de Bolivar Pelletier, quien ingresa a los Leones como Asistente de Operaciones, acumula experiencia en funciones similares con los Nacionales de Washington en el pa\u00eds.<\/p>\n<p>Asimismo, Fausto Severino ingresa como asistente del Gerente General y Coordinador de Scouteo. Severino, actualmente Supervisor Internacional de Scouts de los Nacionales de Washington, coordinar\u00e1 a los escuchas del Escogido y las evaluaciones de jugadores.<\/p>\n<p>Luis Javier, adem\u00e1s de ser asistente del Gerente General, laborar\u00e1 en la posici\u00f3n de Director de Anal\u00edtica y tendr\u00e1 a su cargo el manejo y presentaci\u00f3n de datos y estad\u00edsticas para la toma de decisiones.<\/p>\n<p>El equipo de scouts est\u00e1 compuesto por Anthony Contreras (M\u00e1nager de Clase A de los Padres), Buck Britton (Dirigente de Clase A de los Orioles), Eduardo S\u00e1nchez (Escucha de los Cerveceros) y Braly Guzm\u00e1n (Scout de los Cardenales).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-\u00a0La Directiva del Escogido Baseball Club present\u00f3 oficialmente a Jos\u00e9 G\u00f3mez Fr\u00edas como Gerente General, y de inmediato, el nuevo ejecutivo realiz\u00f3 su primer anuncio importante: \u201cLuis Rojas se mantiene como dirigente\u201d.<\/p>\n","protected":false},"author":9,"featured_media":71798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-71797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71797"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71797\/revisions"}],"predecessor-version":[{"id":71799,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71797\/revisions\/71799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71798"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}