{"id":71930,"date":"2018-02-28T19:44:58","date_gmt":"2018-02-28T23:44:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71930"},"modified":"2018-02-28T19:44:58","modified_gmt":"2018-02-28T23:44:58","slug":"r-dominicana-toma-acciones-para-lograr-exportar-carne-de-res-a-eeuu","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/r-dominicana-toma-acciones-para-lograr-exportar-carne-de-res-a-eeuu\/","title":{"rendered":"R.Dominicana toma acciones para lograr exportar carne de res a EEUU"},"content":{"rendered":"<p class=\"DETALLE_N_titulo \"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-71931 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/res.jpg\" alt=\"\" width=\"329\" height=\"219\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/res.jpg 580w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/res-300x200.jpg 300w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/>Santo Domingo, 28 feb.- Los Ministerios de Salud y de Agricultura de la Rep\u00fablica Dominicana y varias instituciones locales m\u00e1s firmaron hoy un acuerdo para apoyar los esfuerzos del pa\u00eds caribe\u00f1o para lograr la habilitaci\u00f3n que permita la exportaci\u00f3n de carne de res a Estados Unidos.<!--more--><\/p>\n<div id=\"texto\" class=\"texto_txt\">\n<div class=\"DETALLE_N_texto \">\n<p><span id=\"ctl14_lblMostra\">El acuerdo con los establecimientos autorizados (mataderos) tambi\u00e9n fue rubricado por la Junta Agropempresarial Dominicana (JAD) y la Asociaci\u00f3n Dominicana de Hacendados y Agricultores (ADHA), seg\u00fan un comunicado del Ministerio de Salud P\u00fablica.<\/span><\/p>\n<p>El objetivo es establecer un mecanismo a trav\u00e9s del cual se realice el pago de horas extras al personal oficial asignado a labores de inspecci\u00f3n en mataderos con vocaci\u00f3n de exportaci\u00f3n, un requisito indispensable para lograr la equivalencia con el Servicio de Inspecci\u00f3n de Inocuidad Alimentaria (FSIS) del Departamento de Agricultura de Estados Unidos (USDA).<\/p>\n<p>La ministra de Salud, Altagracia Guzm\u00e1n Marcelino, destac\u00f3 \u201cla ardua labor\u201d que la cartera que dirige realiza a trav\u00e9s de la Unidad de Carnes de la Direcci\u00f3n General de Medicamentos, Alimentos y Productos Sanitarios (Digemaps) con el fin de lograr la equivalencia con el FSIS y poder exportar carne de res cruda a EE.UU.<\/p>\n<p>Dentro de los esfuerzos, la funcionaria destac\u00f3 la contrataci\u00f3n de 7 m\u00e9dicos veterinarios y 12 asistentes de inspecci\u00f3n para reforzar las labores en establecimientos autorizados.<\/p>\n<p>Asimismo, la elaboraci\u00f3n y puesta en pr\u00e1ctica de 27 procedimientos oficiales y m\u00e1s de 40 formularios, con el fin de hacer m\u00e1s eficientes las labores oficiales en mataderos y auditor\u00edas peri\u00f3dicas al laboratorio de referencia oficial (Lavecen) con el fin de determinar oportunidades de mejorar respecto a la equivalencia con el FSIS.<\/p>\n<p>Guzm\u00e1n Marcelino tambi\u00e9n destac\u00f3 la contrataci\u00f3n de expertos en implementaci\u00f3n del sistema Haccp (an\u00e1lisis de riesgo en puntos cr\u00edticos de control durante el procesamiento de alimentos) en mataderos ya que, es un requisito indispensable para lograr la equivalencia.<\/p>\n<p>Por \u00faltimo, se\u00f1al\u00f3 que estos esfuerzos han recibido un importante apoyo desde la Presidencia de la Rep\u00fablica con la creaci\u00f3n de una comisi\u00f3n p\u00fablico-privada compuesta por varias instituciones y coordinada por el ministro Administrativo de la Presidencia, Jos\u00e9 Ram\u00f3n Peralta, desde la cual se impulsan acciones para el control de las enfermedades zoon\u00f3ticas.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, 28 feb.- Los Ministerios de Salud y de Agricultura de la Rep\u00fablica Dominicana y varias instituciones locales m\u00e1s firmaron hoy un acuerdo para apoyar los esfuerzos del pa\u00eds caribe\u00f1o para lograr la habilitaci\u00f3n que permita la exportaci\u00f3n de carne de res a Estados Unidos.<\/p>\n","protected":false},"author":9,"featured_media":71931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-71930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71930"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71930\/revisions"}],"predecessor-version":[{"id":71932,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71930\/revisions\/71932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71931"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}