{"id":71936,"date":"2018-02-28T19:51:42","date_gmt":"2018-02-28T23:51:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71936"},"modified":"2018-02-28T19:51:42","modified_gmt":"2018-02-28T23:51:42","slug":"la-importancia-del-pescado-en-la-dieta","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-importancia-del-pescado-en-la-dieta\/","title":{"rendered":"La importancia del pescado en la dieta"},"content":{"rendered":"<div class=\"text\">\n<p>Si te preocupa tu cuerpo<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71937 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706.jpg\" alt=\"\" width=\"426\" height=\"255\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706.jpg 1055w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706-300x179.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706-768x459.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706-1024x611.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/02\/image_content_9589510_20180223164706-500x300.jpg 500w\" sizes=\"auto, (max-width: 426px) 100vw, 426px\" \/>\u00a0y quieres alimentarte bien, apuesta por el pescado. Para comer o cenar tres o cuatro veces por semana, hay mil buenas razones para preferirlo y aqu\u00ed te damos unas cuantas.<\/p>\n<div class=\"text\"><!--more--><\/div>\n<p>&nbsp;<\/p>\n<p>A pesar de que el pescado es un alimento de muchas propiedades con grandes beneficios para el organismo, en nuestro pa\u00eds tiende a ser reemplazado por las carnes blancas como el pollo. Para<\/p>\n<div class=\"text\"><\/div>\n<p>incentivar su consumo, Supermercados Nacional ofreci\u00f3 una charla \u201csobre los beneficios y t\u00e9cnicas modernas de preparaci\u00f3n\u201d, donde los atributos del pescado y sus formas de cocci\u00f3n dan inicio a una temporada repleta de productos del mar.<\/p>\n<p>Lo sabemos. El pescado es un alimento muy completo. Aporta prote\u00ednas de alto valor biol\u00f3gico y \u00e1cidos grasos esenciales (sobre todo en el caso del pescado azul). De ah\u00ed que m\u00e9dicos y nutriconistas recomiendan su consumo, al menos, dos o tres veces a la semana. Si eres de las que le cuesta incorporarlo a su dieta, te damos unas cuantas razones por las que comer pescado regularmente es beneficioso para tu salud.<\/p>\n<p>-Es un alimento rico en nutrientes.<\/p>\n<p>-Buena fuente de vitamina D.<\/p>\n<p>-Ayuda al sano crecimiento.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>-Disminuye al m\u00ednimo los riesgos de padecer una enfermedad autoinmune.<\/p>\n<p>-Previene la depresi\u00f3n, los problemas cardiovasculares y el asma en infantes.<\/p>\n<p>-Protege la visi\u00f3n en la vida adulta.<\/p>\n<p>-Puede ayudar a mejorar la calidad del sue\u00f1o<\/p>\n<p>-Aporta a la salud cerebral.<\/p>\n<p><b>\u00bfBlanco o azul?<\/b><\/p>\n<p>Claro que no todos los pescados son bajos en grasa. Recuerda que existen dos grupos de pescados: azul y blanco. La diferencia radica fundamentalmente en su contenido en grasa. El blanco tiene menos grasa que el azul pero este \u00faltimo tiene un valor nutricional m\u00e1s elevado ya que es rico en \u00e1cidos grasos poliinsaturados como el Omega-3 (beneficioso para la salud cardiovascular por su control sobre los niveles de triglic\u00e9ridos y colesterol).<\/p>\n<p>Los pescados azules, como la sardina y el salm\u00f3n, distintivos por su cola en forma de v o flecha cuentan entre un 8-10% de grasa, aunque aportan prote\u00ednas, minerales, hierro y ayudan a controlar el colesterol.<\/p>\n<p>El pescado blanco, por otro lado, como el bacalao, merluz o lenguado, son recomendados en dietas bajas en calor\u00edas. Puedes reconocerlos por su cola recta en forma de abanico. Tienen entre un 1-3% de grasa, aportan vitaminas del grupo B, prote\u00ednas y ayudan a controlar las enfermedades de tiroides.<\/p>\n<p>\u00bfC\u00f3mo elegirlo? A la hora de comprar el pescado se recomienda evaluar el corte. Si es un filete, retal, tajada, lomo o cogote. Siendo la parte del filete y el lomo las mejores. Algunos peces tienen un sabor estridente al paladar, por lo que se recomienda matizarlo con un poco de aceite de oliva.<\/p>\n<div class=\"foto_central cutlineShow\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si te preocupa tu cuerpo\u00a0y quieres alimentarte bien, apuesta por el pescado. Para comer o cenar tres o cuatro veces por semana, hay mil buenas razones para preferirlo y aqu\u00ed te damos unas cuantas.<\/p>\n","protected":false},"author":9,"featured_media":71937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-71936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71936"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71936\/revisions"}],"predecessor-version":[{"id":71938,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71936\/revisions\/71938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71937"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}