{"id":71961,"date":"2018-03-02T12:29:24","date_gmt":"2018-03-02T16:29:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=71961"},"modified":"2018-03-02T12:29:24","modified_gmt":"2018-03-02T16:29:24","slug":"cambios-en-educacion-provincial-adamilca-nueva-directora-regional-por-sabina","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cambios-en-educacion-provincial-adamilca-nueva-directora-regional-por-sabina\/","title":{"rendered":"Cambios en educaci\u00f3n provincial: Adamilca nueva Directora Regional por Sabina"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/03\/adamilca-rdguez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-71962 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/03\/adamilca-rdguez.jpg\" alt=\"\" width=\"280\" height=\"280\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/03\/adamilca-rdguez.jpg 670w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/03\/adamilca-rdguez-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/03\/adamilca-rdguez-300x300.jpg 300w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/a>La teniente coronel(FAD), Licenciada\u00a0<strong>Adamilca Rodr\u00edguez Mart\u00ednez<\/strong>, fue designada como nueva directora de Regional 11 con asiento en la provincia de Puerto Plata en sustituci\u00f3n de la licenciada <strong>Sabina Rodr\u00edguez<\/strong>.<!--more--><\/p>\n<p>La coronel Rodr\u00edguez Mart\u00ednez quien se desempe\u00f1a en la actualidad como directora del liceo de la Fuerza A\u00e9rea en Puerto Plata, fue la que mayor porcentaje logr\u00f3 de los maestros evaluados para esas funciones.<\/p>\n<p><strong>Adamilca Emelinda Rodr\u00edguez Mart\u00ednez.<\/strong><\/p>\n<ul>\n<li>Licenciatura en Educaci\u00f3n, Menci\u00f3n Ciencias Sociales (Universidad O&amp;M), con Maestr\u00eda en Evaluaci\u00f3n Educativa y Especialidad en Derechos Humanos e Internacional.<\/li>\n<\/ul>\n<div class=\"text_exposed_show\">\n<ul>\n<li>(Instituto Superior de la Defensa)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La teniente coronel(FAD), Licenciada\u00a0Adamilca Rodr\u00edguez Mart\u00ednez, fue designada como nueva directora de Regional 11 con asiento en la provincia de Puerto Plata en sustituci\u00f3n de la licenciada Sabina Rodr\u00edguez.<\/p>\n","protected":false},"author":12,"featured_media":71962,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,3],"tags":[],"class_list":["post-71961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=71961"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71961\/revisions"}],"predecessor-version":[{"id":71963,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/71961\/revisions\/71963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/71962"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=71961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=71961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=71961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}