{"id":72251,"date":"2018-04-12T18:42:15","date_gmt":"2018-04-12T22:42:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=72251"},"modified":"2018-04-12T18:42:15","modified_gmt":"2018-04-12T22:42:15","slug":"aduanas-detecta-mafia-en-importacion-de-vehiculos-de-lujo-hay-cuatro-empleados-vinculados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aduanas-detecta-mafia-en-importacion-de-vehiculos-de-lujo-hay-cuatro-empleados-vinculados\/","title":{"rendered":"Aduanas detecta mafia en importaci\u00f3n de veh\u00edculos de lujo; hay cuatro empleados vinculados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-72252 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/04\/aduanas-detecta-mafia-en-importacion-de-vehiculos-de-lujo-hay-cuatro-empleados-vinculados.jpeg\" alt=\"\" width=\"294\" height=\"195\" \/>El director general de Aduanas, Enrique Ram\u00edrez Paniagua, revel\u00f3 hoy que fue detectada una banda que introduc\u00eda veh\u00edculos de lujo al pa\u00eds en complicidad con cuatro empleados de esa entidad para evadir los impuestos de lugar.<!--more--><\/p>\n<p>\u201cFue detectada una banda que estaba introduciendo al pa\u00eds veh\u00edculos de lujo utilizando personal de aduanas en complicidad para no pagar los impuestos y luego vender esos veh\u00edculos al mercado\u201d, dijo Ram\u00edrez Paniagua.<\/p>\n<p>Manifest\u00f3 que ya han recuperado una cantidad importante de los veh\u00edculos contrabandeados, y que con la ayuda de la polic\u00eda y la autoridad judicial se est\u00e1 investigando el caso.<\/p>\n<p>Los acusados est\u00e1n apresados y \u201cla cancelaci\u00f3n ser\u00e1 parte del proceso\u201d.<\/p>\n<p>Las informaciones fueron dadas a conocer, en el proceso de destrucci\u00f3n de 88.7 millones de unidades de cigarrillos, producto de los m\u00e1s recientes decomisos hechos por la autoridad de la frontera de la Rep\u00fablica Dominicana.<\/p>\n<p>Estiman que este a\u00f1o los decomisos realizados por Aduanes implicar\u00edan unos 136,400 millones de pesos.<\/p>\n<p>\u201cEntendemos que el primer trimestre ha sido muy positivo para la econom\u00eda y la Aduana es un term\u00f3metro para medir lo que est\u00e1 pasando en la econom\u00eda dominicana\u201c, se\u00f1al\u00f3 el director general de Aduanas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director general de Aduanas, Enrique Ram\u00edrez Paniagua, revel\u00f3 hoy que fue detectada una banda que introduc\u00eda veh\u00edculos de lujo al pa\u00eds en complicidad con cuatro empleados de esa entidad para evadir los impuestos de lugar.<\/p>\n","protected":false},"author":9,"featured_media":72252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-72251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=72251"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72251\/revisions"}],"predecessor-version":[{"id":72253,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72251\/revisions\/72253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/72252"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=72251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=72251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=72251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}