{"id":72339,"date":"2018-05-23T18:39:56","date_gmt":"2018-05-23T22:39:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=72339"},"modified":"2018-05-23T18:39:56","modified_gmt":"2018-05-23T22:39:56","slug":"robert-pigozzi-es-primer-latino-clasifica-open-master-esqui","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/robert-pigozzi-es-primer-latino-clasifica-open-master-esqui\/","title":{"rendered":"Robert Pigozzi es primer latino clasifica Open M\u00e1ster Esqu\u00ed"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-72340 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/05\/image1-3.jpg\" alt=\"\" width=\"378\" height=\"252\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/05\/image1-3.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/05\/image1-3-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2018\/05\/image1-3-768x512.jpg 768w\" sizes=\"auto, (max-width: 378px) 100vw, 378px\" \/>Groveland, Florida.\u2014 El dominicano Robert Pigozzi hizo historia al convertirse el en el primer latinoamericano que clasifica para el torneo Masters de esqu\u00ed acu\u00e1tico en la categor\u00eda abierta de la modalidad Slalom, que se celebrar\u00e1 en Callaway Gardens, Atlanta, del 25 al 27 de mayo.<!--more--><\/p>\n<p>En el evento, el nativo de Boca Chica ten\u00eda la obligaci\u00f3n de ganar, ya que era la prueba en que solo al ganador le daban la oportunidad de ir a uno de los eventos m\u00e1s importantes de esqu\u00ed n\u00e1utico en el mundo, el Masters abierto de los Estados Unidos.<\/p>\n<p>Seg\u00fan el atleta, que es nativo de Boca Chica, dijo que:\u201d Aunque hab\u00eda entrenado muy duro, estaba muy nervioso antes de participar en este evento, porque sabia que si ganaba iba a hacer historia en Latinoam\u00e9rica entera\u201d.<\/p>\n<div><\/div>\n<p>Al Master de los Estados Unidos s\u00f3lo entran 8 esquiadores de todo el mundo, lo que explica el hecho de que antes ning\u00fan esquiador de toda latinoamerica haya logrado participar.<\/p>\n<p>Adem\u00e1s del dominicano participar\u00e1n en la prueba Adam Sedlmajer de Rep\u00fablica Checa, Freddy Winter y William Asher de Gran Breta\u00f1a, Jason MacClintock de Canad\u00e1, John Tavers y Nate Smith de Estados Unidos y el italiano Thomas Degasperi.<\/p>\n<p>Pigozzi dijo que \u201cAfortunadamente, en la primera ronda pude igualar mi r\u00e9cord personal y esto me dio la victoria que se consagr\u00f3 en la segunda ronda. Me siento muy contento, porque adem\u00e1s de un logro personal, es un logro para Rep\u00fablica Dominicana y para Latinoam\u00e9rica entera\u201d.<\/p>\n<p>El 59 torneo Masters se inici\u00f3 en el a\u00f1o 1959, en Callaway Gardens, Atlanta, y es considerado mundialmente como un honor y reconocimiento al esfuerzo y dedicaci\u00f3n de los mejores 8 esquiadores de slalom del mundo.<\/p>\n<p>Se recuerda que Pigozzi gan\u00f3 dos medallas de oro en la categor\u00eda, en la modalidad slalom en la versi\u00f3n 36 del campeonato Latinoamericano de ese deporte que se jug\u00f3 en M\u00e9xico a inicios de mayo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Groveland, Florida.\u2014 El dominicano Robert Pigozzi hizo historia al convertirse el en el primer latinoamericano que clasifica para el torneo Masters de esqu\u00ed acu\u00e1tico en la categor\u00eda abierta de la modalidad Slalom, que se celebrar\u00e1 en Callaway Gardens, Atlanta, del 25 al 27 de mayo.<\/p>\n","protected":false},"author":9,"featured_media":72340,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-72339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=72339"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72339\/revisions"}],"predecessor-version":[{"id":72341,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/72339\/revisions\/72341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/72340"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=72339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=72339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=72339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}