{"id":74551,"date":"2019-04-09T17:37:01","date_gmt":"2019-04-09T21:37:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=74551"},"modified":"2019-04-09T17:37:01","modified_gmt":"2019-04-09T21:37:01","slug":"nelson-javier-el-cocodrilo-si-se-malinterpreto-lo-que-dije-pido-disculpas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nelson-javier-el-cocodrilo-si-se-malinterpreto-lo-que-dije-pido-disculpas\/","title":{"rendered":"Nelson Javier (El Cocodrilo): \u201cSi se malinterpret\u00f3 lo que dije, pido disculpas\u201d"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-74552 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/201904092038131.jpeg\" alt=\"\" width=\"280\" height=\"144\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/201904092038131.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/201904092038131-300x155.jpeg 300w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/>El veterano comunicador de Santiago, Nelson Javier, pidi\u00f3 disculpas si se malinterpret\u00f3 su gesto y palabras en torno al caso que se le sigue a Kelvin N\u00fa\u00f1ez, conocido art\u00edsticamente como el payaso Kanqui, a quien se le investiga por varios casos de abuso infantil. <!--more--><\/p>\n<p>El acusado que se encontraba en los Estados Unidos llam\u00f3 a Nelson Javier, conductor de los programas de televisi\u00f3n \u201cEl show de Nelson\u201d y \u201cNueva noche\u201d de Santiago, para pedirle que mediara para \u00e9l entregarse a las autoridades y enfrentar las acusaciones que han salido a la luz sobre una conducta pederasta.<\/p>\n<p>El Cocodrilo a prop\u00f3sito de que explotara a la luz p\u00fablica el esc\u00e1ndalo que envuelve al payaso de Santiago utiliz\u00f3 su espacio para decir algunas palabras que no cayeron muy bien a sus seguidores. \u201cOjal\u00e1 que esto no se convierta en dar a conocer errores de hombres que trabajamos en la televisi\u00f3n que cogemos muchachitas y muchachitos\u201d.<\/p>\n<p>Desde el momento que Javier hizo ese pronunciamiento comenzaron las cr\u00edticas por quienes no vieron bien esas palabras y que \u00e9l estaba defendiendo a una persona que ha actuado muy mal.<\/p>\n<p>\u201cNo conozco a Kanqui, no soy su amigo, nunca \u00e9l ha ido a mi casa. No he dicho, ni dir\u00e9 que \u00e9l es inocente\u201d, coment\u00f3 al programa radial, \u00a0El Zol de la Ma\u00f1ana \u00a0y posteriormente habl\u00f3 en su espacio El Show de Nelson.<\/p>\n<p>\u201cSi dije algo que no estaba acorde conmigo, pido disculpas. Respeto el derecho de cada quien, han tergiversado mis comentarios. A los que han entendido otra cosa les pido excusas\u201d.<\/p>\n<p>El veterano locutor de Santiago manifest\u00f3 que \u00e9l s\u00f3lo cumpli\u00f3 con su deber como comunicador ya que, no s\u00f3lo sirvi\u00f3 de mediador para este caso, sino, que ha sido enlace para muchos otros casos que implican una investigaci\u00f3n por parte de la justicia. \u201cEstuve ah\u00ed como comunicador y como mediador, ya que Kanqui lo pidi\u00f3\u201d.<\/p>\n<p>Al concluir su programa de televisi\u00f3n en el d\u00eda de hoy dej\u00f3 claro que no volver\u00e1 a pasar nada en torno al payaso que est\u00e1 en manos de la justicia luego de que fuera acusado por varios ni\u00f1os de abuso, en un hecho que ha causado mucha sorpresa, sobre todo a la sociedad de Santiago.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El veterano comunicador de Santiago, Nelson Javier, pidi\u00f3 disculpas si se malinterpret\u00f3 su gesto y palabras en torno al caso que se le sigue a Kelvin N\u00fa\u00f1ez, conocido art\u00edsticamente como el payaso Kanqui, a quien se le investiga por varios casos de abuso infantil.<\/p>\n","protected":false},"author":9,"featured_media":74552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-74551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=74551"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74551\/revisions"}],"predecessor-version":[{"id":74553,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74551\/revisions\/74553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/74552"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=74551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=74551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=74551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}