{"id":74739,"date":"2019-04-22T09:56:24","date_gmt":"2019-04-22T13:56:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=74739"},"modified":"2019-04-22T09:57:06","modified_gmt":"2019-04-22T13:57:06","slug":"74739-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/74739-2\/","title":{"rendered":"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado"},"content":{"rendered":"<div class=\"paragraph\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-74740 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/636913957282281919w_11534262_20190420182222-2.jpg\" alt=\"\" width=\"258\" height=\"172\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/636913957282281919w_11534262_20190420182222-2.jpg 524w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/04\/636913957282281919w_11534262_20190420182222-2-300x200.jpg 300w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/>S\u00f3lo por este s\u00e1bado, que como cada 20 de abril los amantes de la marihuana en Estados Unidos est\u00e1n de celebraci\u00f3n, un local en el norte de Denver de la cadena Carl\u2019s Jr.<\/p>\n<p><!--more-->\u00a0ofrece a mayores de 21 a\u00f1os una hamburguesa con un ingrediente in\u00e9dito: Un extracto de cannabis.<\/p>\n<p>\u201cLa cantidad de personas que ya tuvimos esta ma\u00f1ana y que esperamos tener durante el resto del d\u00eda indican que existe una verdadera demanda por este tipo de productos\u201d, dijo Patty Trevi\u00f1o, vicepresidente de mercado de Carl\u2019s Jr.<\/p>\n<p>Trevi\u00f1o se\u00f1al\u00f3 que su \u201cRocky Mountain High Chee<\/p>\n<p>seburger Delight CBD\u201d, que contiene cinco miligramos de cannabidiol (CBD), un extracto del cannabis que no es psicoactivo porque contiene menos del 2 % de tetrahidrocannabinol (THC), constituye una respuesta del local al longevo pedido de los clientes.<\/p>\n<p>Adem\u00e1s del queso y de dos bifes de carne picada, la hamburguesa contiene una pasta que combina el CBD con jalape\u00f1os y la \u201csalsa distintiva\u201d de Carl\u2019s Jr., de acuerdo a la ejecutiva.<\/p>\n<p>Su precio es de 4.20 d\u00f3lares, en alusi\u00f3n a la fecha de hoy, seg\u00fan como se escribe en Estados Unidos (primero el mes y luego el d\u00eda), en la que muchos en el pa\u00eds festejan a la marihuana, cuyo consumo recreativo en Colorado es legal desde enero de 2014.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"multimediaMacroWrapper\">\n<div class=\"contentMedia art-gallery uno\">\n<div class=\"bx-wrapper\">\n<div class=\"bx-viewport\">\n<ul class=\"bxMultimediaText12596130-4\">\n<li class=\"bx-clone\">\n<figure class=\"cutlineShow\">\n<div class=\"img-container\"><img decoding=\"async\" class=\" lazyloaded\" title=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" src=\"https:\/\/estatico2.diariolibre.com\/placeholder\/svg\/viewbox\/524x350\" alt=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" \/><\/div>\n<\/figure>\n<\/li>\n<li>\n<figure class=\"cutlineShow\">\n<div class=\"img-container\"><img decoding=\"async\" class=\" lazyloaded\" title=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" src=\"https:\/\/estatico2.diariolibre.com\/placeholder\/svg\/viewbox\/524x350\" alt=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" \/><\/div>\n<\/figure>\n<\/li>\n<li>\n<figure class=\"cutlineShow\">\n<div class=\"img-container\"><img decoding=\"async\" class=\" lazyloaded\" title=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" src=\"https:\/\/estatico2.diariolibre.com\/placeholder\/svg\/viewbox\/524x350\" alt=\"\u201cSolo por hoy\u201d, hamburguesas con extracto de marihuana en local de Colorado\" \/><\/div>\n<\/figure>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>S\u00f3lo por este s\u00e1bado, que como cada 20 de abril los amantes de la marihuana en Estados Unidos est\u00e1n de celebraci\u00f3n, un local en el norte de Denver de la cadena Carl\u2019s Jr.<\/p>\n","protected":false},"author":9,"featured_media":74740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-74739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=74739"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74739\/revisions"}],"predecessor-version":[{"id":74742,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/74739\/revisions\/74742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/74740"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=74739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=74739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=74739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}