{"id":75319,"date":"2019-06-16T08:26:30","date_gmt":"2019-06-16T12:26:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75319"},"modified":"2019-06-16T08:26:30","modified_gmt":"2019-06-16T12:26:30","slug":"rd-sera-sede-xxi-olimpiada-de-matematicas-ac","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rd-sera-sede-xxi-olimpiada-de-matematicas-ac\/","title":{"rendered":"RD ser\u00e1 sede XXI Olimpiada de Matem\u00e1ticas AC"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75320 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/descarga-1-5.jpg\" alt=\"\" width=\"282\" height=\"179\" \/>Santo Domingo.-El Ministerio de Educaci\u00f3n anunci\u00f3 que se celebrar\u00e1 en el pa\u00eds la XXI Olimpiada de Matem\u00e1ticas de Centroam\u00e9rica y el Caribe, la cual se desarrollar\u00e1 desde el lunes 17 hasta el viernes 21 del mes en curso.<!--more--><\/p>\n<p>Dijo que en el evento participar\u00e1n delegaciones estudiantiles de 13 pa\u00edses que competir\u00e1n por el oro en esta \u201ccompetencia del conocimiento\u201d.<\/p>\n<p>Educaci\u00f3n es la instituci\u00f3n que encabeza la gesti\u00f3n del evento y contar\u00e1 con m\u00e1s de 150 estudiantes, jueces, tutores e invitados especiales entre ellos representantes de Colombia, Puerto Rico, Guatemala, Cuba, Jamaica, Hait\u00ed, Honduras, Venezuela, Panam\u00e1, Nicaragua, El Salvador, M\u00e9xico, Costa y Rep\u00fablica Dominicana como pa\u00eds anfitri\u00f3n.<\/p>\n<p>La delegaci\u00f3n nacional est\u00e1 compuesta por los estudiantes Amelia G\u00f3mez, de cuarto grado de secundaria; \u00c1ngel Ure\u00f1a de quinto, \u00c1ngel Torres, de sexto, y Gleidy Espinal, de cuarto de primaria.<\/p>\n<p>Se resalta que todos tuvieron que pasar las pruebas en las competencias distritales, regionales y nacionales para luego ser elegidos como representantes locales.<\/p>\n<p>El objetivo de esta competencia es promover la participaci\u00f3n de los pa\u00edses de la regi\u00f3n en concursos ol\u00edmpicos de matem\u00e1ticas, adem\u00e1s de identificar j\u00f3venes con talento para esta disciplina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.-El Ministerio de Educaci\u00f3n anunci\u00f3 que se celebrar\u00e1 en el pa\u00eds la XXI Olimpiada de Matem\u00e1ticas de Centroam\u00e9rica y el Caribe, la cual se desarrollar\u00e1 desde el lunes 17 hasta el viernes 21 del mes en curso.<\/p>\n","protected":false},"author":9,"featured_media":75320,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-75319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75319"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75319\/revisions"}],"predecessor-version":[{"id":75321,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75319\/revisions\/75321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75320"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}