{"id":75351,"date":"2019-06-19T07:08:44","date_gmt":"2019-06-19T11:08:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75351"},"modified":"2019-06-19T07:08:44","modified_gmt":"2019-06-19T11:08:44","slug":"mas-de-150-estudiantes-participan-en-xxi-olimpiadas-de-matematicas-de-centroamerica-y-el-caribe","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mas-de-150-estudiantes-participan-en-xxi-olimpiadas-de-matematicas-de-centroamerica-y-el-caribe\/","title":{"rendered":"M\u00e1s de 150 estudiantes participan en XXI Olimp\u00edadas de Matem\u00e1ticas de Centroam\u00e9rica y el Caribe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75352 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/mas-de-150-estudiantes-participan-en-xxi-olimpiadas-de-matematicas-de-centroamerica-y-el-caribe.jpeg\" alt=\"\" width=\"210\" height=\"195\" \/>Con la participaci\u00f3n de m\u00e1s de 150 estudiantes de 13 pa\u00edses, contin\u00faa desarroll\u00e1ndose la \u201cXXI Olimpiadas de Matem\u00e1ticas de Centro Am\u00e9rica y del Caribe\u201d, con los auspicios del Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana.<!--more--><\/p>\n<p>En el evento, que se inici\u00f3 el pasado lunes en uno de los salones del hotel Catalonia y se desarrollar\u00e1 hasta el pr\u00f3ximo viernes 21 de junio, participan delegaciones de Colombia, Puerto Rico, Guatemala, Cuba, Jamaica, Honduras, Venezuela, Panam\u00e1, Nicaragua, El Salvador, M\u00e9xico, Costa Rica y Rep\u00fablica Dominicana como pa\u00eds anfitri\u00f3n.<\/p>\n<p>El objetivo de esta competencia es promover la participaci\u00f3n de los pa\u00edses de la regi\u00f3n en concursos ol\u00edmpicos de matem\u00e1ticas, adem\u00e1s de identificar j\u00f3venes con talento para esta disciplina y fomentar el intercambio de experiencias acad\u00e9micas para fortalecer las relaciones bilaterales.<\/p>\n<p>El director General de Curr\u00edculo, Jos\u00e9 Remigio Garc\u00eda, dijo que el Ministerio de Educaci\u00f3n se agradecido de que el pa\u00eds sirva de sede para esta actividad educativa que se realiza anualmente como concurso de matem\u00e1ticas entre j\u00f3venes estudiantes de diversos pa\u00edses de la regi\u00f3n.<\/p>\n<p>Explic\u00f3 que este tipo de eventos tiene el prop\u00f3sito de crear entusiasmo por la matem\u00e1tica, disciplina que causa muchas veces temor entre los estudiantes por la complejidad que encierra.<\/p>\n<p>\u201cAuguramos el mayor de los \u00e9xitos a todos los participantes; a los estudiantes para que encuentren la importancia de aprender matem\u00e1ticas para la vida y a los docentes para que enriquezcan sus experiencias acad\u00e9micas y puedan estimular sus aprendizajes desmontando los temores y miedos que se han creado en torno a las matem\u00e1ticas\u201d, expres\u00f3 Remigio Garc\u00eda.<\/p>\n<p>Explic\u00f3 en este concurso se abordar\u00e1n problemas de diversas tem\u00e1ticas y dificultad de los diversos campos de la matem\u00e1tica de la educaci\u00f3n secundaria, \u201cque esperamos que todos los participantes est\u00e9n en la capacidad y actitud de enfrentar\u201d.<\/p>\n<p>De su lado, el presidente del Comit\u00e9 Ol\u00edmpico Internacional, maestro Octavio Gal\u00e1n agradeci\u00f3 al Ministerio de Educaci\u00f3n que en todo momento estuvo en la disposici\u00f3n para realizar \u201cesta fiesta del conocimiento\u201d.<\/p>\n<p>Datos<\/p>\n<p>La delegaci\u00f3n nacional est\u00e1 compuesta por los estudiantes Amelia G\u00f3mez, de cuarto grado de secundaria, \u00c1ngel Ure\u00f1a, de quinto, \u00c1ngel Torres, de sexto y Gleidy Espinal, de cuarto. Todos tuvieron que pasar las pruebas en las competencias distritales, regionales y nacionales para luego ser elegidos como representantes locales.<\/p>\n<p>Las reglas de la Olimpiada establecen que los alumnos no deben ser mayores de 16 a\u00f1os, ni haber participado m\u00e1s de una vez en las Olimp\u00edadas Iberoamericana de Matem\u00e1tica o en la Internacional de Matem\u00e1tica, tampoco haberse matriculado en una universidad.<\/p>\n<p>Los premios consisten en medallas de oro, plata y bronce, menciones honor\u00edficas y entregas especiales. Todos los ganadores tambi\u00e9n reciben un diploma que los certifica como victoriosos del concurso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la participaci\u00f3n de m\u00e1s de 150 estudiantes de 13 pa\u00edses, contin\u00faa desarroll\u00e1ndose la \u201cXXI Olimpiadas de Matem\u00e1ticas de Centro Am\u00e9rica y del Caribe\u201d, con los auspicios del Ministerio de Educaci\u00f3n de la Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":9,"featured_media":75352,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-75351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75351"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75351\/revisions"}],"predecessor-version":[{"id":75353,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75351\/revisions\/75353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75352"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}