{"id":75375,"date":"2019-06-20T07:14:20","date_gmt":"2019-06-20T11:14:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75375"},"modified":"2019-06-20T07:14:20","modified_gmt":"2019-06-20T11:14:20","slug":"escuelas-de-rd-pondran-enfasis-en-la-ensenanza-tecnico-profesional-y-en-artes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/escuelas-de-rd-pondran-enfasis-en-la-ensenanza-tecnico-profesional-y-en-artes\/","title":{"rendered":"Escuelas de RD pondr\u00e1n \u00e9nfasis en la ense\u00f1anza t\u00e9cnico-profesional y en artes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-75376 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/Minerd.jpg\" alt=\"\" width=\"325\" height=\"186\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/Minerd.jpg 558w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/Minerd-300x172.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/06\/Minerd-595x340.jpg 595w\" sizes=\"auto, (max-width: 325px) 100vw, 325px\" \/>SANTO DOMINGO. \u2013 A partir de agosto pr\u00f3ximo, cuando comienza el nuevo a\u00f1o escolar, el sistema de educaci\u00f3n p\u00fablica de la Rep\u00fablica Dominicana pondr\u00e1 \u00e9nfasis en las modalidades t\u00e9cnico-profesional y en las artes, se anunci\u00f3 este mi\u00e9rcoles.<!--more--><\/p>\n<p>La decisi\u00f3n en este sentido acaba de ser tomada por el Consejo Nacional de Educaci\u00f3n (CNE) en inter\u00e9s de que los estudiantes se coloquen en condiciones de insertarse \u201cde manera r\u00e1pida\u201d en el mercado laboral, dice una nota de prensa del Ministerio de Educaci\u00f3n.<\/p>\n<p>Durante la \u00faltima reuni\u00f3n del organismo, encabezada por el ministro de Educaci\u00f3n, Antonio Pe\u00f1a Mirabal, el CNE aprob\u00f3 adem\u00e1s el Calendario Escolar 2019-2020, previsto para comenzar el pr\u00f3ximo 19 de agosto y concluir el 19 de junio del 2020, dice el documento.<\/p>\n<div><\/div>\n<p>Constar\u00e1 de 197 d\u00edas laborables, equivalentes a 41 semanas lectivas de clases para los estudiantes, y 212 d\u00edas de trabajo docente, correspondiente a 45 semanas lectivas.<\/p>\n<p>La presentaci\u00f3n de la propuesta del calendario escolar fue realizada por el t\u00e9cnico docente Carlos Vidal, en representaci\u00f3n del Viceministerio de Asuntos T\u00e9cnicos y Pedag\u00f3gicos-<\/p>\n<p>Vidal explic\u00f3 que con las modalidades T\u00e9cnico-Profesional y Artes, los estudiantes tendr\u00e1n la posibilidad de una educaci\u00f3n contextualizada, orientada a dar respuestas a las necesidades tangibles en sus respectivas comunidades.<\/p>\n<p><strong>Entregar\u00e1n medallas<\/strong><\/p>\n<p>Por otra parte, el organismo rector escogi\u00f3 a tres maestros como ganadores de las medalla al M\u00e9rito Magisterial al Est\u00edmulo \u201cSalom\u00e9 Ure\u00f1a de Henr\u00edque\u201d, al Reconocimiento \u201cEugenio Mar\u00eda de Hostos\u201d y al Honor \u201cPedro Henr\u00edquez Ure\u00f1a\u201d, las cuales \u00a0ser\u00e1n entregadas en un acto en el Palacio Nacional el 30 de junio, D\u00eda del Maestro.<\/p>\n<p>Durante la reuni\u00f3n, el ministro Pe\u00f1a Mirabal jurament\u00f3 a los nuevos miembros del organismo: el viceministro Administrativo, Rafael Dar\u00edo Rodr\u00edguez Tav\u00e1rez y a la Consultora Jur\u00eddica, Teresa Garc\u00e9s.<\/p>\n<p><strong>Reconocimiento<\/strong><\/p>\n<p>En otro orden, el CNE reconoci\u00f3 con una placa a la maestra Altagracia D\u00edaz Belliard, ex directora del \u00d3rgano T\u00e9cnico, por su dedicaci\u00f3n, respeto, responsabilidad, entusiasta actitud en el desempe\u00f1o de su labor y siempre con miras a alcanzar las metas propuestas en favor de las mejoras al sistema educativo dominicano.<\/p>\n<p>Asimismo, aprob\u00f3 un reconocimiento al viceministro Adalberto Mart\u00ednez, por sus 50 a\u00f1os de labor ininterrumpida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. \u2013 A partir de agosto pr\u00f3ximo, cuando comienza el nuevo a\u00f1o escolar, el sistema de educaci\u00f3n p\u00fablica de la Rep\u00fablica Dominicana pondr\u00e1 \u00e9nfasis en las modalidades t\u00e9cnico-profesional y en las artes, se anunci\u00f3 este mi\u00e9rcoles.<\/p>\n","protected":false},"author":9,"featured_media":75376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-75375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75375"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75375\/revisions"}],"predecessor-version":[{"id":75377,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75375\/revisions\/75377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75376"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}