{"id":75628,"date":"2019-07-03T07:55:04","date_gmt":"2019-07-03T11:55:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75628"},"modified":"2019-07-03T07:55:04","modified_gmt":"2019-07-03T11:55:04","slug":"reportan-nueve-muertes-a-causa-del-dengue-en-el-sur-y-el-noroeste","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/reportan-nueve-muertes-a-causa-del-dengue-en-el-sur-y-el-noroeste\/","title":{"rendered":"Reportan nueve muertes a causa del dengue en el Sur y el Noroeste"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75629 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/reportan-nueve-muertes-a-causa-del-dengue-en-el-sur-y-el-noroeste.jpeg\" alt=\"\" width=\"330\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/reportan-nueve-muertes-a-causa-del-dengue-en-el-sur-y-el-noroeste.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/reportan-nueve-muertes-a-causa-del-dengue-en-el-sur-y-el-noroeste-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/>Al menos nueve personas han fallecido a causa del dengue en provincias del Sur y de la L\u00ednea Noroeste, mientras que en el hospital Materno Infantil San Lorenzo de Los Minas han ingresado 280 pacientes probables de dengue este a\u00f1o, diez de los cuales permanec\u00edan ayer hospitalizados.<!--more--><\/p>\n<p>En provincias del Sur se reportaron por lo menos siete fallecimientos de ni\u00f1os con s\u00edntomas de la enfermedad y sobre los 300 casos sospechosos; mientras que en Mao y en Dajab\u00f3n al menos dos personas murieron de dengue en una semana, ya que los casos de la enfermedad han aumentado, igual que en Santiago, dijeron m\u00e9dicos y autoridades sanitarias.<\/p>\n<p>Hamil P\u00e9rez Rosario, de 15 a\u00f1os, quien resid\u00eda en Aminilla, de Dajab\u00f3n, muri\u00f3 el lunes luego de ser ingresado en el hospital p\u00fablico de all\u00ed, afectado de dengue hemorr\u00e1gico. En tanto que el asesor de la regional Norte del Colegio M\u00e9dico Dominicano, Manas\u00e9s Pe\u00f1a, declar\u00f3 que hace una semana, un joven de 18 a\u00f1os, que no identific\u00f3, fue trasladado desde Mao hasta el hospital regional Jos\u00e9 Mar\u00eda Cabral y B\u00e1ez de Santiago, donde muri\u00f3.<\/p>\n<p><strong>EN PUNTOS<br \/>\nAlta incidencia.<\/strong>\u00a0Evelyn Cueto, directora del Materno Infantil San Lorenzo de Los Mina, se\u00f1al\u00f3 que el centro ha estado recibiendo casos en aumento, pero controlados.<\/p>\n<p><strong>Recomendaciones.<\/strong>\u00a0Mucha higiene, limpiar los entornos y techos de los hogares, evitar envases en los patios donde se acumule agua, tapar bien el agua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos nueve personas han fallecido a causa del dengue en provincias del Sur y de la L\u00ednea Noroeste, mientras que en el hospital Materno Infantil San Lorenzo de Los Minas han ingresado 280 pacientes probables de dengue este a\u00f1o, diez de los cuales permanec\u00edan ayer hospitalizados.<\/p>\n","protected":false},"author":9,"featured_media":75629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-75628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75628"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75628\/revisions"}],"predecessor-version":[{"id":75630,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75628\/revisions\/75630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75629"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}