{"id":75753,"date":"2019-07-09T07:55:12","date_gmt":"2019-07-09T11:55:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75753"},"modified":"2019-07-09T07:55:12","modified_gmt":"2019-07-09T11:55:12","slug":"sophy-y-fausto-rey-cantaran-en-el-anfiteatro-de-pp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sophy-y-fausto-rey-cantaran-en-el-anfiteatro-de-pp\/","title":{"rendered":"Sophy y Fausto Rey cantar\u00e1n en el anfiteatro de PP"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75754 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/descarga-8.jpg\" alt=\"\" width=\"267\" height=\"189\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/descarga-8.jpg 267w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/descarga-8-75x52.jpg 75w\" sizes=\"auto, (max-width: 267px) 100vw, 267px\" \/>Los cantantes rom\u00e1nticos Fausto Rey y Sophy ser\u00e1n las pr\u00f3ximas atracciones en el Anfiteatro Puerto Plata, donde presentar\u00e1n el s\u00e1bado 27 de julio el concierto \u201c\u00c9xitos y m\u00e1s \u00e9xitos\u201d.<!--more--><\/p>\n<p>Los cantantes estar\u00e1n acompa\u00f1ados por una super big band, inform\u00f3 el productor de la gala, el empresario art\u00edstico Luis Medrano.<\/p>\n<p>Se tratar\u00e1 de un reencuentro 45 a\u00f1os despu\u00e9s de aquella hist\u00f3rica primera vez en el Estadio Ol\u00edmpico, en la celebraci\u00f3n de los XII Juegos Centroamericanos y del Caribe en el a\u00f1o 1974.<\/p>\n<p>D\u00e9cadas m\u00e1s tarde, en 2007 se reedit\u00f3 otro concierto en el hotel Jaragua.<\/p>\n<p>\u201cEs como cuando uno tiene una mujer que le gusta, uno la repite y la repite y nunca se cansa de ella y descubre nuevos detalles en cada repetici\u00f3n\u201d, expres\u00f3 \u201cEl Niche\u201d dominicano embargado de emociones.<\/p>\n<p>\u201cMe muero por estar contigo\u201d, \u201cComp\u00e1rame\u201d, \u201cEl ritmo de la noche\u201d, \u201cCu\u00e9ntale a ella\u201d, \u201cUsted ya me olvid\u00f3\u201d, \u201cHast\u00edo\u201d, \u201cYa no vuelvo contigo\u201d y \u201cUn amante as\u00ed\u201d, son solo algunas de las canciones que entonar\u00e1 La Sophy.<\/p>\n<p>\u201cSophy y Fausto en Rep\u00fablica Dominicana y en Estados Unidos, juntos y separados, han logrado un rotundo \u00e9xito donde quiera que se presentan, para varias generaciones que a\u00fan recuerdan el Estadio Ol\u00edmpico o el Estadio Quisqueya totalmente repleto de p\u00fablico, es una experiencia imposible de olvidar cuando Sophy y Fausto hicieron historia\u201d, afirma Medrano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cantantes rom\u00e1nticos Fausto Rey y Sophy ser\u00e1n las pr\u00f3ximas atracciones en el Anfiteatro Puerto Plata, donde presentar\u00e1n el s\u00e1bado 27 de julio el concierto \u201c\u00c9xitos y m\u00e1s \u00e9xitos\u201d.<\/p>\n","protected":false},"author":9,"featured_media":75754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-75753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75753"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75753\/revisions"}],"predecessor-version":[{"id":75755,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75753\/revisions\/75755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75754"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}