{"id":75756,"date":"2019-07-09T07:58:25","date_gmt":"2019-07-09T11:58:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75756"},"modified":"2019-07-09T07:58:25","modified_gmt":"2019-07-09T11:58:25","slug":"tribunal-de-puerto-plata-condena-hombre-a-20-anos-de-prision-por-incesto-desconocidos-roban-yipeta-del-malecon","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tribunal-de-puerto-plata-condena-hombre-a-20-anos-de-prision-por-incesto-desconocidos-roban-yipeta-del-malecon\/","title":{"rendered":"Tribunal de Puerto Plata condena hombre a 20 a\u00f1os de prisi\u00f3n por incesto, desconocidos roban yipeta del Malec\u00f3n"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-75757\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/08-08-08-51-50-9775189.jpg\" alt=\"\" width=\"552\" height=\"414\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/08-08-08-51-50-9775189.jpg 552w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/08-08-08-51-50-9775189-300x225.jpg 300w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/>PUERTO PLATA.-<\/strong>\u00a0El Tribunal Colegiado de esta jurisdicci\u00f3n conden\u00f3 un hombre a 2 d\u00e9cadas de reclusi\u00f3n tras ser hallado culpable de incurrir en incesto contra su propia hija y de una sobrina.<!--more--><\/p>\n<p>La sentencia recay\u00f3 contra el nombrado Abelino Rosario, quien seg\u00fan el expediente acusatorio tramitado por el Ministerio P\u00fablico, incurri\u00f3 en el abominable delito en un sector del municipio Los Hidalgos (El Mamey).<\/p>\n<p>Los argumentos de pruebas presentados contra Rosario fueron contundentes para que citado tribunal lo condenara a 20 a\u00f1os de prisi\u00f3n, pena que deber\u00e1 cumplir en el Centro Correccional y de Rehabilitaci\u00f3n San Felipe de esta localidad.<\/p>\n<p>Durante el juicio, el imputado confes\u00f3 que tuvo relaciones sexuales con su hija adem\u00e1s de una sobrina cuyas identidades se omiten por razones legales, supuestamente para que tuvieran experiencia cuando les tocara estar con un hombre.<\/p>\n<p>En otro tenor informativo, sujetos desconocidos robaron anoche una yipeta propiedad del ciudadano franc\u00e9s Jordi Felipe, cuando dicho veh\u00edculo estaba estacionado en la avenida del Malec\u00f3n en esta ciudad atl\u00e1ntica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.-\u00a0El Tribunal Colegiado de esta jurisdicci\u00f3n conden\u00f3 un hombre a 2 d\u00e9cadas de reclusi\u00f3n tras ser hallado culpable de incurrir en incesto contra su propia hija y de una sobrina.<\/p>\n","protected":false},"author":9,"featured_media":75757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-75756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75756"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75756\/revisions"}],"predecessor-version":[{"id":75758,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75756\/revisions\/75758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75757"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}