{"id":75785,"date":"2019-07-11T08:31:17","date_gmt":"2019-07-11T12:31:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75785"},"modified":"2019-07-11T08:31:17","modified_gmt":"2019-07-11T12:31:17","slug":"con-el-merengue-no-esta-en-venta-la-constitucion-johnny-le-pone-musica-a-su-reclamo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/con-el-merengue-no-esta-en-venta-la-constitucion-johnny-le-pone-musica-a-su-reclamo\/","title":{"rendered":"Con el merengue \u201cNo est\u00e1 en venta la Constituci\u00f3n\u201d Johnny le pone m\u00fasica a su reclamo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75786 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/201907101535471.jpeg\" alt=\"\" width=\"330\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/201907101535471.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/201907101535471-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/>Se ha hecho viral en las redes sociales el tema del\u00a0 merenguero Johnny Ventura denominado \u201cNo est\u00e1 en venta la Constituci\u00f3n\u201d, en medio de las manifestaciones de protesta que encabeza ante los aprestos de los danilistas de reformar la Carta Magna.\u00a0<!--more--><\/p>\n<p>El popular merenguero y seguidor de Leonel Fern\u00e1ndez, lanza el tema en medio de las tensiones que se viven en la sociedad dominicana, sobre todo en el Congreso Nacional, debido a las denuncias de diversos legisladores de que en cualquier momento se introducir\u00eda por el Senado el proyecto de ley de convocatoria a la Asamblea Nacional Revisora de la Constituci\u00f3n, para para permitir una tercera postulaci\u00f3n presidencial de Danilo Medina.<\/p>\n<p>A continuaci\u00f3n el audio:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha hecho viral en las redes sociales el tema del\u00a0 merenguero Johnny Ventura denominado \u201cNo est\u00e1 en venta la Constituci\u00f3n\u201d, en medio de las manifestaciones de protesta que encabeza ante los aprestos de los danilistas de reformar la Carta Magna.\u00a0<\/p>\n","protected":false},"author":9,"featured_media":75786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-75785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75785"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75785\/revisions"}],"predecessor-version":[{"id":75787,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75785\/revisions\/75787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75786"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}