{"id":75821,"date":"2019-07-13T08:55:26","date_gmt":"2019-07-13T12:55:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=75821"},"modified":"2019-07-13T08:55:26","modified_gmt":"2019-07-13T12:55:26","slug":"ministro-de-educacion-dice-ningun-centro-debe-negarle-la-inscripcion-a-un-nino","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ministro-de-educacion-dice-ningun-centro-debe-negarle-la-inscripcion-a-un-nino\/","title":{"rendered":"Ministro de Educaci\u00f3n dice ning\u00fan centro debe negarle la inscripci\u00f3n a un ni\u00f1o"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75822 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/07\/descarga-1-4.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>El ministro de Educaci\u00f3n, Antonio Pe\u00f1a Mirabal, advirti\u00f3 que a ning\u00fan ni\u00f1o, ni\u00f1a, adolescente o adulto, se le puede negar el derecho a la educaci\u00f3n, sobre todo, por los aportes cuantitativos y cualitativos que realiza la Revoluci\u00f3n Educativa del presidente Danilo Medina.<!--more--><\/p>\n<p>\u201cLa educaci\u00f3n es un derecho fundamental, y nadie puede negarle el derecho a ning\u00fan ni\u00f1o para que pueda recibir educaci\u00f3n\u201d, precis\u00f3 Pe\u00f1a Mirabal. El ministro de Educaci\u00f3n habl\u00f3 a los medios durante un recorrido en la provincia de Monte Plata por algunas de las instalaciones que ser\u00e1n reacondicionadas para los Juegos Deportivos Escolares.<\/p>\n<p>Sostuvo, adem\u00e1s, que si no hay cupo en un centro, el director distrital debe buscar otras opciones, para no dejar fuera del aula a ning\u00fan estudiante.<\/p>\n<p><strong>Llamado<\/strong><\/p>\n<p>En tal sentido, Pe\u00f1a Mirabal llam\u00f3 a los directores regionales y distritales, as\u00ed como a los directores de escuelas, para que hagan todo lo posible en el apoyo a las familias que buscan una oportunidad de inscripci\u00f3n para sus hijos y, a veces, no encuentran el espacio por la migraci\u00f3n masiva que se genera desde colegios a escuelas de Jornada Escolar Extendida.<\/p>\n<p>\u201cDesde el Ministerio de Educaci\u00f3n no hay ning\u00fan tipo de restricci\u00f3n en el sentido de que todo el que quiera estudiar tiene derecho a hacerlo\u201d, precis\u00f3 el ministro de Educaci\u00f3n, a prop\u00f3sito de que en agosto pr\u00f3ximo inicia el a\u00f1o escolar 2019-2020.<\/p>\n<p>Pe\u00f1a Mirabal fue enf\u00e1tico en que el Ministerio de Educaci\u00f3n est\u00e1 en la obligaci\u00f3n de darle cabida a la comunidad educativa en los distintos centros de todo el pa\u00eds, los cuales ya garantizan el acceso a m\u00e1s de dos millones de estudiantes.<\/p>\n<p>\u201cNing\u00fan director de centro puede rechazar ni repeler ning\u00fan tipo de solicitud de parte de padres, madres o tutores que quieran inscribir sus hijos para el pr\u00f3ximo a\u00f1o escolar. La meta es que nadie se quede fuera del aula y, con el favor de Dios y el apoyo del cuerpo docente, as\u00ed ser\u00e1\u00bb, manifest\u00f3.<\/p>\n<p>La Revoluci\u00f3n Educativa, adem\u00e1s de brindar una ense\u00f1anza integral ocho horas al d\u00eda, tambi\u00e9n nutre a los estudiantes con desayuno, dos meriendas y almuerzo, los cuales se suman a la entrega gratuita de uniformes, kits did\u00e1cticos y oportunidades de desarrollo tecnol\u00f3gico con Rep\u00fablica Digital Educaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Educaci\u00f3n, Antonio Pe\u00f1a Mirabal, advirti\u00f3 que a ning\u00fan ni\u00f1o, ni\u00f1a, adolescente o adulto, se le puede negar el derecho a la educaci\u00f3n, sobre todo, por los aportes cuantitativos y cualitativos que realiza la Revoluci\u00f3n Educativa del presidente Danilo Medina.<\/p>\n","protected":false},"author":9,"featured_media":75822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-75821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=75821"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75821\/revisions"}],"predecessor-version":[{"id":75823,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/75821\/revisions\/75823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/75822"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=75821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=75821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=75821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}