{"id":76192,"date":"2019-08-11T14:50:24","date_gmt":"2019-08-11T18:50:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76192"},"modified":"2019-08-11T14:53:35","modified_gmt":"2019-08-11T18:53:35","slug":"las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos\/","title":{"rendered":"Las Reinas del Caribe suman oro a Rep\u00fablica Dominicana en los Panamericanos"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76193\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos.jpeg\" alt=\"\" width=\"623\" height=\"460\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos.jpeg 623w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos-300x222.jpeg 300w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><\/a>Las Reinas del Caribe de Rep\u00fablica Dominicana conquistaron este domingo la medalla de oro en el voleibol, tras disponer con marcador de 3-1 a Colombia en el partido final de esta disciplina correspondiente a los Panamericanos que se efect\u00faan en Lima, Per\u00fa.<!--more--><\/p>\n<p>Tras una espera de 16 a\u00f1os de haber alcanzado esta presea en los Panam efectuado en Santo Domingo en el 2003, las dominicanas vuelven a edificar sus dotes de brillantes hero\u00ednas a nivel mundial, tras este nuevo logro ante un equipo de Colombia, que se convirti\u00f3 en la gran revelaci\u00f3n del torneo.<\/p>\n<p>Las quisqueyanas ganaron un \u00faltimo sets 25-16 para sellar la corona, tras un \u00faltimo punto marcado por un remate de Priscila Rivera. Las Reinas conquistaron el evento de manera invicta y solo perdieron sets ante Colombia, dos y frente a Argentina en la semifinal.<\/p>\n<p>Esta corona de las quisqueyanas representa el octavo oro que registra la Rep\u00fablica Dominicana en los actuales juegos y ahora suma 35 medallas en total.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-76197\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n.jpg\" alt=\"\" width=\"619\" height=\"619\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/08\/68359062_1096527713875646_842220271879323648_n-768x768.jpg 768w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/listindiario.com\/el-deporte\/2019\/08\/11\/577768\/las-reinas-del-caribe-suman-oro-a-republica-dominicana-en-los-panamericanos\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Reinas del Caribe de Rep\u00fablica Dominicana conquistaron este domingo la medalla de oro en el voleibol, tras disponer con marcador de 3-1 a Colombia en el partido final de esta disciplina correspondiente a los Panamericanos que se efect\u00faan en Lima, Per\u00fa.<\/p>\n","protected":false},"author":12,"featured_media":76197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-76192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76192"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76192\/revisions"}],"predecessor-version":[{"id":76198,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76192\/revisions\/76198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76197"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}