{"id":76437,"date":"2019-09-02T09:27:43","date_gmt":"2019-09-02T13:27:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76437"},"modified":"2019-09-02T09:27:43","modified_gmt":"2019-09-02T13:27:43","slug":"enfermedad-cerebrovascular-cinco-datos-que-debes-saber-sobre-esta-urgencia-medica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/enfermedad-cerebrovascular-cinco-datos-que-debes-saber-sobre-esta-urgencia-medica\/","title":{"rendered":"Enfermedad cerebrovascular: cinco datos que debes saber sobre esta urgencia m\u00e9dica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-76438 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/descarga-3.jpg\" alt=\"\" width=\"275\" height=\"183\" \/>La enfermedad cerebrovascular tiene un alto costo social y econ\u00f3mico, pues es una importante causa de muerte y discapacidad.<!--more--><\/p>\n<p>Si bien las personas de 70 a\u00f1os en adelante tienen m\u00e1s probabilidades de sufrir un accidente cerebrovascular, el riesgo de derrames empieza a aumentar a partir de los 55 a\u00f1os. Individuos en edad productiva pueden verse afectados y, con ellos, su entorno familiar m\u00e1s cercano.<\/p>\n<p>\u00bfC\u00f3mo prevenir la enfermedad cerebrovascular? \u00bfCu\u00e1les son sus tipos? \u00bfC\u00f3mo reconocer los s\u00edntomas m\u00e1s comunes? \u00bfPor qu\u00e9 hay que actuar con rapidez ante el primer indicio de un derrame?<\/p>\n<p>El paname\u00f1o V\u00edctor Urrutia, especialista en derrames cerebrales y director del Johns Hopkins Comprehensive Stroke Center, comparte con List\u00edn Diario la respuesta a estas y otras preguntas.<\/p>\n<p>Estos son cinco datos b\u00e1sicos que debes conocer sobre esta urgencia m\u00e9dica.<\/p>\n<p><strong>1. Hay dos tipos de derrame cerebral<\/strong><br \/>\nEl m\u00e1s com\u00fan, el infarto cerebral, representa el 85 por ciento de los casos. Este se produce debido a la oclusi\u00f3n de una arteria. La arteria se obstruye cuando se forma un co\u00e1gulo o se desprende la placa de colesterol.<\/p>\n<p>\u201cIgual que en el coraz\u00f3n, que cuando se tapa la arteria se infarta el coraz\u00f3n, en el cerebro, si se tapa la arteria, se da\u00f1a esa parte del cerebro\u201d, explica Urrutia.<\/p>\n<p>El otro tipo de enfermedad cerebrovascular, que se presenta en el 15 por ciento de los casos, es la hemorragia. En esta, el vaso sangu\u00edneo no se obstruye, sino que se rompe produciendo un sangrado. La acumulaci\u00f3n de la sangre genera presi\u00f3n en el cerebro da\u00f1ando la parte afectada.<\/p>\n<p>La mortalidad de la hemorragia es de 40 por ciento; la del infarto cerebral, de 5 a 10 por ciento.<\/p>\n<p>Los hombres sufren derrames a edades m\u00e1s tempranas que las mujeres, pero entre ellas el riesgo aumenta m\u00e1s tarde en la vida.<\/p>\n<p>Existe una clase de evento cerebrovascular m\u00e1s com\u00fan en mujeres: la hemorragia subaracnoidea. Esta ocurre en la parte externa del cerebro y, por lo regular, se debe a un aneurisma.<\/p>\n<p><strong>2. Varios factores de riesgo son modificables<\/strong><br \/>\nTanto en el derrame como en el infarto cerebral, la presi\u00f3n alta constituye el principal factor de riesgo.<\/p>\n<p>\u201cLa presi\u00f3n alta normalmente no da s\u00edntomas\u201d, dice Urrutia. \u201cLa \u00fanica forma en que una persona puede saber si tiene presi\u00f3n alta es si se hace una revisi\u00f3n de la presi\u00f3n peri\u00f3dicamente y esa es una de las recomendaciones b\u00e1sicas para la prevenci\u00f3n\u201d.<\/p>\n<p>Otras medidas preventivas incluyen el ejercicio regular y una dieta saludable. Unos 20 o 30 minutos de ejercicio moderado al d\u00eda ayudan a controlar factores de riesgo como el sobrepeso, la diabetes y la presi\u00f3n alta. Tambi\u00e9n se recomienda ingerir abundantes frutas y vegetales, reducir el consumo de sal, comer menos grasas animales y preferir, en cambio, grasas vegetales como el aceite de oliva y las nueces.<\/p>\n<p>El tabaquismo eleva el riesgo de accidentes cerebrovasculares, por tanto, es importante evitarlo.<\/p>\n<p><strong>3. Los s\u00edntomas se presentan de forma s\u00fabita<\/strong><br \/>\nLas manifestaciones del derrame cerebral dependen del \u00e1rea del cerebro que se vea afectada. Estas incluyen:<\/p>\n<ul>\n<li>P\u00e9rdida de balance o equilibrio<\/li>\n<li>\n<p>Disminuci\u00f3n en la visi\u00f3n en un ojo o visi\u00f3n doble<\/p>\n<\/li>\n<li>\n<p>Debilidad en un lado de la cara<\/p>\n<\/li>\n<li>\n<p>Debilidad en el brazo y la pierna de un lado del cuerpo<\/p>\n<\/li>\n<li>\n<p>Problemas en el lenguaje (dificultad para hablar o entender el habla)<\/p>\n<\/li>\n<\/ul>\n<p>En la hemorragia cerebral puede haber dolor de cabeza s\u00fabito o disminuci\u00f3n en el estado de conciencia.<\/p>\n<p>Los s\u00edntomas asociados al evento cerebrovascular se asemejan a los de otros problemas m\u00e9dicos. \u201cLa clave es que sean s\u00fabitos: uno est\u00e1 bien y de repente le dan estos s\u00edntomas\u201d, aclara Urrutia.<\/p>\n<p><strong>4. Ante un derrame, se debe actuar con rapidez<\/strong><br \/>\nAnte la primera se\u00f1al de que la persona sufre un derrame cerebral, hay que actuar con rapidez. El paciente debe ir a la emergencia de inmediato (si se encuentra inconsciente o tiene dificultad para respirar es mejor llevarlo al centro de salud m\u00e1s cercano para estabilizarlo y luego trasladarlo a una instituci\u00f3n que posea la tecnolog\u00eda y los medios para tratarlo).<\/p>\n<p>Urrutia recomienda, adem\u00e1s, apuntar la hora en que empezaron los s\u00edntomas o la \u00faltima vez que la persona se encontraba en buen estado. \u00bfPor qu\u00e9? Porque la efectividad del tratamiento depende del tiempo transcurrido desde que empez\u00f3 el episodio.<\/p>\n<p>Para el infarto cerebral, el tipo de derrame m\u00e1s frecuente, existen dos tratamientos \u201cmuy efectivos\u201d que se pueden aplicar hasta cuatro horas y media luego del inicio de los s\u00edntomas: la terapia trombol\u00edtica (se administra un medicamento que disuelve el co\u00e1gulo que ha obstruido la arteria) y la trombectom\u00eda (cuando la arteria es grande, se extrae el co\u00e1gulo con ayuda de un cat\u00e9ter).<\/p>\n<p>\u201cLo nuevo es que ese procedimiento (la trombectom\u00eda) se puede hacer en una persona hasta en las 24 horas de haber empezado los s\u00edntomas, pero requiere una imagen del cerebro m\u00e1s avanzada, estudios de perfusi\u00f3n con tomograf\u00eda axial computarizada o con resonancia magn\u00e9tica, para seleccionar a los pacientes que todav\u00eda pueden ser beneficiados por el procedimiento\u201d, indica Urrutia.<\/p>\n<p>Como toda condici\u00f3n urgente, expresa el m\u00e9dico, los pacientes con derrame cerebral se benefician de una buena organizaci\u00f3n del sistema de salud. \u201cSi el hospital est\u00e1 preparado para detectar tempranamente a los pacientes y pasarlos por un proceso r\u00e1pido de diagn\u00f3stico y tratamiento, eso le da las mejores probabilidades a la persona de recuperarse lo m\u00e1s posible\u201d.<\/p>\n<p><strong>5. El sobreviviente podr\u00eda volver a sufrir un derrame<\/strong><br \/>\nLuego de un evento cerebrovascular, los m\u00e9dicos hacen pruebas en el paciente para determinar la causa del problema e iniciar terapias que prevengan derrames futuros.<\/p>\n<p>Al mismo tiempo, la persona debe someterse a terapias de rehabilitaci\u00f3n para superar las secuelas dejadas por el da\u00f1o en el cerebro. Estas involucran terapia f\u00edsica, ocupacional y del lenguaje.<\/p>\n<p>En centros como Johns Hopkins, informa Urrutia, se est\u00e1 implementando el uso de aditamentos rob\u00f3ticos para ayudar a los pacientes a recuperar la movilidad. Otra novedad es el uso de videojuegos con el mismo fin.<\/p>\n<p><strong>V\u00edctor Urrutia<br \/>\nNeur\u00f3logo<\/strong><br \/>\n<strong>\u201cNo se debe dejar pasar tiempo\u201d\u00a0<\/strong><br \/>\nEspecialista en derrames cerebrales y director del Johns Hopkins Comprehensive Stroke Center. Se centra en los aspectos cl\u00ednicos de la enfermedad cerebrovascular, espec\u00edficamente la terapia y prevenci\u00f3n. Estuvo en el pa\u00eds para disertar durante un evento de educaci\u00f3n cl\u00ednica organizado por la Sociedad Dominicana de Neurolog\u00eda y Neurocirug\u00eda (SDNN).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad cerebrovascular tiene un alto costo social y econ\u00f3mico, pues es una importante causa de muerte y discapacidad.<\/p>\n","protected":false},"author":9,"featured_media":76438,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-76437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76437"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76437\/revisions"}],"predecessor-version":[{"id":76439,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76437\/revisions\/76439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76438"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}