{"id":76449,"date":"2019-09-03T08:25:54","date_gmt":"2019-09-03T12:25:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76449"},"modified":"2019-09-03T08:25:54","modified_gmt":"2019-09-03T12:25:54","slug":"dorian-arrasa-en-bahamas-y-sigue-su-rumbo-a-florida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dorian-arrasa-en-bahamas-y-sigue-su-rumbo-a-florida\/","title":{"rendered":"Dorian arrasa en Bahamas y sigue su rumbo a Florida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-76450 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/dorian-arrasa-en-bahamas-y-sigue-su-rumbo-a-florida.jpeg\" alt=\"\" width=\"330\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/dorian-arrasa-en-bahamas-y-sigue-su-rumbo-a-florida.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/dorian-arrasa-en-bahamas-y-sigue-su-rumbo-a-florida-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/>El hurac\u00e1n Dorian arras\u00f3 parte de las Bahamas dejando hasta el momento cinco muertos y da\u00f1os incalculables, mientras segu\u00eda ayer lunes su camino hacia la costa de Florida (EE.UU.), que permanece en m\u00e1xima alerta ante la fuerza del cicl\u00f3n de categor\u00eda 4.<!--more--><\/p>\n<p>El hurac\u00e1n Dorian baj\u00f3 ayer a categor\u00eda 4 en la escala Saffir-Simpson despu\u00e9s de que sus vientos m\u00e1ximos sostenidos se redujeran a 145 millas por hora (233 km\/h) y a\u00fan permanece sobre el norte del archipi\u00e9lago de Bahamas. \u201cLas Bahamas est\u00e1 actualmente en guerra y siendo atacada por el hurac\u00e1n Dorian\u201d, dijo el primer ministro de Bahamas, Hubert Minnis, que confirm\u00f3 la muerte de cinco personas por el desastre natural.<\/p>\n<p>Previamente, el ministro de Asuntos Exteriores de Bahamas, Darren Henfield, dijo que hay informes extraoficiales de numerosos cuerpos flotando en las Islas \u00c1baco. El funcionario indic\u00f3 que las l\u00edneas el\u00e9ctricas est\u00e1n ca\u00eddas y los \u00e1rboles derribados y asegur\u00f3 que los equipos de rescate se trasladar\u00e1n a las zonas donde hay informaci\u00f3n de personas en peligro en cuanto las condiciones lo permitan y poder hacer un balance oficial de v\u00edctimas y da\u00f1os.<\/p>\n<p>En las im\u00e1genes difundidas por habitantes de \u00c1bacos se pueden ver autom\u00f3viles y casas bajo el agua que ha convertido las calles en r\u00edos, todo ello acompa\u00f1ado de vientos que en algunos momentos se acercaron a los 350 kil\u00f3metros por hora. Gran Bahama tambi\u00e9n result\u00f3 totalmente inundada y a\u00fan se siente la fuerza del hurac\u00e1n.<\/p>\n<p><strong>Emergencia<\/strong><br \/>\nPor otro lado, el presidente de EE.UU., Donald Trump, emiti\u00f3 declaraciones de emergencia para los estados de Georgia, Carolina del Norte y del Sur, que se suman a la aprobada el pasado viernes para Florida.<\/p>\n<p>El gobernador de Carolina del Sur, Henry McMaster, orden\u00f3 la evacuaci\u00f3n obligatoria a partir del mediod\u00eda de ayer lunes. Los expertos del NHC prev\u00e9n que Dorian se aproxime lentamente hacia la costa de Florida, aunque no llegue a impactar directamente gracias a un giro gradual hacia el nornoroeste hoy martes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hurac\u00e1n Dorian arras\u00f3 parte de las Bahamas dejando hasta el momento cinco muertos y da\u00f1os incalculables, mientras segu\u00eda ayer lunes su camino hacia la costa de Florida (EE.UU.), que permanece en m\u00e1xima alerta ante la fuerza del cicl\u00f3n de categor\u00eda 4.<\/p>\n","protected":false},"author":9,"featured_media":76450,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-76449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76449"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76449\/revisions"}],"predecessor-version":[{"id":76451,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76449\/revisions\/76451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76450"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}