{"id":76503,"date":"2019-09-14T21:38:48","date_gmt":"2019-09-15T01:38:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76503"},"modified":"2019-09-14T21:38:48","modified_gmt":"2019-09-15T01:38:48","slug":"salud-mental-en-el-trabajo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/salud-mental-en-el-trabajo\/","title":{"rendered":"Salud mental en el trabajo"},"content":{"rendered":"<div class=\"paragraph\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-76504 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/1254153-3_12225945_20190914211114.jpg\" alt=\"\" width=\"310\" height=\"199\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/1254153-3_12225945_20190914211114.jpg 546w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/1254153-3_12225945_20190914211114-300x192.jpg 300w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" \/>Hablar de salud mental en el entorno laboral sigue siendo un gran tab\u00fa. Un informe elaborado por la consultora\u00a0<b>Page Group indica que el 36% de los trabajadores considera que tratar estos temas puede ser perjudicial para su carrera<\/b>; el 20% cree que provocar\u00e1 el rechazo de sus compa\u00f1eros y el 34% entiende que puede terminar reflejando una imagen equivocada de ellos.<\/p>\n<p><!--more-->Adem\u00e1s, entre el 50% de los trabajadores que han experimentado problemas de salud mental y han acudido a sus superiores, 1 de cada 5 asegura haberse sentido incomprendido y no cree haber solucionado nada.<\/p>\n<p>Asimismo, el informe se\u00f1ala que en la actualidad m\u00e1s de\u00a0<b>300 millones de personas sufren problemas derivados de una mala salud mental,<\/b>\u00a0lo que supone una importante p\u00e9rdida econ\u00f3mica para el sector empresarial. En el a\u00f1o 2017, esta se cifr\u00f3 en 246 billones de d\u00f3lares a nivel mundial.<\/p>\n<div class=\"in-content-info 3 0\"><\/div>\n<p>\u201cEl estr\u00e9s laboral es uno de los grandes problemas del siglo XXI. Hoy en d\u00eda, el trabajo es mucho m\u00e1s intelectual que en generaciones anteriores, pues est\u00e1 m\u00e1s centrado en tareas cognitivas. Adem\u00e1s, vivimos en un mundo globalizado, con continuos cambios y una fuerte competencia, por lo que tener un nivel de productividad alto es clave, lo que provoca m\u00e1s estr\u00e9s\u201d, afirma Esther Carrera, miembro de Page Group.<\/p>\n<p>\u201cEl estr\u00e9s es la respuesta que da el organismo, a trav\u00e9s de mecanismos biol\u00f3gicos y psicol\u00f3gicos, para adaptarse y afrontar las demandas del ambiente. Es esencial para la supervivencia pues hace que nos adaptemos a los cambios e imprevistos que puedan surgir\u201d, explica Mar\u00eda Jos\u00e9 Collado Mateo, doctora en psicolog\u00eda y codirectora del Centro Cuarto de Contadores,\u00a0ubicado en la localidad madrile\u00f1a de Legan\u00e9s. ()<\/p>\n<p>La psic\u00f3loga aclara que hay un estr\u00e9s positivo, que nos ayuda a enfrentarnos adecuadamente a los retos cotidianos, y un estr\u00e9s negativo o distr\u00e9s, que se caracteriza por una sensaci\u00f3n de sobrecarga.<\/p>\n<\/div>\n<div class=\"Nota_incrustada EM14093777\">\n<div class=\"mb-2 pt-2 pb-3 img-title-info h-xs-auto bg-transparent nota-inclustada-generica\">\n<blockquote><p><span class=\"sup_title\">TE PUEDE INTERESAR<\/span><\/p>\n<h3 class=\"mx-2\"><span class=\"priority-content\">Depresi\u00f3n: un flagelo de la salud mental que va en orden ascendente<\/span><\/h3>\n<\/blockquote>\n<\/div>\n<\/div>\n<div class=\"paragraph\">\n<p>En este sentido, manifiesta que la respuesta de estr\u00e9s ante una situaci\u00f3n \u201cdepende en gran medida de la valoraci\u00f3n que la persona hace de ella, por lo que puede desencadenarse aunque esa persona tenga los recursos necesarios para afrontar dicha situaci\u00f3n adecuadamente\u201d.<\/p>\n<p>Collado indica que existe un amplio abanico de factores por los que se puede desencadenar un episodio de\u00a0<b>estr\u00e9s laboral.<\/b>\u00a0As\u00ed, es posible que las demandas del trabajo sean excesivas para la formaci\u00f3n del trabajador, los recursos materiales sean inadecuados, la carga mental de trabajo excesiva, el grado de control sobre el propio trabajo demasiado bajo o el tiempo para llevarlo a cabo con \u00e9xito sea insuficiente.<\/p>\n<p>Pero, seg\u00fan explica la especialista, el estr\u00e9s laboral tambi\u00e9n puede darse si las demandas del trabajo son demasiado bajas para la formaci\u00f3n del trabajador. \u201cEn muchas ocasiones el trabajador se siente infravalorado y estresado porque no puede desarrollar su potencial\u201d, apunta.<\/p>\n<p>Por otro lado, el estr\u00e9s laboral puede producirse debido a \u201cfactores sociales ajenos a la tarea\u201d, como una mala relaci\u00f3n con los compa\u00f1eros, subordinados o jefes o por recibir \u00f3rdenes o informaci\u00f3n contradictoria, entre otros.\u00a0<b>\u201cSon factores que pueden desencadenar episodios de estr\u00e9s si no se tienen buenas habilidades de resoluci\u00f3n de conflictos interpersonales\u201d, sostiene.<\/b><\/p>\n<p>Asimismo, el lugar de trabajo puede tener su papel en el desarrollo del estr\u00e9s laboral debido, por ejemplo, a temperaturas demasiado altas o demasiado bajas o a entornos con alto riesgo de accidentes f\u00edsicos o qu\u00edmicos. \u201cUn \u00faltimo factor importante es la inseguridad laboral, as\u00ed como la falta de posibilidades de promoci\u00f3n y desarrollo profesional\u201d, comenta.<\/p>\n<p>La psic\u00f3loga explica que el estr\u00e9s laboral se caracteriza por un sentimiento de sobrecarga \u201cdonde las peque\u00f1as tareas se viven con angustia y se sienten como una sobre-exigencia. Esto viene acompa\u00f1ado por agotamiento psicol\u00f3gico y malestar f\u00edsico asociado a s\u00edntomas como problemas de sue\u00f1o, digestivos, cardiacos, endocrinos o dermatol\u00f3gicos, as\u00ed como inestabilidad emocional, ansiedad, irritabilidad, falta de concentraci\u00f3n e, incluso, abuso de sustancias\u201d.<\/p>\n<p>Collado manifiesta que el estr\u00e9s laboral puede prevenirse a trav\u00e9s de las propias organizaciones y su relaci\u00f3n con sus trabajadores. En este sentido, la\u00a0<b>Organizaci\u00f3n Mundial de la Salud (OMS<\/b>) destaca la necesidad de reducir el estr\u00e9s a trav\u00e9s de la prevenci\u00f3n primaria, secundaria y terciaria.<\/p>\n<p>Por prevenci\u00f3n primaria entiende una buena ergonom\u00eda en el trabajo, unos roles bien definidos y una buena organizaci\u00f3n y gesti\u00f3n laboral. La prevenci\u00f3n secundaria se refiere a la necesidad de educar y capacitar a los trabajadores para el adecuado desempe\u00f1o de su funci\u00f3n. Por \u00faltimo, la prevenci\u00f3n terciaria tiene que ver con la reducci\u00f3n de los efectos del estr\u00e9s mediante el desarrollo de sistemas de gesti\u00f3n m\u00e1s sensibles y de una mejora de la salud ocupacional.<\/p>\n<p>En lo relativo al propio trabajador, si ya padece estr\u00e9s, \u201ces importante que aprenda a gestionar adecuadamente la valoraci\u00f3n de las situaciones que generan estr\u00e9s, a mejorar la gesti\u00f3n del tiempo, la autoestima y las habilidades de soluci\u00f3n de conflictos, adem\u00e1s de realizar actividad f\u00edsica regularmente\u201d, recomienda la psic\u00f3loga.<\/p>\n<p>Purificaci\u00f3n Le\u00f3n EFE-REPORTAJES<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hablar de salud mental en el entorno laboral sigue siendo un gran tab\u00fa. Un informe elaborado por la consultora\u00a0Page Group indica que el 36% de los trabajadores considera que tratar estos temas puede ser perjudicial para su carrera; el 20% cree que provocar\u00e1 el rechazo de sus compa\u00f1eros y el 34% entiende que puede terminar reflejando una imagen equivocada de ellos.<\/p>\n","protected":false},"author":9,"featured_media":76504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-76503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76503"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76503\/revisions"}],"predecessor-version":[{"id":76505,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76503\/revisions\/76505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76504"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}