{"id":76657,"date":"2019-09-23T12:31:27","date_gmt":"2019-09-23T16:31:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76657"},"modified":"2019-09-23T12:31:27","modified_gmt":"2019-09-23T16:31:27","slug":"romeo-santos-una-noche-memorable-para-la-bachata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/romeo-santos-una-noche-memorable-para-la-bachata\/","title":{"rendered":"Romeo Santos: Una noche memorable para la bachata"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-76658 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/romeo-santos-una-noche-memorable-para-la-bachata.jpeg\" alt=\"\" width=\"330\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/romeo-santos-una-noche-memorable-para-la-bachata.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/romeo-santos-una-noche-memorable-para-la-bachata-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/>El espect\u00e1culo \u201cUtop\u00eda the concert\u201d, que present\u00f3 Romeo Santos, la noche del s\u00e1bado, en el Metlife Stadium, de Nueva Jersey, se inscribir\u00e1 como uno de los shows m\u00e1s memorables que un artista dominicano haya realizado en Estados Unidos.<!--more--><\/p>\n<p>Y es que el evento rompi\u00f3 r\u00e9cords de recaudaci\u00f3n, cont\u00f3 con la presencia de m\u00e1s de 80 mil personas, tuvo invitados inolvidables como la rapera Cardi B, nueve bachateros, de los 11, con quienes Romeo grab\u00f3 su disco \u201cUtop\u00eda\u201d, (no pudieron estar presentes Teodoro Reyes y Anthony Santos) las actuaciones de los reguetoneros puertorrique\u00f1os Ozuna, Wisin y Yandel y una propuesta art\u00edstica de cuatro horas en el escenario.<\/p>\n<p>Desde que el artista dominicano anunci\u00f3 la haza\u00f1a de hacer un concierto en el retador estadio, el p\u00fablico supo que se tratar\u00eda de una producci\u00f3n en la que estar\u00edan cantando los artistas con quienes grab\u00f3 su m\u00e1s reciente disco \u201cUtop\u00eda\u201d, el que dio a conocer el pasado mes de abril, bajo el sello Sony Music Latin.<\/p>\n<p>Romeo subi\u00f3 a las 9:44 de la noche del s\u00e1bado y baj\u00f3 del escenario a la 1:48 de la madrugada del domingo con un cielo iluminado por fuegos artificiales y con un p\u00fablico mas que satisfecho, ya que adem\u00e1s de disfrutarse al artista entonando varias de las canciones de su larga lista de \u00e9xitos, tambi\u00e9n lo vieron interpretar por primera vez, junto a sus protagonistas, las canciones de \u201cUtop\u00eda\u201d.<\/p>\n<p>Mucho menos se esperaban la presencia de la rapera estadounidense,de ascendencia dominicana,Cardi B quien sorprendi\u00f3 en el escenario durante la actuaci\u00f3n del grupo Aventura mientras cantaban el cl\u00e1sico \u201cObsesi\u00f3n\u201d.<\/p>\n<p>En tarima la presencia de Cardi B se vio asediada por los guitarristas de Aventura, luego, tras la ovaci\u00f3n del p\u00fablico, Romeo la invit\u00f3 a cantar uno de sus \u00e9xitos pero antes Belcalis Alm\u00e1nzar (su nombre de pila) dijo en un espa\u00f1ol muy al estilo dominicano: \u201cep\u00e9rame d\u00e9jame quitarme lo zapato\u201d, y se acomod\u00f3 descalza para cantar \u201cI Like It\u201d, tema\u00a0 que grab\u00f3 junto a Bad Bunny, recibiendo la algarab\u00eda de los asistentes.<\/p>\n<p><strong>Bachateros invitados<\/strong><\/p>\n<p>La presencia de los invitados en \u201cUtop\u00eda the Concert\u201d no fue solo para acompa\u00f1ar a Romeo e interpretar las canciones que grabaron juntos en el disco, ya que tambi\u00e9n el p\u00fablico disfrut\u00f3 a capela o acompa\u00f1ado por la agrupaci\u00f3n, algunos de los temas m\u00e1s cl\u00e1sicos de cada bachatero, los cuales fueron coreados y ovacionados por todas las almas humanas presentes en el MetLife.<\/p>\n<p>Zacar\u00edas Ferreira tuvo el honor de ser el primer invitado y cantar junto Romeo el corte \u201cMe quedo\u201d. Antes el \u201cRey de la bachata\u201d hab\u00eda realizado la apertura con el tema \u201cIleso\u201d, interpretaci\u00f3n que debi\u00f3 realizar con Teodoro Reyes, pero este no pudo estar presente.<\/p>\n<p>El turno siguiente fue para Joe Veras, a quien se le observ\u00f3 afectado de sus piernas. Joe y Romeo cantaron \u201cAmor enterrado\u201d.<\/p>\n<p>Luego Elvis Mart\u00ednez lleg\u00f3 a escena para cantar \u201cMillonario\u201d, recibiendo los aplausos del p\u00fablico. De los cantantes del g\u00e9nero del amargue que estuvieron presentes, Monchy y Alezandra fueron de los m\u00e1s esperados, y es que luego de su separaci\u00f3n llevaban a\u00f1os sin cantar juntos. Acompa\u00f1ados de Romeo entonaron \u201cA\u00f1o luz\u201d. Al iniciar la canci\u00f3n los bachateros se dieron un abrazo llamando la atenci\u00f3n de los presentes ya que entre ambos existen evidentes diferencias.<\/p>\n<p>El Chaval de la Bachata tambi\u00e9n se llev\u00f3 fuertes ovaciones cuando le toc\u00f3 interpretar \u201cCanalla\u201d.\u00a0 tros de los m\u00e1s esperados y aplaudidos fueron Raul\u00edn Rodr\u00edguez y Frank Reyes. Raul\u00edn se luci\u00f3 con su estilo cantando \u201cLa demanda\u201d, y lo mismo hizo Frank Reyes al vocalizar \u201cPayaso\u201d.<\/p>\n<p>Luis Vargas tambi\u00e9n hizo lo suyo al entonar \u201cLos \u00faltimos\u201d. Luis tom\u00f3 alcohol en el escenario y hasta toc\u00f3 la guitarra en la espalda y con una botella.<\/p>\n<p>El siguiente d\u00fao de Romeo fue con Quico Rodr\u00edguez, pero antes de presentarlo Romeo revel\u00f3 que vaticin\u00f3 que la canci\u00f3n \u201cEl beso que no te di\u201d, tema que grabaron, ser\u00eda un hit, porque as\u00ed lo sinti\u00f3 en el estudio cuando la estaban grabando y acert\u00f3 porque el p\u00fablico la acogi\u00f3 a solo minutos de darla a conocer en las plataformas digitales.<\/p>\n<p>El final de los invitados fue el grupo Aventura. Henry, Max y Lenny se disfrutaron el volver a compartir el escenario junto a quien fuera su l\u00edder.<\/p>\n<p>Con Aventura Romeo hizo otros temas adem\u00e1s de \u201cLa demanda\u201d, canci\u00f3n con la que cerr\u00f3. En reguet\u00f3n<\/p>\n<p>El bachatero dominicano ha sido uno de los artistas mejor acogidos en el g\u00e9nero urbano. Sus \u201cjuntes\u201d con los exponentes del reguet\u00f3n se han convertido en himnos, as\u00ed que por este memorable concierto tambi\u00e9n desfilaron Wisin y Yandel y Ozuna.<\/p>\n<p>Con el d\u00fao de la historia hizo \u201cAullando\u201d y \u201cNoche de sexo\u201d; y con Ozuna cant\u00f3 \u201cSobredosis\u201d, \u201cLoba\u201d y \u201cEl farsante\u201d.<\/p>\n<p><strong>Agradecido<\/strong><\/p>\n<p>Durante las cuatro horas que tuvo el concierto Romeo se dio unos cuantos tragos de alcohol, agradeci\u00f3 el \u00e9xito y hasta la ausencia de Anthony Santos.<\/p>\n<p>Con una ingeniosa explicaci\u00f3n Romeo le cont\u00f3 a su fanaticada que lament\u00f3 la ausencia de Anthony Santos esa noche. Primero le agradeci\u00f3 al Mayimbe de la bachata por ser el artista que m\u00e1s le ha inspirado, luego resalt\u00f3 que tambi\u00e9n agradece los favores que Anthony Santos ha hecho por \u00e9l en su carrera.<\/p>\n<p>\u201cSi yo le he pedido 50 favores a Anthony Santos 50 favores me ha concedido. Yo llevo dos meses ensayando este concierto y por eso vamos a hacer esta bachata para que la escuche all\u00e1 en su campo \u201c, dijo Romeo al tocar la guitarra y cantar el tema de Anthony \u201cPor mi timidez\u201d.<\/p>\n<p><strong>RECONOCIDO<\/strong><\/p>\n<p><strong>R\u00c9CORDS<br \/>\nDisco de Platino.<\/strong>\u00a0Previo a la presentaci\u00f3n Romeo recibi\u00f3 el reconocimiento de parte del r\u00e9cords Guinness por ser el artita latino que m\u00e1s recuadaci\u00f3n monetaria realiz\u00f3 en el MetLife. Tambien recibi\u00f3 un doble disco de Platino de parte la Sony y un reconocmiento de parte de Pandora por generar mas tres billones de reproducciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El espect\u00e1culo \u201cUtop\u00eda the concert\u201d, que present\u00f3 Romeo Santos, la noche del s\u00e1bado, en el Metlife Stadium, de Nueva Jersey, se inscribir\u00e1 como uno de los shows m\u00e1s memorables que un artista dominicano haya realizado en Estados Unidos.<\/p>\n","protected":false},"author":9,"featured_media":76658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-76657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76657"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76657\/revisions"}],"predecessor-version":[{"id":76659,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76657\/revisions\/76659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76658"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}