{"id":76708,"date":"2019-09-28T08:40:06","date_gmt":"2019-09-28T12:40:06","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76708"},"modified":"2019-09-28T08:40:06","modified_gmt":"2019-09-28T12:40:06","slug":"nuevos-conciertos-del-dr-jazz-festival-2019-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nuevos-conciertos-del-dr-jazz-festival-2019-en-puerto-plata\/","title":{"rendered":"Nuevos conciertos del DR Jazz Festival 2019 en Puerto Plata"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-76709 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/09\/Ejecutivos-de-Fedujazz-e-invitados-especiales-300x200-2.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>PUERTO PLATA.- E<\/strong>l Dominican Republic Jazz Festival 2019 contin\u00faa en esta ciudad con las presentaciones de destacados m\u00fasicos y cantantes nacionales e internacionales.<!--more--><\/p>\n<p>Los detalles fueron ofrecidos por la Junta Directiva de FEDUJAZZ, durante una rueda de prensa celebrada en Caf\u00e9 del Mar en el Lifestyle Holidays Vacation Club &amp; Resort en Cofres\u00ed, de aqu\u00ed.<\/p>\n<p>En el encuentro expusieron que este a\u00f1o el evento se realiza con el lema \u201cTributo al jazz en Am\u00e9rica Latina\u201d y el recorrido de conciertos inicia el viernes 25 de octubre con el Ensamble FEDUJAZZ, Penbiang Sang y desde Estados Unidos Arturo O\u2019Farrill and the Afro Latin Jazz Ensemble, en el Centro Le\u00f3n en Santiago a las 8:00 de la noche.<\/p>\n<p>El s\u00e1bado 26 de octubre a las 6:00 de la tarde en el Auditorio Rafael Solano UASD, Puerto Plata se presentar\u00e1 el documental \u201cSolano\u201d y posteriormente un concierto con Joshy y su 4 jazz. El 1 de noviembre a las 8:00 de la noche, el hermoso Sos\u00faa recibe la m\u00fasica de BGJI, Nando Michelin de Uruguay y The Dominican Jazz Project.<\/p>\n<p>Los conciertos contin\u00faan el s\u00e1bado 2 de noviembre en Playa Cabarete a las 8:00 de la noche con las presentaciones de Josean Jacobo pianista dominicano, Justin Kauflin Trio de Estados Unidos y Miguel Zen\u00f3n desde Puerto Rico.<\/p>\n<p>Mientras que el domingo 3 de noviembre cierra el Jazz Festival 2019 en Playa de Cabarete con el Berklee Global Jazz Institute, Jane Bunnett and Maqueque (Canada y Cuba) y con el carisma y gran energ\u00eda que le caracteriza se presenta Jos\u00e9 Alberto El Canario.<\/p>\n<p>Dentro del marco de la celebraci\u00f3n del Jazz Festival 2019,\u00a0cientos de ni\u00f1os ser\u00e1n beneficiados con diversos talleres musicales totalmente gratuitos, ofrecidos por m\u00fasicos profesionales nacionales e internacionales.\u00a0Adem\u00e1s, tambi\u00e9n se estar\u00e1n realizando Jam Sessions totalmente gratuitos para los que gusten participar.<\/p>\n<p>Este importante encuentro musical, sin fines de lucro, es organizado por la Fundaci\u00f3n\u00a0\u00a0Educativa Dominican Republic Jazz Festival (FEDUJAZZ) y cuenta con el apoyo\u00a0\u00a0del Ministerio de Turismo, Lifestyle, Millenium, la Embajada de Estados Unidos entre otros importantes patrocinadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- El Dominican Republic Jazz Festival 2019 contin\u00faa en esta ciudad con las presentaciones de destacados m\u00fasicos y cantantes nacionales e internacionales.<\/p>\n","protected":false},"author":9,"featured_media":76709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-76708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76708"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76708\/revisions"}],"predecessor-version":[{"id":76710,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76708\/revisions\/76710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76709"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}