{"id":76943,"date":"2019-10-14T14:02:47","date_gmt":"2019-10-14T18:02:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=76943"},"modified":"2019-10-14T14:02:47","modified_gmt":"2019-10-14T18:02:47","slug":"temporada-de-cruceros-se-inicia-con-mas-de-mil-turistas-que-visitan-santo-domingo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/temporada-de-cruceros-se-inicia-con-mas-de-mil-turistas-que-visitan-santo-domingo\/","title":{"rendered":"Temporada de cruceros se inicia con m\u00e1s de mil turistas que visitan Santo Domingo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-76944 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/10\/ocean-dream_12406212_20191014114231.jpg\" alt=\"\" width=\"307\" height=\"197\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/10\/ocean-dream_12406212_20191014114231.jpg 546w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/10\/ocean-dream_12406212_20191014114231-300x192.jpg 300w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/>El pasado 6 de octubre inici\u00f3 la temporada de cruceros para el per\u00edodo\u00a0<b>2019-2020<\/b>\u00a0en la ciudad de Santo Domingo con la llegada del crucero \u201c<b>Ocean Dream<\/b>\u00a0y su m\u00e1s de 1,000 cruceristas y sus\u00a0<b>500 tripulantes<\/b>\u00a0desde Jap\u00f3n.<!--more--><\/p>\n<p>Para esta temporada se espera la llegada de m\u00faltiples cruceros comerciales y de lujo a la terminal Don Diego en el puerto de Santo Domingo;\u00a0<b>Sans Souci<\/b>\u00a0ofrecer\u00e1 experiencias para que los visitantes conecten con los atractivos del destino.<\/p>\n<p>\u201cNuestro objetivo es ofrecerles a los cruceristas experiencias inolvidables y ser la primera impresi\u00f3n de la excelencia de lo mucho que Rep\u00fablica Dominicana tiene para ofrecer. Desde\u00a0<b>Sans Souci<\/b>, Puerto de Santo Domingo, buscamos crear un impacto positivo en el turismo y la econom\u00eda de la ciudad y el pa\u00eds\u201d, asegur\u00f3 Gabriel Rodr\u00edguez Pereyra, director ejecutivo de\u00a0<b>Sans Souci Ports S.A<\/b>.<\/p>\n<div class=\"in-content-info 3 0\"><\/div>\n<div class=\"in-content\"><\/div>\n<p>En los \u00faltimos a\u00f1os, Santo Domingo se convirti\u00f3 en unos de los destinos m\u00e1s seguros para los cruceristas. Datos del<b>\u00a0Cuerpo Especializado de Seguridad Tur\u00edstica de la Rep\u00fablica Dominicana\u00a0<\/b>(Cestur) demuestran que durante las \u00faltimas cinco temporadas de cruceros no se reportaron incidentes con los turistas que han visitado el pa\u00eds.<\/p>\n<p>Otros atractivos que hacen de la ciudad de Santo Domingo \u00fanica es su diversa y desarrollada gastronom\u00eda, abundantes puntos y actividades culturales, m\u00faltiples atracciones tur\u00edsticas con m\u00e1s de 500 a\u00f1os de historia disponibles en la Ciudad Colonial de Santo Domingo y el excelente servicio y trato a los miles de personas que visitan el destino tur\u00edstico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 6 de octubre inici\u00f3 la temporada de cruceros para el per\u00edodo\u00a02019-2020\u00a0en la ciudad de Santo Domingo con la llegada del crucero \u201cOcean Dream\u00a0y su m\u00e1s de 1,000 cruceristas y sus\u00a0500 tripulantes\u00a0desde Jap\u00f3n.<\/p>\n","protected":false},"author":9,"featured_media":76944,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[460],"tags":[],"class_list":["post-76943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=76943"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76943\/revisions"}],"predecessor-version":[{"id":76945,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/76943\/revisions\/76945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/76944"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=76943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=76943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=76943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}