{"id":77098,"date":"2019-11-12T15:20:54","date_gmt":"2019-11-12T19:20:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=77098"},"modified":"2019-11-12T15:20:54","modified_gmt":"2019-11-12T19:20:54","slug":"america-latina-y-el-caribe-a-punto-de-un-fuerte-crecimiento-en-energia-solar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/america-latina-y-el-caribe-a-punto-de-un-fuerte-crecimiento-en-energia-solar\/","title":{"rendered":"Am\u00e9rica Latina y el Caribe a punto de un fuerte crecimiento en energ\u00eda solar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-77099\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/11\/unnamed-11-1024x550.jpg\" alt=\"\" width=\"1024\" height=\"550\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/11\/unnamed-11-1024x550.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/11\/unnamed-11-1024x550-300x161.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2019\/11\/unnamed-11-1024x550-768x413.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>Am\u00e9rica Latina y el Caribe podr\u00edan multiplicar por un factor de 40 su capacidad solar instalada para el 2050, seg\u00fan indica un nuevo informe de la Agencia Internacional de Energ\u00edas Renovables (IRENA).<!--more--><\/p>\n<p>Seg\u00fan el informe\u00a0<em>Future of Solar Photovoltaic (<\/em>El futuro de la energ\u00eda solar fotovoltaica)\u00a0<strong>\u00a0<\/strong>presentado hoy en \u00abSun World 2019\u00bb en Lima, para entonces, la solar FV representar\u00eda la segunda mayor fuente de energ\u00eda, detr\u00e1s de la e\u00f3lica, generando una cuarta parte de la energ\u00eda mundial. En total, la capacidad mundial de energ\u00eda solar FV aumentar\u00eda de 480\u00a0GW en 2018, a m\u00e1s de 8\u00a0000\u00a0GW en 2050, lo que implica un crecimiento de casi un 9\u00a0por ciento por a\u00f1o.<\/p>\n<p>Se\u00f1ala que con inversiones anuales de m\u00e1s de 7\u00a0000 millones, la capacidad de la regi\u00f3n en energ\u00eda solar fotovoltaica (FV) pasar\u00eda de 7\u00a0GW actualmente a m\u00e1s de 280\u00a0GW a mediados de siglo. Aunque la energ\u00eda solar seguir\u00e1 siendo la m\u00e1s usada en Asia, Am\u00e9rica del Norte y Europa, se prev\u00e9 que el crecimiento del mercado ser\u00e1 en otras regiones del mundo.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abLa energ\u00eda solar FV y otras fuentes renovables representan la soluci\u00f3n m\u00e1s eficaz y ya disponible para abordar la creciente demanda de energ\u00eda a la vez que se limitan las emisiones de carbono\u00bb, explica el Director General de IRENA, Francesco La Camera. \u00abLas energ\u00edas renovables son pr\u00e1cticas, asequibles y respetuosas con el clima. Son esenciales para un crecimiento sostenible, permiten el acceso a la energ\u00eda, impulsan el crecimiento econ\u00f3mico, crean empleo y mejoran la salud. En especial, la energ\u00eda solar est\u00e1 destinada a ser\u00a0una de las principales fuentes de energ\u00eda en 2050. Los \u00edndices de crecimiento previstos en mercados como el de Am\u00e9rica Latina demuestran que podemos ampliar la transici\u00f3n energ\u00e9tica a todos los pa\u00edses. Es posible.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>Si va acompa\u00f1ada de pol\u00edticas s\u00f3lidas, la transformaci\u00f3n impulsada por las energ\u00edas renovables, como la solar, puede aportar ventajas socioecon\u00f3micas considerables, indica el nuevo informe de IRENA. A escala mundial la industria solar tiene el potencial de generar empleo a m\u00e1s de 18\u00a0millones de personas en 2050, lo que representa m\u00e1s de cuatro veces los 4,4\u00a0millones de empleos actuales.<\/p>\n<p>&nbsp;<\/p>\n<p>En la \u00faltima d\u00e9cada, la capacidad instalada de energ\u00eda solar FV fuera de la red se ha multiplicado por m\u00e1s de\u00a010, de 0,25\u00a0GW en 2008, hasta pr\u00e1cticamente 3\u00a0GW en 2018. Gracias a su car\u00e1cter modular y flexible, la tecnolog\u00eda solar FV puede adaptarse a una amplia gama de aplicaciones fuera de la red y a las condiciones locales. De hecho, la energ\u00eda solar FV fuera de la red es una tecnolog\u00eda clave para lograr el acceso universal a la electricidad, como establecen los Objetivos de Desarrollo Sostenible de la Organizaci\u00f3n de Naciones Unidas.<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, el despliegue de sistemas de energ\u00eda solar FV instalados en tejados ha aumentado considerablemente, lo que convierte la solar FV en un mercado m\u00e1s atractivo que el de adquirir electricidad a la red. Es evidente que la competitividad de la energ\u00eda solar distribuida facilita su despliegue en grandes mercados como Brasil, China, Alemania y M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9rica Latina y el Caribe podr\u00edan multiplicar por un factor de 40 su capacidad solar instalada para el 2050, seg\u00fan indica un nuevo informe de la Agencia Internacional de Energ\u00edas Renovables (IRENA).<\/p>\n","protected":false},"author":9,"featured_media":77099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-77098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=77098"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77098\/revisions"}],"predecessor-version":[{"id":77100,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77098\/revisions\/77100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/77099"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=77098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=77098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=77098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}